{"id":8125,"date":"2021-06-11T12:53:00","date_gmt":"2021-06-11T12:53:00","guid":{"rendered":"https:\/\/jornalnosbairros.com.br\/wp\/?p=8125"},"modified":"2021-06-11T12:55:00","modified_gmt":"2021-06-11T12:55:00","slug":"pessoas-de-55-e-56-anos-serao-imunizadas-neste-sabado-12em-navegantes","status":"publish","type":"post","link":"https:\/\/jornalnosbairros.com.br\/wp\/2021\/06\/pessoas-de-55-e-56-anos-serao-imunizadas-neste-sabado-12em-navegantes\/","title":{"rendered":"PESSOAS DE 55 E 56 ANOS SER\u00c3O IMUNIZADAS NESTE S\u00c1BADO (12) EM NAVEGANTES"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>11\/06\/2021<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Para dar celeridade \u00e0 imuniza\u00e7\u00e3o da popula\u00e7\u00e3o, Navegantes promove o Dia D da vacina\u00e7\u00e3o contra o coronav\u00edrus, neste s\u00e1bado (12), para os grupos j\u00e1 liberados. Na mesma data, o munic\u00edpio amplia seu p\u00fablico alvo e passa a vacinar pessoas com 55 e 56 anos, sem comorbidades.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">No Dia D, ser\u00e3o seis pontos de vacina\u00e7\u00e3o: UBS Machados, UBS Porto das Balsas, UBS Central, UBS Gravat\u00e1, UBS S\u00e3o Domingos 2 e UBS Meia Praia. O hor\u00e1rio de atendimento ser\u00e1 das 8h \u00e0s 12h.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A aplica\u00e7\u00e3o das vacinas, neste dia, ser\u00e1 por livre demanda. Basta chegar a um dos quatro locais citados e apresentar documento oficial com foto, comprovante de resid\u00eancia e carteirinha de vacina\u00e7\u00e3o (se tiver).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">No caso dos grupos com comorbidades, defici\u00eancia permanente e profissionais da educa\u00e7\u00e3o, \u00e9 necess\u00e1rio tamb\u00e9m levar documento que comprove sua condi\u00e7\u00e3o ou atividade de trabalho. Vale lembrar que o uso de m\u00e1scara \u00e9 obrigat\u00f3rio.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Para mais informa\u00e7\u00f5es sobre a vacina\u00e7\u00e3o contra a Covid-19, entre em contato com o Departamento de Vigil\u00e2ncia Epidemiol\u00f3gica (DVE), que atende, nos dias \u00fateis, das 8h \u00e0s 12h e das 13h30 \u00e0s 17h30, pelo telefone (47) 3185-2367.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/jornalnosbairros.com.br\/wp\/noticias\/\">Leia mais not\u00edcias do JB<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>11\/06\/2021 Para dar celeridade \u00e0 imuniza\u00e7\u00e3o da popula\u00e7\u00e3o, Navegantes promove o Dia D da vacina\u00e7\u00e3o contra o coronav\u00edrus, neste s\u00e1bado (12), para os grupos j\u00e1 liberados. Na mesma data, o munic\u00edpio amplia seu&hellip;<\/p>\n","protected":false},"author":2,"featured_media":8126,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"ai_generated_summary":"","footnotes":""},"categories":[31,25],"tags":[],"class_list":["post-8125","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-navegantes","category-saude"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>PESSOAS DE 55 E 56 ANOS SER\u00c3O IMUNIZADAS NESTE S\u00c1BADO (12) EM NAVEGANTES - Jornal nos Bairros<\/title>\n<meta name=\"description\" content=\"vacina\u00e7\u00e3o covi 55 e 56 anos navegantes sem comorbidades Dia D\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/jornalnosbairros.com.br\/wp\/2021\/06\/pessoas-de-55-e-56-anos-serao-imunizadas-neste-sabado-12em-navegantes\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"PESSOAS DE 55 E 56 ANOS SER\u00c3O IMUNIZADAS NESTE S\u00c1BADO (12) EM NAVEGANTES - Jornal nos Bairros\" \/>\n<meta property=\"og:description\" content=\"vacina\u00e7\u00e3o covi 55 e 56 anos navegantes sem comorbidades Dia D\" \/>\n<meta property=\"og:url\" content=\"https:\/\/jornalnosbairros.com.br\/wp\/2021\/06\/pessoas-de-55-e-56-anos-serao-imunizadas-neste-sabado-12em-navegantes\/\" \/>\n<meta property=\"og:site_name\" content=\"Jornal nos Bairros\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/jornalnosbairros\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/jornalnosbairros\" \/>\n<meta property=\"article:published_time\" content=\"2021-06-11T12:53:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-06-11T12:55:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/jornalnosbairros.com.br\/wp\/wp-content\/uploads\/2021\/06\/vacinacao-covid-navegantes-56.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"513\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Louise Benassi\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/jornal_bairros\" \/>\n<meta name=\"twitter:site\" content=\"@jornal_bairros\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Louise Benassi\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/2021\\\/06\\\/pessoas-de-55-e-56-anos-serao-imunizadas-neste-sabado-12em-navegantes\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/2021\\\/06\\\/pessoas-de-55-e-56-anos-serao-imunizadas-neste-sabado-12em-navegantes\\\/\"},\"author\":{\"name\":\"Louise Benassi\",\"@id\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/#\\\/schema\\\/person\\\/0fff6800408f4a5288e868b423aa66e6\"},\"headline\":\"PESSOAS DE 55 E 56 ANOS SER\u00c3O IMUNIZADAS NESTE S\u00c1BADO (12) EM NAVEGANTES\",\"datePublished\":\"2021-06-11T12:53:00+00:00\",\"dateModified\":\"2021-06-11T12:55:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/2021\\\/06\\\/pessoas-de-55-e-56-anos-serao-imunizadas-neste-sabado-12em-navegantes\\\/\"},\"wordCount\":220,\"publisher\":{\"@id\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/2021\\\/06\\\/pessoas-de-55-e-56-anos-serao-imunizadas-neste-sabado-12em-navegantes\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/vacinacao-covid-navegantes-56.jpg\",\"articleSection\":[\"NAVEGANTES\",\"SA\u00daDE\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/2021\\\/06\\\/pessoas-de-55-e-56-anos-serao-imunizadas-neste-sabado-12em-navegantes\\\/\",\"url\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/2021\\\/06\\\/pessoas-de-55-e-56-anos-serao-imunizadas-neste-sabado-12em-navegantes\\\/\",\"name\":\"PESSOAS DE 55 E 56 ANOS SER\u00c3O IMUNIZADAS NESTE S\u00c1BADO (12) EM NAVEGANTES - Jornal nos Bairros\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/2021\\\/06\\\/pessoas-de-55-e-56-anos-serao-imunizadas-neste-sabado-12em-navegantes\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/2021\\\/06\\\/pessoas-de-55-e-56-anos-serao-imunizadas-neste-sabado-12em-navegantes\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/vacinacao-covid-navegantes-56.jpg\",\"datePublished\":\"2021-06-11T12:53:00+00:00\",\"dateModified\":\"2021-06-11T12:55:00+00:00\",\"description\":\"vacina\u00e7\u00e3o covi 55 e 56 anos navegantes sem comorbidades Dia D\",\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/2021\\\/06\\\/pessoas-de-55-e-56-anos-serao-imunizadas-neste-sabado-12em-navegantes\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/2021\\\/06\\\/pessoas-de-55-e-56-anos-serao-imunizadas-neste-sabado-12em-navegantes\\\/#primaryimage\",\"url\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/vacinacao-covid-navegantes-56.jpg\",\"contentUrl\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/vacinacao-covid-navegantes-56.jpg\",\"width\":800,\"height\":513,\"caption\":\"vacina\u00e7\u00e3o covid navegantes 56\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/#website\",\"url\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/\",\"name\":\"Jornal nos Bairros\",\"description\":\"Not\u00edcias di\u00e1rias de Navegantes e regi\u00e3o\",\"publisher\":{\"@id\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/#organization\"},\"alternateName\":\"JB\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/#organization\",\"name\":\"Jornal nos Bairros de Navegantes\",\"url\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/LOGO-JB.png\",\"contentUrl\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/LOGO-JB.png\",\"width\":168,\"height\":150,\"caption\":\"Jornal nos Bairros de Navegantes\"},\"image\":{\"@id\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/jornalnosbairros\",\"https:\\\/\\\/x.com\\\/jornal_bairros\",\"https:\\\/\\\/www.instagram.com\\\/jornalnosbairros\",\"https:\\\/\\\/www.youtube.com\\\/@jornalnosbairros\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/#\\\/schema\\\/person\\\/0fff6800408f4a5288e868b423aa66e6\",\"name\":\"Louise Benassi\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9d4314cebcb775b6f2598392f1ed67a5d487928fbd387d9492add88335cb0166?s=96&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9d4314cebcb775b6f2598392f1ed67a5d487928fbd387d9492add88335cb0166?s=96&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9d4314cebcb775b6f2598392f1ed67a5d487928fbd387d9492add88335cb0166?s=96&r=g\",\"caption\":\"Louise Benassi\"},\"description\":\"Louise Benassi SC 002880\\\/JP - Jornalista do Jornal nos Bairros de Navegantes - Contato: fale@jornalnosbairros.com.br - Siga: @jornalnosbairros - Acesse: www.jornalnosbairros.com.br - WhatsApp 47 33196585\",\"sameAs\":[\"http:\\\/\\\/www.jornalnosbairros.com.br\",\"https:\\\/\\\/www.facebook.com\\\/jornalnosbairros\",\"https:\\\/\\\/www.instagram.com\\\/jornalnosbairros\\\/\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/jornal_bairros\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCbdZNY5wPbaBq5KtRGP4WxQ\"],\"url\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/author\\\/louise\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"PESSOAS DE 55 E 56 ANOS SER\u00c3O IMUNIZADAS NESTE S\u00c1BADO (12) EM NAVEGANTES - Jornal nos Bairros","description":"vacina\u00e7\u00e3o covi 55 e 56 anos navegantes sem comorbidades Dia D","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/jornalnosbairros.com.br\/wp\/2021\/06\/pessoas-de-55-e-56-anos-serao-imunizadas-neste-sabado-12em-navegantes\/","og_locale":"pt_BR","og_type":"article","og_title":"PESSOAS DE 55 E 56 ANOS SER\u00c3O IMUNIZADAS NESTE S\u00c1BADO (12) EM NAVEGANTES - Jornal nos Bairros","og_description":"vacina\u00e7\u00e3o covi 55 e 56 anos navegantes sem comorbidades Dia D","og_url":"https:\/\/jornalnosbairros.com.br\/wp\/2021\/06\/pessoas-de-55-e-56-anos-serao-imunizadas-neste-sabado-12em-navegantes\/","og_site_name":"Jornal nos Bairros","article_publisher":"https:\/\/www.facebook.com\/jornalnosbairros","article_author":"https:\/\/www.facebook.com\/jornalnosbairros","article_published_time":"2021-06-11T12:53:00+00:00","article_modified_time":"2021-06-11T12:55:00+00:00","og_image":[{"width":800,"height":513,"url":"https:\/\/jornalnosbairros.com.br\/wp\/wp-content\/uploads\/2021\/06\/vacinacao-covid-navegantes-56.jpg","type":"image\/jpeg"}],"author":"Louise Benassi","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/jornal_bairros","twitter_site":"@jornal_bairros","twitter_misc":{"Escrito por":"Louise Benassi","Est. tempo de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/jornalnosbairros.com.br\/wp\/2021\/06\/pessoas-de-55-e-56-anos-serao-imunizadas-neste-sabado-12em-navegantes\/#article","isPartOf":{"@id":"https:\/\/jornalnosbairros.com.br\/wp\/2021\/06\/pessoas-de-55-e-56-anos-serao-imunizadas-neste-sabado-12em-navegantes\/"},"author":{"name":"Louise Benassi","@id":"https:\/\/jornalnosbairros.com.br\/wp\/#\/schema\/person\/0fff6800408f4a5288e868b423aa66e6"},"headline":"PESSOAS DE 55 E 56 ANOS SER\u00c3O IMUNIZADAS NESTE S\u00c1BADO (12) EM NAVEGANTES","datePublished":"2021-06-11T12:53:00+00:00","dateModified":"2021-06-11T12:55:00+00:00","mainEntityOfPage":{"@id":"https:\/\/jornalnosbairros.com.br\/wp\/2021\/06\/pessoas-de-55-e-56-anos-serao-imunizadas-neste-sabado-12em-navegantes\/"},"wordCount":220,"publisher":{"@id":"https:\/\/jornalnosbairros.com.br\/wp\/#organization"},"image":{"@id":"https:\/\/jornalnosbairros.com.br\/wp\/2021\/06\/pessoas-de-55-e-56-anos-serao-imunizadas-neste-sabado-12em-navegantes\/#primaryimage"},"thumbnailUrl":"https:\/\/jornalnosbairros.com.br\/wp\/wp-content\/uploads\/2021\/06\/vacinacao-covid-navegantes-56.jpg","articleSection":["NAVEGANTES","SA\u00daDE"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/jornalnosbairros.com.br\/wp\/2021\/06\/pessoas-de-55-e-56-anos-serao-imunizadas-neste-sabado-12em-navegantes\/","url":"https:\/\/jornalnosbairros.com.br\/wp\/2021\/06\/pessoas-de-55-e-56-anos-serao-imunizadas-neste-sabado-12em-navegantes\/","name":"PESSOAS DE 55 E 56 ANOS SER\u00c3O IMUNIZADAS NESTE S\u00c1BADO (12) EM NAVEGANTES - Jornal nos Bairros","isPartOf":{"@id":"https:\/\/jornalnosbairros.com.br\/wp\/#website"},"primaryImageOfPage":{"@id":"https:\/\/jornalnosbairros.com.br\/wp\/2021\/06\/pessoas-de-55-e-56-anos-serao-imunizadas-neste-sabado-12em-navegantes\/#primaryimage"},"image":{"@id":"https:\/\/jornalnosbairros.com.br\/wp\/2021\/06\/pessoas-de-55-e-56-anos-serao-imunizadas-neste-sabado-12em-navegantes\/#primaryimage"},"thumbnailUrl":"https:\/\/jornalnosbairros.com.br\/wp\/wp-content\/uploads\/2021\/06\/vacinacao-covid-navegantes-56.jpg","datePublished":"2021-06-11T12:53:00+00:00","dateModified":"2021-06-11T12:55:00+00:00","description":"vacina\u00e7\u00e3o covi 55 e 56 anos navegantes sem comorbidades Dia D","inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/jornalnosbairros.com.br\/wp\/2021\/06\/pessoas-de-55-e-56-anos-serao-imunizadas-neste-sabado-12em-navegantes\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/jornalnosbairros.com.br\/wp\/2021\/06\/pessoas-de-55-e-56-anos-serao-imunizadas-neste-sabado-12em-navegantes\/#primaryimage","url":"https:\/\/jornalnosbairros.com.br\/wp\/wp-content\/uploads\/2021\/06\/vacinacao-covid-navegantes-56.jpg","contentUrl":"https:\/\/jornalnosbairros.com.br\/wp\/wp-content\/uploads\/2021\/06\/vacinacao-covid-navegantes-56.jpg","width":800,"height":513,"caption":"vacina\u00e7\u00e3o covid navegantes 56"},{"@type":"WebSite","@id":"https:\/\/jornalnosbairros.com.br\/wp\/#website","url":"https:\/\/jornalnosbairros.com.br\/wp\/","name":"Jornal nos Bairros","description":"Not\u00edcias di\u00e1rias de Navegantes e regi\u00e3o","publisher":{"@id":"https:\/\/jornalnosbairros.com.br\/wp\/#organization"},"alternateName":"JB","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/jornalnosbairros.com.br\/wp\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/jornalnosbairros.com.br\/wp\/#organization","name":"Jornal nos Bairros de Navegantes","url":"https:\/\/jornalnosbairros.com.br\/wp\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/jornalnosbairros.com.br\/wp\/#\/schema\/logo\/image\/","url":"https:\/\/jornalnosbairros.com.br\/wp\/wp-content\/uploads\/2025\/01\/LOGO-JB.png","contentUrl":"https:\/\/jornalnosbairros.com.br\/wp\/wp-content\/uploads\/2025\/01\/LOGO-JB.png","width":168,"height":150,"caption":"Jornal nos Bairros de Navegantes"},"image":{"@id":"https:\/\/jornalnosbairros.com.br\/wp\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/jornalnosbairros","https:\/\/x.com\/jornal_bairros","https:\/\/www.instagram.com\/jornalnosbairros","https:\/\/www.youtube.com\/@jornalnosbairros"]},{"@type":"Person","@id":"https:\/\/jornalnosbairros.com.br\/wp\/#\/schema\/person\/0fff6800408f4a5288e868b423aa66e6","name":"Louise Benassi","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/9d4314cebcb775b6f2598392f1ed67a5d487928fbd387d9492add88335cb0166?s=96&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/9d4314cebcb775b6f2598392f1ed67a5d487928fbd387d9492add88335cb0166?s=96&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9d4314cebcb775b6f2598392f1ed67a5d487928fbd387d9492add88335cb0166?s=96&r=g","caption":"Louise Benassi"},"description":"Louise Benassi SC 002880\/JP - Jornalista do Jornal nos Bairros de Navegantes - Contato: fale@jornalnosbairros.com.br - Siga: @jornalnosbairros - Acesse: www.jornalnosbairros.com.br - WhatsApp 47 33196585","sameAs":["http:\/\/www.jornalnosbairros.com.br","https:\/\/www.facebook.com\/jornalnosbairros","https:\/\/www.instagram.com\/jornalnosbairros\/","https:\/\/x.com\/https:\/\/twitter.com\/jornal_bairros","https:\/\/www.youtube.com\/channel\/UCbdZNY5wPbaBq5KtRGP4WxQ"],"url":"https:\/\/jornalnosbairros.com.br\/wp\/author\/louise\/"}]}},"_links":{"self":[{"href":"https:\/\/jornalnosbairros.com.br\/wp\/wp-json\/wp\/v2\/posts\/8125","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jornalnosbairros.com.br\/wp\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jornalnosbairros.com.br\/wp\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jornalnosbairros.com.br\/wp\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/jornalnosbairros.com.br\/wp\/wp-json\/wp\/v2\/comments?post=8125"}],"version-history":[{"count":3,"href":"https:\/\/jornalnosbairros.com.br\/wp\/wp-json\/wp\/v2\/posts\/8125\/revisions"}],"predecessor-version":[{"id":8130,"href":"https:\/\/jornalnosbairros.com.br\/wp\/wp-json\/wp\/v2\/posts\/8125\/revisions\/8130"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/jornalnosbairros.com.br\/wp\/wp-json\/wp\/v2\/media\/8126"}],"wp:attachment":[{"href":"https:\/\/jornalnosbairros.com.br\/wp\/wp-json\/wp\/v2\/media?parent=8125"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jornalnosbairros.com.br\/wp\/wp-json\/wp\/v2\/categories?post=8125"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jornalnosbairros.com.br\/wp\/wp-json\/wp\/v2\/tags?post=8125"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}