{"id":43307,"date":"2025-11-23T20:19:53","date_gmt":"2025-11-23T23:19:53","guid":{"rendered":"https:\/\/jornalnosbairros.com.br\/wp\/?p=43307"},"modified":"2025-11-24T10:27:11","modified_gmt":"2025-11-24T13:27:11","slug":"piloto-do-beto-carrero-morre-em-apresentacao","status":"publish","type":"post","link":"https:\/\/jornalnosbairros.com.br\/wp\/2025\/11\/piloto-do-beto-carrero-morre-em-apresentacao\/","title":{"rendered":"Piloto do Beto Carrero morre em apresenta\u00e7\u00e3o"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><em><strong>Lurrique Ferrari, de 36 anos, chegou a ser encaminhado ao hospital, mas n\u00e3o resistiu. <\/strong><\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Neste domingo (23), um dos pilotos do show de manobras radicais do parque Beto Carrero World, em Penha, morreu devido a um acidente durante uma apresenta\u00e7\u00e3o com sua motocicleta. Lurrique Ferrari, de 36 anos, chegou a ser socorrido e levado ao hospital Marieta \u00a0Konder Bornhauser, em Itaja\u00ed, mas n\u00e3o resistiu.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O acidente aconteceu quando o piloto realizava um salto na atra\u00e7\u00e3o conhecida como &#8220;Hot Wheels Epic Show&#8221;, e acabou batendo contra uma rampa. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A cena foi vista por centenas de espectadores presentes na plateia, que tamb\u00e9m filmavam a apresenta\u00e7\u00e3o.\u00a0O v\u00eddeo mostra Lurrique indo atr\u00e1s de outro piloto, que consegue completar a manobra. Ele, por\u00e9m, salta da primeira rampa, mas n\u00e3o consegue acessar a segunda, batendo com a cabe\u00e7a na estrutura. Em seguida, cai no ch\u00e3o.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"640\" data-src=\"https:\/\/jornalnosbairros.com.br\/wp\/wp-content\/uploads\/2025\/11\/1_hot_wheels_1-37560910-1024x640.jpg\" alt=\"\" class=\"wp-image-43312 lazyload\" data-srcset=\"https:\/\/jornalnosbairros.com.br\/wp\/wp-content\/uploads\/2025\/11\/1_hot_wheels_1-37560910-1024x640.jpg 1024w, https:\/\/jornalnosbairros.com.br\/wp\/wp-content\/uploads\/2025\/11\/1_hot_wheels_1-37560910-300x188.jpg 300w, https:\/\/jornalnosbairros.com.br\/wp\/wp-content\/uploads\/2025\/11\/1_hot_wheels_1-37560910-768x480.jpg 768w, https:\/\/jornalnosbairros.com.br\/wp\/wp-content\/uploads\/2025\/11\/1_hot_wheels_1-37560910.jpg 1200w\" data-sizes=\"(max-width: 1024px) 100vw, 1024px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1024px; --smush-placeholder-aspect-ratio: 1024\/640;\" \/><figcaption class=\"wp-element-caption\">Lurrique trabalhava h\u00e1 cerca de um ano no parque. <\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">\u00a0Lurrique foi socorrido e encaminhado ao hospital Marieta Konder Bornhauser, em Itaja\u00ed, chegou a passar por uma cirurgia, mas n\u00e3o resistiu aos ferimentos. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O parque lamentou a morte do piloto e destacou que ele recebeu atendimento imediato. A administra\u00e7\u00e3o est\u00e1 prestando suporte \u00e0 fam\u00edlia e j\u00e1 iniciou seus protocolos internos para apura\u00e7\u00e3o das causas do acidente.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O caso ser\u00e1 investigado pela Pol\u00edcia Civil.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Lurrique era natural de Adamantina, no interior de S\u00e3o Paulo. O\u00a0piloto trabalhava no parque h\u00e1 cerca de um ano. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8220;Neste momento de dor indescrit\u00edvel, manifestamos nossa solidariedade, respeito e sentimentos aos familiares, amigos e colegas de equipe. Lurrique era admirado pelo talento, pela dedica\u00e7\u00e3o e pela paix\u00e3o com que desempenhava seu trabalho, e deixar\u00e1 saudade em todos que tiveram o privil\u00e9gio de conviver com ele. O parque est\u00e1 prestando suporte \u00e0 fam\u00edlia e j\u00e1 iniciou seus protocolos internos para apura\u00e7\u00e3o das causas do acidente\u201d, diz a nota emitida pelo Parque Beto Carrero. <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Lurrique Ferrari, de 36 anos, chegou a ser encaminhado ao hospital, mas n\u00e3o resistiu. Neste domingo (23), um dos pilotos do show de manobras radicais do parque Beto Carrero World, em Penha, morreu&hellip;<\/p>\n","protected":false},"author":1,"featured_media":43308,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ai_generated_summary":"","footnotes":""},"categories":[33,5],"tags":[1001,83,149],"class_list":["post-43307","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-penha","category-policia","tag-betocarrero","tag-penha","tag-policia-2"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Piloto do Beto Carrero morre em apresenta\u00e7\u00e3o - Jornal nos Bairros<\/title>\n<meta name=\"description\" content=\"Neste Domingo (23), o piloto Lurrique Ferrari, morreu devido a um acidente durante um show com sua moto no parque Beto Carrero em Penha.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/jornalnosbairros.com.br\/wp\/2025\/11\/piloto-do-beto-carrero-morre-em-apresentacao\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Piloto do Beto Carrero morre em apresenta\u00e7\u00e3o - Jornal nos Bairros\" \/>\n<meta property=\"og:description\" content=\"Neste Domingo (23), o piloto Lurrique Ferrari, morreu devido a um acidente durante um show com sua moto no parque Beto Carrero em Penha.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/jornalnosbairros.com.br\/wp\/2025\/11\/piloto-do-beto-carrero-morre-em-apresentacao\/\" \/>\n<meta property=\"og:site_name\" content=\"Jornal nos Bairros\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/jornalnosbairros\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/jornalnosbairros\" \/>\n<meta property=\"article:published_time\" content=\"2025-11-23T23:19:53+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-11-24T13:27:11+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/jornalnosbairros.com.br\/wp\/wp-content\/uploads\/2025\/11\/piloto-morre-acidente-beto-carrero.png\" \/>\n\t<meta property=\"og:image:width\" content=\"684\" \/>\n\t<meta property=\"og:image:height\" content=\"485\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Editoria\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/jornal_bairros\" \/>\n<meta name=\"twitter:site\" content=\"@jornal_bairros\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Editoria\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/2025\\\/11\\\/piloto-do-beto-carrero-morre-em-apresentacao\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/2025\\\/11\\\/piloto-do-beto-carrero-morre-em-apresentacao\\\/\"},\"author\":{\"name\":\"Editoria\",\"@id\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/#\\\/schema\\\/person\\\/9a74fde2f4332c018c3b4d29a6129437\"},\"headline\":\"Piloto do Beto Carrero morre em apresenta\u00e7\u00e3o\",\"datePublished\":\"2025-11-23T23:19:53+00:00\",\"dateModified\":\"2025-11-24T13:27:11+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/2025\\\/11\\\/piloto-do-beto-carrero-morre-em-apresentacao\\\/\"},\"wordCount\":332,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/2025\\\/11\\\/piloto-do-beto-carrero-morre-em-apresentacao\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/piloto-morre-acidente-beto-carrero.png\",\"keywords\":[\"betocarrero\",\"penha\",\"pol\u00edcia\"],\"articleSection\":[\"PENHA\",\"POL\u00cdCIA\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/2025\\\/11\\\/piloto-do-beto-carrero-morre-em-apresentacao\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/2025\\\/11\\\/piloto-do-beto-carrero-morre-em-apresentacao\\\/\",\"url\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/2025\\\/11\\\/piloto-do-beto-carrero-morre-em-apresentacao\\\/\",\"name\":\"Piloto do Beto Carrero morre em apresenta\u00e7\u00e3o - Jornal nos Bairros\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/2025\\\/11\\\/piloto-do-beto-carrero-morre-em-apresentacao\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/2025\\\/11\\\/piloto-do-beto-carrero-morre-em-apresentacao\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/piloto-morre-acidente-beto-carrero.png\",\"datePublished\":\"2025-11-23T23:19:53+00:00\",\"dateModified\":\"2025-11-24T13:27:11+00:00\",\"description\":\"Neste Domingo (23), o piloto Lurrique Ferrari, morreu devido a um acidente durante um show com sua moto no parque Beto Carrero em Penha.\",\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/2025\\\/11\\\/piloto-do-beto-carrero-morre-em-apresentacao\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/2025\\\/11\\\/piloto-do-beto-carrero-morre-em-apresentacao\\\/#primaryimage\",\"url\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/piloto-morre-acidente-beto-carrero.png\",\"contentUrl\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/piloto-morre-acidente-beto-carrero.png\",\"width\":684,\"height\":485},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/#website\",\"url\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/\",\"name\":\"Jornal nos Bairros\",\"description\":\"Not\u00edcias di\u00e1rias de Navegantes e regi\u00e3o\",\"publisher\":{\"@id\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/#organization\"},\"alternateName\":\"JB\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/#organization\",\"name\":\"Jornal nos Bairros de Navegantes\",\"url\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/LOGO-JB.png\",\"contentUrl\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/LOGO-JB.png\",\"width\":168,\"height\":150,\"caption\":\"Jornal nos Bairros de Navegantes\"},\"image\":{\"@id\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/jornalnosbairros\",\"https:\\\/\\\/x.com\\\/jornal_bairros\",\"https:\\\/\\\/www.instagram.com\\\/jornalnosbairros\",\"https:\\\/\\\/www.youtube.com\\\/@jornalnosbairros\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/#\\\/schema\\\/person\\\/9a74fde2f4332c018c3b4d29a6129437\",\"name\":\"Editoria\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b53a04b7003d01b914d43ebacd13b233f0d99ed1cb7f8cb7d8553ef90e3f466b?s=96&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b53a04b7003d01b914d43ebacd13b233f0d99ed1cb7f8cb7d8553ef90e3f466b?s=96&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b53a04b7003d01b914d43ebacd13b233f0d99ed1cb7f8cb7d8553ef90e3f466b?s=96&r=g\",\"caption\":\"Editoria\"},\"description\":\"Edi\u00e7\u00e3o do Jornal nos Bairros de Navegantes - Contato: fale@jornalnosbairros.com.br - Siga: @jornalnosbairros - Acesse: www.jornalnosbairros.com.br\",\"sameAs\":[\"http:\\\/\\\/www.jornalnosbairros.com.br\\\/wp\",\"https:\\\/\\\/www.facebook.com\\\/jornalnosbairros\",\"https:\\\/\\\/www.instagram.com\\\/jornalnosbairros\\\/\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/jornal_bairros\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCbdZNY5wPbaBq5KtRGP4WxQ?view_as=subscriber\"],\"url\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Piloto do Beto Carrero morre em apresenta\u00e7\u00e3o - Jornal nos Bairros","description":"Neste Domingo (23), o piloto Lurrique Ferrari, morreu devido a um acidente durante um show com sua moto no parque Beto Carrero em Penha.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/jornalnosbairros.com.br\/wp\/2025\/11\/piloto-do-beto-carrero-morre-em-apresentacao\/","og_locale":"pt_BR","og_type":"article","og_title":"Piloto do Beto Carrero morre em apresenta\u00e7\u00e3o - Jornal nos Bairros","og_description":"Neste Domingo (23), o piloto Lurrique Ferrari, morreu devido a um acidente durante um show com sua moto no parque Beto Carrero em Penha.","og_url":"https:\/\/jornalnosbairros.com.br\/wp\/2025\/11\/piloto-do-beto-carrero-morre-em-apresentacao\/","og_site_name":"Jornal nos Bairros","article_publisher":"https:\/\/www.facebook.com\/jornalnosbairros","article_author":"https:\/\/www.facebook.com\/jornalnosbairros","article_published_time":"2025-11-23T23:19:53+00:00","article_modified_time":"2025-11-24T13:27:11+00:00","og_image":[{"width":684,"height":485,"url":"https:\/\/jornalnosbairros.com.br\/wp\/wp-content\/uploads\/2025\/11\/piloto-morre-acidente-beto-carrero.png","type":"image\/png"}],"author":"Editoria","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/jornal_bairros","twitter_site":"@jornal_bairros","twitter_misc":{"Escrito por":"Editoria","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/jornalnosbairros.com.br\/wp\/2025\/11\/piloto-do-beto-carrero-morre-em-apresentacao\/#article","isPartOf":{"@id":"https:\/\/jornalnosbairros.com.br\/wp\/2025\/11\/piloto-do-beto-carrero-morre-em-apresentacao\/"},"author":{"name":"Editoria","@id":"https:\/\/jornalnosbairros.com.br\/wp\/#\/schema\/person\/9a74fde2f4332c018c3b4d29a6129437"},"headline":"Piloto do Beto Carrero morre em apresenta\u00e7\u00e3o","datePublished":"2025-11-23T23:19:53+00:00","dateModified":"2025-11-24T13:27:11+00:00","mainEntityOfPage":{"@id":"https:\/\/jornalnosbairros.com.br\/wp\/2025\/11\/piloto-do-beto-carrero-morre-em-apresentacao\/"},"wordCount":332,"commentCount":0,"publisher":{"@id":"https:\/\/jornalnosbairros.com.br\/wp\/#organization"},"image":{"@id":"https:\/\/jornalnosbairros.com.br\/wp\/2025\/11\/piloto-do-beto-carrero-morre-em-apresentacao\/#primaryimage"},"thumbnailUrl":"https:\/\/jornalnosbairros.com.br\/wp\/wp-content\/uploads\/2025\/11\/piloto-morre-acidente-beto-carrero.png","keywords":["betocarrero","penha","pol\u00edcia"],"articleSection":["PENHA","POL\u00cdCIA"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/jornalnosbairros.com.br\/wp\/2025\/11\/piloto-do-beto-carrero-morre-em-apresentacao\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/jornalnosbairros.com.br\/wp\/2025\/11\/piloto-do-beto-carrero-morre-em-apresentacao\/","url":"https:\/\/jornalnosbairros.com.br\/wp\/2025\/11\/piloto-do-beto-carrero-morre-em-apresentacao\/","name":"Piloto do Beto Carrero morre em apresenta\u00e7\u00e3o - Jornal nos Bairros","isPartOf":{"@id":"https:\/\/jornalnosbairros.com.br\/wp\/#website"},"primaryImageOfPage":{"@id":"https:\/\/jornalnosbairros.com.br\/wp\/2025\/11\/piloto-do-beto-carrero-morre-em-apresentacao\/#primaryimage"},"image":{"@id":"https:\/\/jornalnosbairros.com.br\/wp\/2025\/11\/piloto-do-beto-carrero-morre-em-apresentacao\/#primaryimage"},"thumbnailUrl":"https:\/\/jornalnosbairros.com.br\/wp\/wp-content\/uploads\/2025\/11\/piloto-morre-acidente-beto-carrero.png","datePublished":"2025-11-23T23:19:53+00:00","dateModified":"2025-11-24T13:27:11+00:00","description":"Neste Domingo (23), o piloto Lurrique Ferrari, morreu devido a um acidente durante um show com sua moto no parque Beto Carrero em Penha.","inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/jornalnosbairros.com.br\/wp\/2025\/11\/piloto-do-beto-carrero-morre-em-apresentacao\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/jornalnosbairros.com.br\/wp\/2025\/11\/piloto-do-beto-carrero-morre-em-apresentacao\/#primaryimage","url":"https:\/\/jornalnosbairros.com.br\/wp\/wp-content\/uploads\/2025\/11\/piloto-morre-acidente-beto-carrero.png","contentUrl":"https:\/\/jornalnosbairros.com.br\/wp\/wp-content\/uploads\/2025\/11\/piloto-morre-acidente-beto-carrero.png","width":684,"height":485},{"@type":"WebSite","@id":"https:\/\/jornalnosbairros.com.br\/wp\/#website","url":"https:\/\/jornalnosbairros.com.br\/wp\/","name":"Jornal nos Bairros","description":"Not\u00edcias di\u00e1rias de Navegantes e regi\u00e3o","publisher":{"@id":"https:\/\/jornalnosbairros.com.br\/wp\/#organization"},"alternateName":"JB","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/jornalnosbairros.com.br\/wp\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/jornalnosbairros.com.br\/wp\/#organization","name":"Jornal nos Bairros de Navegantes","url":"https:\/\/jornalnosbairros.com.br\/wp\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/jornalnosbairros.com.br\/wp\/#\/schema\/logo\/image\/","url":"https:\/\/jornalnosbairros.com.br\/wp\/wp-content\/uploads\/2025\/01\/LOGO-JB.png","contentUrl":"https:\/\/jornalnosbairros.com.br\/wp\/wp-content\/uploads\/2025\/01\/LOGO-JB.png","width":168,"height":150,"caption":"Jornal nos Bairros de Navegantes"},"image":{"@id":"https:\/\/jornalnosbairros.com.br\/wp\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/jornalnosbairros","https:\/\/x.com\/jornal_bairros","https:\/\/www.instagram.com\/jornalnosbairros","https:\/\/www.youtube.com\/@jornalnosbairros"]},{"@type":"Person","@id":"https:\/\/jornalnosbairros.com.br\/wp\/#\/schema\/person\/9a74fde2f4332c018c3b4d29a6129437","name":"Editoria","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/b53a04b7003d01b914d43ebacd13b233f0d99ed1cb7f8cb7d8553ef90e3f466b?s=96&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b53a04b7003d01b914d43ebacd13b233f0d99ed1cb7f8cb7d8553ef90e3f466b?s=96&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b53a04b7003d01b914d43ebacd13b233f0d99ed1cb7f8cb7d8553ef90e3f466b?s=96&r=g","caption":"Editoria"},"description":"Edi\u00e7\u00e3o do Jornal nos Bairros de Navegantes - Contato: fale@jornalnosbairros.com.br - Siga: @jornalnosbairros - Acesse: www.jornalnosbairros.com.br","sameAs":["http:\/\/www.jornalnosbairros.com.br\/wp","https:\/\/www.facebook.com\/jornalnosbairros","https:\/\/www.instagram.com\/jornalnosbairros\/","https:\/\/x.com\/https:\/\/twitter.com\/jornal_bairros","https:\/\/www.youtube.com\/channel\/UCbdZNY5wPbaBq5KtRGP4WxQ?view_as=subscriber"],"url":"https:\/\/jornalnosbairros.com.br\/wp\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/jornalnosbairros.com.br\/wp\/wp-json\/wp\/v2\/posts\/43307","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jornalnosbairros.com.br\/wp\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jornalnosbairros.com.br\/wp\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jornalnosbairros.com.br\/wp\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/jornalnosbairros.com.br\/wp\/wp-json\/wp\/v2\/comments?post=43307"}],"version-history":[{"count":9,"href":"https:\/\/jornalnosbairros.com.br\/wp\/wp-json\/wp\/v2\/posts\/43307\/revisions"}],"predecessor-version":[{"id":43324,"href":"https:\/\/jornalnosbairros.com.br\/wp\/wp-json\/wp\/v2\/posts\/43307\/revisions\/43324"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/jornalnosbairros.com.br\/wp\/wp-json\/wp\/v2\/media\/43308"}],"wp:attachment":[{"href":"https:\/\/jornalnosbairros.com.br\/wp\/wp-json\/wp\/v2\/media?parent=43307"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jornalnosbairros.com.br\/wp\/wp-json\/wp\/v2\/categories?post=43307"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jornalnosbairros.com.br\/wp\/wp-json\/wp\/v2\/tags?post=43307"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}