{"id":43263,"date":"2025-11-20T10:43:02","date_gmt":"2025-11-20T13:43:02","guid":{"rendered":"https:\/\/jornalnosbairros.com.br\/wp\/?p=43263"},"modified":"2025-11-21T16:38:47","modified_gmt":"2025-11-21T19:38:47","slug":"natal-de-encantos-inicia-neste-sabado-em-navegantes","status":"publish","type":"post","link":"https:\/\/jornalnosbairros.com.br\/wp\/2025\/11\/natal-de-encantos-inicia-neste-sabado-em-navegantes\/","title":{"rendered":"Natal de Encantos inicia neste s\u00e1bado em Navegantes"},"content":{"rendered":"\n<p class=\"has-text-align-center wp-block-paragraph\"><strong><em>Confira a programa\u00e7\u00e3o completa do Natal em Navegantes<\/em><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Neste s\u00e1bado (22), a partir das 19 horas, inicia o Natal de Encantos em Navegantes. A Arena de Eventos do bairro S\u00e3o Pedro (Pontal) vai se transformar no seu destino favorito para celebrar a \u00e9poca m\u00e1gica.<br><br>O governo municipal preparou o local para voc\u00ea e sua fam\u00edlia viver momentos inesquec\u00edveis com shows di\u00e1rios, a casa do Papai Noel e diversas atra\u00e7\u00f5es para todas as idades.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A Vila de Natal vai estar aberta \u00e0 comunidade de Quarta a Domingo, sempre as 19 horas e segue at\u00e9 o dia 23 de dezembro com um grande encerramento da Orquestra Sinf\u00f4nica de Santa Catarina.<\/p>\n\n\n\n<p class=\"has-pale-cyan-blue-background-color has-background wp-block-paragraph\"><strong>Programa\u00e7\u00e3o da Vila do Papai Noel<\/strong>:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>22\/11 (s\u00e1bado)<\/strong><br>19h:00 Abertura Oficial<br>20h:00 Show Infantil<br>20h:30 Chegada do Papai Noel<br>22h:00 Show com Banda S\/A<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>23\/11 (domingo)<\/strong><br>19h:00 Abertura Oficial<br>19h:30 Abertura do atendimento na Casa do Papai Noel com recrea\u00e7\u00e3o<br>20h:00 Show Infantil<br>20h:20 Hora da Neve<br>20h:30 Show com Grupo Desafio<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>26\/11 (quarta-feira)<\/strong><br>08h:30 Abertura da Vila para as escolas<br>10:00 Show infantil e recrea\u00e7\u00e3o<br>11h:30 Fechamento da vila<br>13h:30 Reabertura da vila<br>15:00 Show Infantil e recrea\u00e7\u00e3o<br>16h:30 Fechamento da vila<br>19h:30 Abertura do atendimento na Casa do Papai Noel com recrea\u00e7\u00e3o<br>20h:00 Show infantil<br>20h:30 Hora da neve<br>21h:00 Show Jess\u00e9 Mariano voz e viol\u00e3o<br>21h:00 Hora da Neve<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>27\/11 (quinta-feira)<\/strong><br>08h:30 Abertura da Vila para as escolas<br>10:00 Show infantil e recrea\u00e7\u00e3o<br>11h:30 Fechamento da vila<br>13h:30 Reabertura da vila<br>15h:00 Show Infantil e recrea\u00e7\u00e3o<br>16h:30 Fechamento da vila<br>19h:00 Abertura da Vila<br>19h:30 Abertura do atendimento na Casa do Papai Noel com recrea\u00e7\u00e3o<br>20h:00 Show Infantil<br>20h:30 Hora da neve<br>20:30 Show com Banda Fishmongers<br>21h:30 Hora da neve<br>22h:30 Show com Juninho Almeida e Banda<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>28\/11 (sexta-feira)<\/strong><br>19h:00 Abertura da Vila<br>19h:30 Abertura do atendimento na Casa do Papai Noel com recrea\u00e7\u00e3o<br>20h:00 Show Infantil<br>20h:30 Hora da neve<br>20h:30 Parada Natalina- Personagens<br>21h:00 Show com Banda Kali<br>21h:30 Hora da neve<br>23h:00 Show com Lucas e Bianchi e Banda<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>29\/11 (s\u00e1bado)<\/strong><br>19h:00 Abertura da Vila<br>19h:30 Abertura do atendimento na Casa do Papai Noel com recrea\u00e7\u00e3o<br>20h:00 Show Infantil<br>20h:30 Hora da neve<br>20h:30 Parada Natalina &#8211; Personagens<br>21h:00 Show com Breno Neto e Banda<br>21h:30 Hora da neve 23h:00 Show com a Banda Gt 80<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>30\/11 (domingo)<\/strong><br>19h:00 Abertura da Vila<br>19h:30 Abertura do atendimento na Casa do Papai Noel com recrea\u00e7\u00e3o<br>20h:00 Show Infantil<br>20h:30 Hora da neve<br>20h:30 Parada Natalina- Personagens<br>21h:00 Show Fabinho Nascimento e Banda<br>21h:30 Hora da neve<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>03\/12 (quarta-feira)<\/strong><br>08h:30 Abertura da Vila para as escolas<br>10h:00 Show infantil e recrea\u00e7\u00e3o<br>11h:30 Fechamento da vila<br>13h:30 Reabertura da vila<br>15h:00 Show Infantil e recrea\u00e7\u00e3o<br>16h:30 Fechamento da vila<br>19h:00 Abertura da Vila<br>19h:30 Abertura do atendimento na Casa do Papai Noel com recrea\u00e7\u00e3o<br>20h:00 Show Infantil 20h:30 Hora da neve<br>20:30 Show com Grupo Pagode do Jeff<br>21h:30 Hora da neve<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>04\/12 (quinta-feira)<\/strong><br>08h:30 Abertura da Vila para as escolas<br>10h:00 Show infantil e recrea\u00e7\u00e3o<br>11h:30 Fechamento da vila<br>13h:30 Reabertura da vila<br>15h:00 Show Infantil e recrea\u00e7\u00e3o<br>16h:30 Fechamento da vila<br>19h:00 Abertura da Vila<br>19h:30 Abertura do atendimento na Casa do Papai Noel com recrea\u00e7\u00e3o<br>20h:00 Show Infantil<br>20h:30 Hora da neve<br>20h:30 Show com Rafael Vieira Voz e Viol\u00e3o<br>21h:30 Hora da neve 22h:00 Show com Banda Lalitoral<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>05\/12(sexta feira)<\/strong><br>19h:00 Abertura da Vila<br>19h:30 Abertura do atendimento na Casa do Papai Noel com recrea\u00e7\u00e3o<br>20h:00 Show Infantil<br>20h:30 Hora da neve<br>20h:30 Parada Natalina &#8211; Personagens<br>21h:00 Show com Caio e Cristiano e Banda<br>21h:30 Hora da neve 23h:00 Show com Grupo Pagode Playlist<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>06\/12(S\u00e1bado)<\/strong><br>19h:00 Abertura da Vila<br>19h:30 Abertura do atendimento na Casa do Papai Noel com recrea\u00e7\u00e3o<br>20h:00 Show Infantil<br>20h:30 Hora da neve<br>20h:30 Parada Natalina- Personagens<br>21h:00 Show com Israel Lucero<br>21h:30 Hora da neve 23h:00 Show com Grupo Contagia samba<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>07\/12 (Domingo)<\/strong><br>19h:00 Abertura da Vila<br>19h:30 Abertura do atendimento na Casa do Papai Noel com recrea\u00e7\u00e3o<br>20h:00 Show Infantil 20h:30 Hora da neve<br>20h:30 Parada Musical 20h:30 Show com Grupo Azara\u00e7\u00e3o<br>21h:30 Hora da neve <br><br>10\/12 (quarta-feira) <br>08h:30 Abertura da Vila para as escolas<br>10:00 Show infantil e recrea\u00e7\u00e3o 11h:30 Fechamento da vila<br>13h:30 Reabertura da vila<br>15h:00 Show Infantil e recrea\u00e7\u00e3o<br>16h:30 Fechamento da vila<br>19h:00 Abertura da Vila<br>19h:30 Abertura do atendimento na Casa do Papai Noel com recrea\u00e7\u00e3o<br>20h:00 Show Infantil 20h:30 Hora da neve<br>20h:30 Show com Banda Plano Cruzado<br>21h:30 Hora da neve <br><br>11\/12( quinta feira)<br>08h:30 Abertura da Vila para as escolas<br>10h:00 Show infantil e recrea\u00e7\u00e3o<br>11h:30 Fechamento da vila<br>13h:30 Reabertura da vila<br>15h:00 Show Infantil e recrea\u00e7\u00e3o<br>16h:30 Fechamento da vila<br>19h:00 Abertura da Vila<br>19h:30 Abertura do atendimento na Casa do Papai Noel com recrea\u00e7\u00e3o<br>20h:00 Show Infantil<br>20h:30 Hora da neve<br>20h:30 Show com Trio Cai\u00e7ara<br>21h:30 Hora da neve 22h:00 Show com Mayckon Santos e banda<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>12\/12 (sexta)<\/strong><br>19h:00 Abertura da Vila<br>19h:15 Abertura do atendimento na Casa do Papai Noel com recrea\u00e7\u00e3o<br>20h:00 Show Infantil<br>20h:30 Hora da neve 20h:30 Parada Natalina- Personagens<br>21h:00 Show Mazzei Mattos e Banda<br>21h:30 Hora da neve<br>23h:00 Show com Banda Stone Jokers<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>13\/12(s\u00e1bado)<\/strong><br>19h:00 Abertura da Vila<br>19h:15 Abertura do atendimento na Casa do Papai Noel com recrea\u00e7\u00e3o<br>20h:00 Show Infantil<br>20h:30 Hora da neve<br>20h:30 Parada Natalina- Personagens<br>21h:00 Show com Richard Willian e Banda<br>21h:30 Hora da neve 23h:00 Show com Banda Flerte<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>14\/12(domingo)<\/strong><br>19h:00 Abertura da Vila<br>19h:30 Abertura do atendimento na Casa do Papai Noel com recrea\u00e7\u00e3o<br>20h:00 Show Infantil<br>20h:30 Parada Natalina- Personagens<br>20h:30 Hora da neve 20h:30 Show com Banda Vintage Culture<br>21h:30 Hora da neve<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>17\/12( quarta-feira)<\/strong><br>08h:30 Abertura da Vila para as escolas 1<br>10h:00 Show infantil e recrea\u00e7\u00e3o<br>11h:30 Fechamento da vila<br>13h:30 Reabertura da vila<br>15h:00 Show Infantil e recrea\u00e7\u00e3o<br>16h:30 Fechamento da vila<br>19h:00 Abertura da Vila<br>19h:30 Abertura do atendimento na Casa do Papai Noel com recrea\u00e7\u00e3o<br>20h:00 Show Infantil<br>20h:30 Hora da neve<br>20h:30 Show com Cazuza Cover e banda<br>21h:30 Hora da neve <br><br><strong>18\/12(quinta feira)<\/strong><br>08h:30 Abertura da Vila para as escolas<br>10:00 Show infantil e recrea\u00e7\u00e3o<br>11h:30 Fechamento da vila<br>13h:30 Reabertura da vila<br>15h:00 Show Infantil e recrea\u00e7\u00e3o<br>16h:30 Fechamento da vila<br>19h:00 Abertura da Vila<br>19h:30 Abertura do atendimento na Casa do Papai Noel com recrea\u00e7\u00e3o<br>20h:00 Show Infantil<br>20h:30 Hora da neve<br>20h:30 Show com Breno Neto e Banda<br>21h:30 Hora da neve<br>22h:00 Show com Banda Jimi Thing <br><br><strong>19\/12- (sexta-feira)<\/strong><br>19h:00 Abertura da Vila <br>19h:30 Abertura do atendimento na Casa do Papai Noel com recrea\u00e7\u00e3o<br>20h:00 Show Infantil<br>20h:30 Hora da neve<br>20h:30 Parada Natalina- Personagens<br>21h:00 Show com Grupo Pagode Playlist<br>21h:30 Hora da neve<br>23h:00 Show com Banda Honey Dreep<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>20\/12- (s\u00e1bado)<\/strong><br>19h:00 Abertura da Vila<br>19h:30 Abertura do atendimento na Casa do Papai Noel com recrea\u00e7\u00e3o<br>20h:00 Show Infantil<br>20h:30 Hora da neve<br>20h:30 Parada Natalina &#8211; Personagens<br>21h:00 Show com kamila Ferraz e Banda<br>21h:30 Hora da neve<br>23h:00 Show com Mayckow Santos e banda<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>21\/12 (domingo)<\/strong><br>19h:00 Abertura da Vila<br>19h:30 Abertura do atendimento na Casa do Papai Noel com recrea\u00e7\u00e3o<br>20h:00 Show Infantil<br>20h:30 Hora da neve<br>20h:30 Parada Natalina- Personagens<br>21h:00 Show com Trio Cai\u00e7ara<br>21h:30 Hora da neve 23h:00 Show com a Banda Mr. Mcfly<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>22\/12 (segunda feira)<\/strong><br>19h:00 Abertura da Vila<br>19h:30 Abertura do atendimento na Casa do Papai Noel com recrea\u00e7\u00e3o<br>20h:00 Show Infantil<br>20h:30 Hora da neve<br>20h30 Show com Banda Stone Jokers<br>21h:30 Hora da neve<br>22h:00 Show com Fabinho Nascimento e Banda<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>23\/12 (ter\u00e7a feira)<\/strong><br>19h:00 Abertura da Vila<br>19h:30 Abertura do atendimento na Casa do Papai Noel com recrea\u00e7\u00e3o<br>20h:00 Hora da neve<br>20h:30 Parada Natalina- Personagens <br>20h:30 Show com a Orquestra Sinf\u00f4nica de Santa Catarina<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<div class=\"wp-block-buttons is-horizontal is-content-justification-center is-nowrap is-layout-flex wp-container-core-buttons-is-layout-c9c93e97 wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button has-custom-width wp-block-button__width-75 is-style-fill\"><a class=\"wp-block-button__link has-black-color has-vivid-green-cyan-background-color has-text-color has-background has-link-color has-text-align-center has-custom-font-size wp-element-button\" href=\"https:\/\/chat.whatsapp.com\/DJkjPyw34SVCxRUdvlspB8\" style=\"border-radius:14px;font-size:18px;text-decoration:none\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">Participe do grupo do <strong>Jornal nos Bairros<\/strong><\/a><\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Confira a programa\u00e7\u00e3o completa do Natal em Navegantes Neste s\u00e1bado (22), a partir das 19 horas, inicia o Natal de Encantos em Navegantes. A Arena de Eventos do bairro S\u00e3o Pedro (Pontal) vai&hellip;<\/p>\n","protected":false},"author":1,"featured_media":43288,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ai_generated_summary":"","footnotes":""},"categories":[31],"tags":[],"class_list":["post-43263","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-navegantes"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Natal de Encantos inicia neste s\u00e1bado em Navegantes - Jornal nos Bairros<\/title>\n<meta name=\"description\" content=\"Neste s\u00e1bado (22), a partir das 19 horas, inicia o Natal de Encantos em Navegantes. Confira a programa\u00e7\u00e3o completa.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/jornalnosbairros.com.br\/wp\/2025\/11\/natal-de-encantos-inicia-neste-sabado-em-navegantes\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Natal de Encantos inicia neste s\u00e1bado em Navegantes - Jornal nos Bairros\" \/>\n<meta property=\"og:description\" content=\"Neste s\u00e1bado (22), a partir das 19 horas, inicia o Natal de Encantos em Navegantes. Confira a programa\u00e7\u00e3o completa.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/jornalnosbairros.com.br\/wp\/2025\/11\/natal-de-encantos-inicia-neste-sabado-em-navegantes\/\" \/>\n<meta property=\"og:site_name\" content=\"Jornal nos Bairros\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/jornalnosbairros\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/jornalnosbairros\" \/>\n<meta property=\"article:published_time\" content=\"2025-11-20T13:43:02+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-11-21T19:38:47+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/jornalnosbairros.com.br\/wp\/wp-content\/uploads\/2025\/11\/Vila-de-Natal-de-Navegantes-por-Eder-Nascimento.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"936\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Editoria\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/jornal_bairros\" \/>\n<meta name=\"twitter:site\" content=\"@jornal_bairros\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Editoria\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/2025\\\/11\\\/natal-de-encantos-inicia-neste-sabado-em-navegantes\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/2025\\\/11\\\/natal-de-encantos-inicia-neste-sabado-em-navegantes\\\/\"},\"author\":{\"name\":\"Editoria\",\"@id\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/#\\\/schema\\\/person\\\/9a74fde2f4332c018c3b4d29a6129437\"},\"headline\":\"Natal de Encantos inicia neste s\u00e1bado em Navegantes\",\"datePublished\":\"2025-11-20T13:43:02+00:00\",\"dateModified\":\"2025-11-21T19:38:47+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/2025\\\/11\\\/natal-de-encantos-inicia-neste-sabado-em-navegantes\\\/\"},\"wordCount\":1329,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/2025\\\/11\\\/natal-de-encantos-inicia-neste-sabado-em-navegantes\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/Vila-de-Natal-de-Navegantes-por-Eder-Nascimento.jpeg\",\"articleSection\":[\"NAVEGANTES\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/2025\\\/11\\\/natal-de-encantos-inicia-neste-sabado-em-navegantes\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/2025\\\/11\\\/natal-de-encantos-inicia-neste-sabado-em-navegantes\\\/\",\"url\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/2025\\\/11\\\/natal-de-encantos-inicia-neste-sabado-em-navegantes\\\/\",\"name\":\"Natal de Encantos inicia neste s\u00e1bado em Navegantes - Jornal nos Bairros\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/2025\\\/11\\\/natal-de-encantos-inicia-neste-sabado-em-navegantes\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/2025\\\/11\\\/natal-de-encantos-inicia-neste-sabado-em-navegantes\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/Vila-de-Natal-de-Navegantes-por-Eder-Nascimento.jpeg\",\"datePublished\":\"2025-11-20T13:43:02+00:00\",\"dateModified\":\"2025-11-21T19:38:47+00:00\",\"description\":\"Neste s\u00e1bado (22), a partir das 19 horas, inicia o Natal de Encantos em Navegantes. Confira a programa\u00e7\u00e3o completa.\",\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/2025\\\/11\\\/natal-de-encantos-inicia-neste-sabado-em-navegantes\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/2025\\\/11\\\/natal-de-encantos-inicia-neste-sabado-em-navegantes\\\/#primaryimage\",\"url\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/Vila-de-Natal-de-Navegantes-por-Eder-Nascimento.jpeg\",\"contentUrl\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/Vila-de-Natal-de-Navegantes-por-Eder-Nascimento.jpeg\",\"width\":1280,\"height\":936,\"caption\":\"Vila de Natal de Navegantes por Eder Nascimento\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/#website\",\"url\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/\",\"name\":\"Jornal nos Bairros\",\"description\":\"Not\u00edcias di\u00e1rias de Navegantes e regi\u00e3o\",\"publisher\":{\"@id\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/#organization\"},\"alternateName\":\"JB\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/#organization\",\"name\":\"Jornal nos Bairros de Navegantes\",\"url\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/LOGO-JB.png\",\"contentUrl\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/LOGO-JB.png\",\"width\":168,\"height\":150,\"caption\":\"Jornal nos Bairros de Navegantes\"},\"image\":{\"@id\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/jornalnosbairros\",\"https:\\\/\\\/x.com\\\/jornal_bairros\",\"https:\\\/\\\/www.instagram.com\\\/jornalnosbairros\",\"https:\\\/\\\/www.youtube.com\\\/@jornalnosbairros\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/#\\\/schema\\\/person\\\/9a74fde2f4332c018c3b4d29a6129437\",\"name\":\"Editoria\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b53a04b7003d01b914d43ebacd13b233f0d99ed1cb7f8cb7d8553ef90e3f466b?s=96&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b53a04b7003d01b914d43ebacd13b233f0d99ed1cb7f8cb7d8553ef90e3f466b?s=96&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b53a04b7003d01b914d43ebacd13b233f0d99ed1cb7f8cb7d8553ef90e3f466b?s=96&r=g\",\"caption\":\"Editoria\"},\"description\":\"Edi\u00e7\u00e3o do Jornal nos Bairros de Navegantes - Contato: fale@jornalnosbairros.com.br - Siga: @jornalnosbairros - Acesse: www.jornalnosbairros.com.br\",\"sameAs\":[\"http:\\\/\\\/www.jornalnosbairros.com.br\\\/wp\",\"https:\\\/\\\/www.facebook.com\\\/jornalnosbairros\",\"https:\\\/\\\/www.instagram.com\\\/jornalnosbairros\\\/\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/jornal_bairros\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCbdZNY5wPbaBq5KtRGP4WxQ?view_as=subscriber\"],\"url\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Natal de Encantos inicia neste s\u00e1bado em Navegantes - Jornal nos Bairros","description":"Neste s\u00e1bado (22), a partir das 19 horas, inicia o Natal de Encantos em Navegantes. Confira a programa\u00e7\u00e3o completa.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/jornalnosbairros.com.br\/wp\/2025\/11\/natal-de-encantos-inicia-neste-sabado-em-navegantes\/","og_locale":"pt_BR","og_type":"article","og_title":"Natal de Encantos inicia neste s\u00e1bado em Navegantes - Jornal nos Bairros","og_description":"Neste s\u00e1bado (22), a partir das 19 horas, inicia o Natal de Encantos em Navegantes. Confira a programa\u00e7\u00e3o completa.","og_url":"https:\/\/jornalnosbairros.com.br\/wp\/2025\/11\/natal-de-encantos-inicia-neste-sabado-em-navegantes\/","og_site_name":"Jornal nos Bairros","article_publisher":"https:\/\/www.facebook.com\/jornalnosbairros","article_author":"https:\/\/www.facebook.com\/jornalnosbairros","article_published_time":"2025-11-20T13:43:02+00:00","article_modified_time":"2025-11-21T19:38:47+00:00","og_image":[{"width":1280,"height":936,"url":"https:\/\/jornalnosbairros.com.br\/wp\/wp-content\/uploads\/2025\/11\/Vila-de-Natal-de-Navegantes-por-Eder-Nascimento.jpeg","type":"image\/jpeg"}],"author":"Editoria","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/jornal_bairros","twitter_site":"@jornal_bairros","twitter_misc":{"Escrito por":"Editoria","Est. tempo de leitura":"7 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/jornalnosbairros.com.br\/wp\/2025\/11\/natal-de-encantos-inicia-neste-sabado-em-navegantes\/#article","isPartOf":{"@id":"https:\/\/jornalnosbairros.com.br\/wp\/2025\/11\/natal-de-encantos-inicia-neste-sabado-em-navegantes\/"},"author":{"name":"Editoria","@id":"https:\/\/jornalnosbairros.com.br\/wp\/#\/schema\/person\/9a74fde2f4332c018c3b4d29a6129437"},"headline":"Natal de Encantos inicia neste s\u00e1bado em Navegantes","datePublished":"2025-11-20T13:43:02+00:00","dateModified":"2025-11-21T19:38:47+00:00","mainEntityOfPage":{"@id":"https:\/\/jornalnosbairros.com.br\/wp\/2025\/11\/natal-de-encantos-inicia-neste-sabado-em-navegantes\/"},"wordCount":1329,"commentCount":0,"publisher":{"@id":"https:\/\/jornalnosbairros.com.br\/wp\/#organization"},"image":{"@id":"https:\/\/jornalnosbairros.com.br\/wp\/2025\/11\/natal-de-encantos-inicia-neste-sabado-em-navegantes\/#primaryimage"},"thumbnailUrl":"https:\/\/jornalnosbairros.com.br\/wp\/wp-content\/uploads\/2025\/11\/Vila-de-Natal-de-Navegantes-por-Eder-Nascimento.jpeg","articleSection":["NAVEGANTES"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/jornalnosbairros.com.br\/wp\/2025\/11\/natal-de-encantos-inicia-neste-sabado-em-navegantes\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/jornalnosbairros.com.br\/wp\/2025\/11\/natal-de-encantos-inicia-neste-sabado-em-navegantes\/","url":"https:\/\/jornalnosbairros.com.br\/wp\/2025\/11\/natal-de-encantos-inicia-neste-sabado-em-navegantes\/","name":"Natal de Encantos inicia neste s\u00e1bado em Navegantes - Jornal nos Bairros","isPartOf":{"@id":"https:\/\/jornalnosbairros.com.br\/wp\/#website"},"primaryImageOfPage":{"@id":"https:\/\/jornalnosbairros.com.br\/wp\/2025\/11\/natal-de-encantos-inicia-neste-sabado-em-navegantes\/#primaryimage"},"image":{"@id":"https:\/\/jornalnosbairros.com.br\/wp\/2025\/11\/natal-de-encantos-inicia-neste-sabado-em-navegantes\/#primaryimage"},"thumbnailUrl":"https:\/\/jornalnosbairros.com.br\/wp\/wp-content\/uploads\/2025\/11\/Vila-de-Natal-de-Navegantes-por-Eder-Nascimento.jpeg","datePublished":"2025-11-20T13:43:02+00:00","dateModified":"2025-11-21T19:38:47+00:00","description":"Neste s\u00e1bado (22), a partir das 19 horas, inicia o Natal de Encantos em Navegantes. Confira a programa\u00e7\u00e3o completa.","inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/jornalnosbairros.com.br\/wp\/2025\/11\/natal-de-encantos-inicia-neste-sabado-em-navegantes\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/jornalnosbairros.com.br\/wp\/2025\/11\/natal-de-encantos-inicia-neste-sabado-em-navegantes\/#primaryimage","url":"https:\/\/jornalnosbairros.com.br\/wp\/wp-content\/uploads\/2025\/11\/Vila-de-Natal-de-Navegantes-por-Eder-Nascimento.jpeg","contentUrl":"https:\/\/jornalnosbairros.com.br\/wp\/wp-content\/uploads\/2025\/11\/Vila-de-Natal-de-Navegantes-por-Eder-Nascimento.jpeg","width":1280,"height":936,"caption":"Vila de Natal de Navegantes por Eder Nascimento"},{"@type":"WebSite","@id":"https:\/\/jornalnosbairros.com.br\/wp\/#website","url":"https:\/\/jornalnosbairros.com.br\/wp\/","name":"Jornal nos Bairros","description":"Not\u00edcias di\u00e1rias de Navegantes e regi\u00e3o","publisher":{"@id":"https:\/\/jornalnosbairros.com.br\/wp\/#organization"},"alternateName":"JB","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/jornalnosbairros.com.br\/wp\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/jornalnosbairros.com.br\/wp\/#organization","name":"Jornal nos Bairros de Navegantes","url":"https:\/\/jornalnosbairros.com.br\/wp\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/jornalnosbairros.com.br\/wp\/#\/schema\/logo\/image\/","url":"https:\/\/jornalnosbairros.com.br\/wp\/wp-content\/uploads\/2025\/01\/LOGO-JB.png","contentUrl":"https:\/\/jornalnosbairros.com.br\/wp\/wp-content\/uploads\/2025\/01\/LOGO-JB.png","width":168,"height":150,"caption":"Jornal nos Bairros de Navegantes"},"image":{"@id":"https:\/\/jornalnosbairros.com.br\/wp\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/jornalnosbairros","https:\/\/x.com\/jornal_bairros","https:\/\/www.instagram.com\/jornalnosbairros","https:\/\/www.youtube.com\/@jornalnosbairros"]},{"@type":"Person","@id":"https:\/\/jornalnosbairros.com.br\/wp\/#\/schema\/person\/9a74fde2f4332c018c3b4d29a6129437","name":"Editoria","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/b53a04b7003d01b914d43ebacd13b233f0d99ed1cb7f8cb7d8553ef90e3f466b?s=96&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b53a04b7003d01b914d43ebacd13b233f0d99ed1cb7f8cb7d8553ef90e3f466b?s=96&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b53a04b7003d01b914d43ebacd13b233f0d99ed1cb7f8cb7d8553ef90e3f466b?s=96&r=g","caption":"Editoria"},"description":"Edi\u00e7\u00e3o do Jornal nos Bairros de Navegantes - Contato: fale@jornalnosbairros.com.br - Siga: @jornalnosbairros - Acesse: www.jornalnosbairros.com.br","sameAs":["http:\/\/www.jornalnosbairros.com.br\/wp","https:\/\/www.facebook.com\/jornalnosbairros","https:\/\/www.instagram.com\/jornalnosbairros\/","https:\/\/x.com\/https:\/\/twitter.com\/jornal_bairros","https:\/\/www.youtube.com\/channel\/UCbdZNY5wPbaBq5KtRGP4WxQ?view_as=subscriber"],"url":"https:\/\/jornalnosbairros.com.br\/wp\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/jornalnosbairros.com.br\/wp\/wp-json\/wp\/v2\/posts\/43263","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jornalnosbairros.com.br\/wp\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jornalnosbairros.com.br\/wp\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jornalnosbairros.com.br\/wp\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/jornalnosbairros.com.br\/wp\/wp-json\/wp\/v2\/comments?post=43263"}],"version-history":[{"count":2,"href":"https:\/\/jornalnosbairros.com.br\/wp\/wp-json\/wp\/v2\/posts\/43263\/revisions"}],"predecessor-version":[{"id":43291,"href":"https:\/\/jornalnosbairros.com.br\/wp\/wp-json\/wp\/v2\/posts\/43263\/revisions\/43291"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/jornalnosbairros.com.br\/wp\/wp-json\/wp\/v2\/media\/43288"}],"wp:attachment":[{"href":"https:\/\/jornalnosbairros.com.br\/wp\/wp-json\/wp\/v2\/media?parent=43263"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jornalnosbairros.com.br\/wp\/wp-json\/wp\/v2\/categories?post=43263"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jornalnosbairros.com.br\/wp\/wp-json\/wp\/v2\/tags?post=43263"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}