{"id":42779,"date":"2025-10-29T15:58:57","date_gmt":"2025-10-29T18:58:57","guid":{"rendered":"https:\/\/jornalnosbairros.com.br\/wp\/?p=42779"},"modified":"2025-10-29T16:01:36","modified_gmt":"2025-10-29T19:01:36","slug":"projeto-idealizado-em-navegantes-recebe-aplausos-da-assembleia-legislativa","status":"publish","type":"post","link":"https:\/\/jornalnosbairros.com.br\/wp\/2025\/10\/projeto-idealizado-em-navegantes-recebe-aplausos-da-assembleia-legislativa\/","title":{"rendered":"Projeto idealizado em Navegantes recebe aplausos da Assembleia Legislativa"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong><em>O projeto &#8220;Navegando no Conhecimento\u201d leva a hist\u00f3ria e o universo da pesca artesanal para dentro da sala de aula.<\/em><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O munic\u00edpio de Navegantes recebeu aplausos durante sess\u00e3o itinerante da Assembleia Legislativa de Santa Catarina realizada na ter\u00e7a-feira (28), em Balne\u00e1rio Cambori\u00fa. O Assessor Especial de Pesca, Fabiano Velozo, idealizador do projeto &#8220;Navegando no Conhecimento\u201d, recebeu a mo\u00e7\u00e3o das m\u00e3os da deputada Paulinha (PODEMOS), autora da proposi\u00e7\u00e3o. &nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O projeto, reconhecido a n\u00edvel estadual, \u00e9 realizado pela Secretaria de Agricultura, Pesca e Pecu\u00e1ria de Navegantes em parceria com a Secretaria de Educa\u00e7\u00e3o. Ele leva a hist\u00f3ria e o universo da pesca artesanal para dentro das escolas, com objetivo de despertar o sentimento de valoriza\u00e7\u00e3o e respeito por essa atividade que sustenta milhares de fam\u00edlias na cidade.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Os alunos recebem palestras, din\u00e2micas e exibi\u00e7\u00e3o de materiais que mostram a import\u00e2ncia da pesca para o desenvolvimento local, destacando aspectos hist\u00f3ricos, econ\u00f4micos, sociais e ambientais.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Para o assessor, a import\u00e2ncia dessa tradi\u00e7\u00e3o ser apresentada \u00e0s novas gera\u00e7\u00f5es de forma educativa e envolvente est\u00e1 na liga\u00e7\u00e3o da hist\u00f3ria, economia e identidade cultural de Navegantes \u00e0 atividade pesqueira.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por isso, os alunos aprendem aspectos do dia-a-dia na pesca artesanal \u2014 desde as embarca\u00e7\u00f5es e apetrechos at\u00e9 as hist\u00f3rias e desafios que marcam a profiss\u00e3o. As explica\u00e7\u00f5es despertam curiosidade e trazem \u00e0 tona o orgulho por uma tradi\u00e7\u00e3o que sustenta fam\u00edlias e preserva a identidade mar\u00edtima de Navegantes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Al\u00e9m de aproximar a comunidade escolar dos pescadores, a iniciativa tamb\u00e9m incentiva a educa\u00e7\u00e3o ambiental, mostrando boas pr\u00e1ticas e a necessidade de um uso respons\u00e1vel dos recursos naturais.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O projeto &#8220;Navegando no Conhecimento\u201d leva a hist\u00f3ria e o universo da pesca artesanal para dentro da sala de aula. O munic\u00edpio de Navegantes recebeu aplausos durante sess\u00e3o itinerante da Assembleia Legislativa de&hellip;<\/p>\n","protected":false},"author":1,"featured_media":42782,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ai_generated_summary":"","footnotes":""},"categories":[3],"tags":[],"class_list":["post-42779","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-geral"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Projeto idealizado em Navegantes recebe aplausos da Assembleia Legislativa - Jornal nos Bairros<\/title>\n<meta name=\"description\" content=\"Projeto Navegando no Conhecimento, idealizado em Navegantes, recebeu mo\u00e7\u00e3o de aplausos da Assembleia Legislativa\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/jornalnosbairros.com.br\/wp\/2025\/10\/projeto-idealizado-em-navegantes-recebe-aplausos-da-assembleia-legislativa\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Projeto idealizado em Navegantes recebe aplausos da Assembleia Legislativa - Jornal nos Bairros\" \/>\n<meta property=\"og:description\" content=\"Projeto Navegando no Conhecimento, idealizado em Navegantes, recebeu mo\u00e7\u00e3o de aplausos da Assembleia Legislativa\" \/>\n<meta property=\"og:url\" content=\"https:\/\/jornalnosbairros.com.br\/wp\/2025\/10\/projeto-idealizado-em-navegantes-recebe-aplausos-da-assembleia-legislativa\/\" \/>\n<meta property=\"og:site_name\" content=\"Jornal nos Bairros\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/jornalnosbairros\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/jornalnosbairros\" \/>\n<meta property=\"article:published_time\" content=\"2025-10-29T18:58:57+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-29T19:01:36+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/jornalnosbairros.com.br\/wp\/wp-content\/uploads\/2025\/10\/Projeto-idealizado-em-Navegantes-recebe-mocao-de-aplausos-na-Assembleia-Legislativa-2-e1761764487122.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1352\" \/>\n\t<meta property=\"og:image:height\" content=\"963\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Editoria\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/jornal_bairros\" \/>\n<meta name=\"twitter:site\" content=\"@jornal_bairros\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Editoria\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/2025\\\/10\\\/projeto-idealizado-em-navegantes-recebe-aplausos-da-assembleia-legislativa\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/2025\\\/10\\\/projeto-idealizado-em-navegantes-recebe-aplausos-da-assembleia-legislativa\\\/\"},\"author\":{\"name\":\"Editoria\",\"@id\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/#\\\/schema\\\/person\\\/9a74fde2f4332c018c3b4d29a6129437\"},\"headline\":\"Projeto idealizado em Navegantes recebe aplausos da Assembleia Legislativa\",\"datePublished\":\"2025-10-29T18:58:57+00:00\",\"dateModified\":\"2025-10-29T19:01:36+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/2025\\\/10\\\/projeto-idealizado-em-navegantes-recebe-aplausos-da-assembleia-legislativa\\\/\"},\"wordCount\":300,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/2025\\\/10\\\/projeto-idealizado-em-navegantes-recebe-aplausos-da-assembleia-legislativa\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/Projeto-idealizado-em-Navegantes-recebe-mocao-de-aplausos-na-Assembleia-Legislativa-2-e1761764487122.jpeg\",\"articleSection\":[\"GERAL\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/2025\\\/10\\\/projeto-idealizado-em-navegantes-recebe-aplausos-da-assembleia-legislativa\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/2025\\\/10\\\/projeto-idealizado-em-navegantes-recebe-aplausos-da-assembleia-legislativa\\\/\",\"url\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/2025\\\/10\\\/projeto-idealizado-em-navegantes-recebe-aplausos-da-assembleia-legislativa\\\/\",\"name\":\"Projeto idealizado em Navegantes recebe aplausos da Assembleia Legislativa - Jornal nos Bairros\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/2025\\\/10\\\/projeto-idealizado-em-navegantes-recebe-aplausos-da-assembleia-legislativa\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/2025\\\/10\\\/projeto-idealizado-em-navegantes-recebe-aplausos-da-assembleia-legislativa\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/Projeto-idealizado-em-Navegantes-recebe-mocao-de-aplausos-na-Assembleia-Legislativa-2-e1761764487122.jpeg\",\"datePublished\":\"2025-10-29T18:58:57+00:00\",\"dateModified\":\"2025-10-29T19:01:36+00:00\",\"description\":\"Projeto Navegando no Conhecimento, idealizado em Navegantes, recebeu mo\u00e7\u00e3o de aplausos da Assembleia Legislativa\",\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/2025\\\/10\\\/projeto-idealizado-em-navegantes-recebe-aplausos-da-assembleia-legislativa\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/2025\\\/10\\\/projeto-idealizado-em-navegantes-recebe-aplausos-da-assembleia-legislativa\\\/#primaryimage\",\"url\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/Projeto-idealizado-em-Navegantes-recebe-mocao-de-aplausos-na-Assembleia-Legislativa-2-e1761764487122.jpeg\",\"contentUrl\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/Projeto-idealizado-em-Navegantes-recebe-mocao-de-aplausos-na-Assembleia-Legislativa-2-e1761764487122.jpeg\",\"width\":1352,\"height\":963},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/#website\",\"url\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/\",\"name\":\"Jornal nos Bairros\",\"description\":\"Not\u00edcias di\u00e1rias de Navegantes e regi\u00e3o\",\"publisher\":{\"@id\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/#organization\"},\"alternateName\":\"JB\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/#organization\",\"name\":\"Jornal nos Bairros de Navegantes\",\"url\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/LOGO-JB.png\",\"contentUrl\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/LOGO-JB.png\",\"width\":168,\"height\":150,\"caption\":\"Jornal nos Bairros de Navegantes\"},\"image\":{\"@id\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/jornalnosbairros\",\"https:\\\/\\\/x.com\\\/jornal_bairros\",\"https:\\\/\\\/www.instagram.com\\\/jornalnosbairros\",\"https:\\\/\\\/www.youtube.com\\\/@jornalnosbairros\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/#\\\/schema\\\/person\\\/9a74fde2f4332c018c3b4d29a6129437\",\"name\":\"Editoria\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b53a04b7003d01b914d43ebacd13b233f0d99ed1cb7f8cb7d8553ef90e3f466b?s=96&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b53a04b7003d01b914d43ebacd13b233f0d99ed1cb7f8cb7d8553ef90e3f466b?s=96&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b53a04b7003d01b914d43ebacd13b233f0d99ed1cb7f8cb7d8553ef90e3f466b?s=96&r=g\",\"caption\":\"Editoria\"},\"description\":\"Edi\u00e7\u00e3o do Jornal nos Bairros de Navegantes - Contato: fale@jornalnosbairros.com.br - Siga: @jornalnosbairros - Acesse: www.jornalnosbairros.com.br\",\"sameAs\":[\"http:\\\/\\\/www.jornalnosbairros.com.br\\\/wp\",\"https:\\\/\\\/www.facebook.com\\\/jornalnosbairros\",\"https:\\\/\\\/www.instagram.com\\\/jornalnosbairros\\\/\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/jornal_bairros\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCbdZNY5wPbaBq5KtRGP4WxQ?view_as=subscriber\"],\"url\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Projeto idealizado em Navegantes recebe aplausos da Assembleia Legislativa - Jornal nos Bairros","description":"Projeto Navegando no Conhecimento, idealizado em Navegantes, recebeu mo\u00e7\u00e3o de aplausos da Assembleia Legislativa","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/jornalnosbairros.com.br\/wp\/2025\/10\/projeto-idealizado-em-navegantes-recebe-aplausos-da-assembleia-legislativa\/","og_locale":"pt_BR","og_type":"article","og_title":"Projeto idealizado em Navegantes recebe aplausos da Assembleia Legislativa - Jornal nos Bairros","og_description":"Projeto Navegando no Conhecimento, idealizado em Navegantes, recebeu mo\u00e7\u00e3o de aplausos da Assembleia Legislativa","og_url":"https:\/\/jornalnosbairros.com.br\/wp\/2025\/10\/projeto-idealizado-em-navegantes-recebe-aplausos-da-assembleia-legislativa\/","og_site_name":"Jornal nos Bairros","article_publisher":"https:\/\/www.facebook.com\/jornalnosbairros","article_author":"https:\/\/www.facebook.com\/jornalnosbairros","article_published_time":"2025-10-29T18:58:57+00:00","article_modified_time":"2025-10-29T19:01:36+00:00","og_image":[{"width":1352,"height":963,"url":"https:\/\/jornalnosbairros.com.br\/wp\/wp-content\/uploads\/2025\/10\/Projeto-idealizado-em-Navegantes-recebe-mocao-de-aplausos-na-Assembleia-Legislativa-2-e1761764487122.jpeg","type":"image\/jpeg"}],"author":"Editoria","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/jornal_bairros","twitter_site":"@jornal_bairros","twitter_misc":{"Escrito por":"Editoria","Est. tempo de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/jornalnosbairros.com.br\/wp\/2025\/10\/projeto-idealizado-em-navegantes-recebe-aplausos-da-assembleia-legislativa\/#article","isPartOf":{"@id":"https:\/\/jornalnosbairros.com.br\/wp\/2025\/10\/projeto-idealizado-em-navegantes-recebe-aplausos-da-assembleia-legislativa\/"},"author":{"name":"Editoria","@id":"https:\/\/jornalnosbairros.com.br\/wp\/#\/schema\/person\/9a74fde2f4332c018c3b4d29a6129437"},"headline":"Projeto idealizado em Navegantes recebe aplausos da Assembleia Legislativa","datePublished":"2025-10-29T18:58:57+00:00","dateModified":"2025-10-29T19:01:36+00:00","mainEntityOfPage":{"@id":"https:\/\/jornalnosbairros.com.br\/wp\/2025\/10\/projeto-idealizado-em-navegantes-recebe-aplausos-da-assembleia-legislativa\/"},"wordCount":300,"commentCount":0,"publisher":{"@id":"https:\/\/jornalnosbairros.com.br\/wp\/#organization"},"image":{"@id":"https:\/\/jornalnosbairros.com.br\/wp\/2025\/10\/projeto-idealizado-em-navegantes-recebe-aplausos-da-assembleia-legislativa\/#primaryimage"},"thumbnailUrl":"https:\/\/jornalnosbairros.com.br\/wp\/wp-content\/uploads\/2025\/10\/Projeto-idealizado-em-Navegantes-recebe-mocao-de-aplausos-na-Assembleia-Legislativa-2-e1761764487122.jpeg","articleSection":["GERAL"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/jornalnosbairros.com.br\/wp\/2025\/10\/projeto-idealizado-em-navegantes-recebe-aplausos-da-assembleia-legislativa\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/jornalnosbairros.com.br\/wp\/2025\/10\/projeto-idealizado-em-navegantes-recebe-aplausos-da-assembleia-legislativa\/","url":"https:\/\/jornalnosbairros.com.br\/wp\/2025\/10\/projeto-idealizado-em-navegantes-recebe-aplausos-da-assembleia-legislativa\/","name":"Projeto idealizado em Navegantes recebe aplausos da Assembleia Legislativa - Jornal nos Bairros","isPartOf":{"@id":"https:\/\/jornalnosbairros.com.br\/wp\/#website"},"primaryImageOfPage":{"@id":"https:\/\/jornalnosbairros.com.br\/wp\/2025\/10\/projeto-idealizado-em-navegantes-recebe-aplausos-da-assembleia-legislativa\/#primaryimage"},"image":{"@id":"https:\/\/jornalnosbairros.com.br\/wp\/2025\/10\/projeto-idealizado-em-navegantes-recebe-aplausos-da-assembleia-legislativa\/#primaryimage"},"thumbnailUrl":"https:\/\/jornalnosbairros.com.br\/wp\/wp-content\/uploads\/2025\/10\/Projeto-idealizado-em-Navegantes-recebe-mocao-de-aplausos-na-Assembleia-Legislativa-2-e1761764487122.jpeg","datePublished":"2025-10-29T18:58:57+00:00","dateModified":"2025-10-29T19:01:36+00:00","description":"Projeto Navegando no Conhecimento, idealizado em Navegantes, recebeu mo\u00e7\u00e3o de aplausos da Assembleia Legislativa","inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/jornalnosbairros.com.br\/wp\/2025\/10\/projeto-idealizado-em-navegantes-recebe-aplausos-da-assembleia-legislativa\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/jornalnosbairros.com.br\/wp\/2025\/10\/projeto-idealizado-em-navegantes-recebe-aplausos-da-assembleia-legislativa\/#primaryimage","url":"https:\/\/jornalnosbairros.com.br\/wp\/wp-content\/uploads\/2025\/10\/Projeto-idealizado-em-Navegantes-recebe-mocao-de-aplausos-na-Assembleia-Legislativa-2-e1761764487122.jpeg","contentUrl":"https:\/\/jornalnosbairros.com.br\/wp\/wp-content\/uploads\/2025\/10\/Projeto-idealizado-em-Navegantes-recebe-mocao-de-aplausos-na-Assembleia-Legislativa-2-e1761764487122.jpeg","width":1352,"height":963},{"@type":"WebSite","@id":"https:\/\/jornalnosbairros.com.br\/wp\/#website","url":"https:\/\/jornalnosbairros.com.br\/wp\/","name":"Jornal nos Bairros","description":"Not\u00edcias di\u00e1rias de Navegantes e regi\u00e3o","publisher":{"@id":"https:\/\/jornalnosbairros.com.br\/wp\/#organization"},"alternateName":"JB","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/jornalnosbairros.com.br\/wp\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/jornalnosbairros.com.br\/wp\/#organization","name":"Jornal nos Bairros de Navegantes","url":"https:\/\/jornalnosbairros.com.br\/wp\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/jornalnosbairros.com.br\/wp\/#\/schema\/logo\/image\/","url":"https:\/\/jornalnosbairros.com.br\/wp\/wp-content\/uploads\/2025\/01\/LOGO-JB.png","contentUrl":"https:\/\/jornalnosbairros.com.br\/wp\/wp-content\/uploads\/2025\/01\/LOGO-JB.png","width":168,"height":150,"caption":"Jornal nos Bairros de Navegantes"},"image":{"@id":"https:\/\/jornalnosbairros.com.br\/wp\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/jornalnosbairros","https:\/\/x.com\/jornal_bairros","https:\/\/www.instagram.com\/jornalnosbairros","https:\/\/www.youtube.com\/@jornalnosbairros"]},{"@type":"Person","@id":"https:\/\/jornalnosbairros.com.br\/wp\/#\/schema\/person\/9a74fde2f4332c018c3b4d29a6129437","name":"Editoria","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/b53a04b7003d01b914d43ebacd13b233f0d99ed1cb7f8cb7d8553ef90e3f466b?s=96&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b53a04b7003d01b914d43ebacd13b233f0d99ed1cb7f8cb7d8553ef90e3f466b?s=96&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b53a04b7003d01b914d43ebacd13b233f0d99ed1cb7f8cb7d8553ef90e3f466b?s=96&r=g","caption":"Editoria"},"description":"Edi\u00e7\u00e3o do Jornal nos Bairros de Navegantes - Contato: fale@jornalnosbairros.com.br - Siga: @jornalnosbairros - Acesse: www.jornalnosbairros.com.br","sameAs":["http:\/\/www.jornalnosbairros.com.br\/wp","https:\/\/www.facebook.com\/jornalnosbairros","https:\/\/www.instagram.com\/jornalnosbairros\/","https:\/\/x.com\/https:\/\/twitter.com\/jornal_bairros","https:\/\/www.youtube.com\/channel\/UCbdZNY5wPbaBq5KtRGP4WxQ?view_as=subscriber"],"url":"https:\/\/jornalnosbairros.com.br\/wp\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/jornalnosbairros.com.br\/wp\/wp-json\/wp\/v2\/posts\/42779","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jornalnosbairros.com.br\/wp\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jornalnosbairros.com.br\/wp\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jornalnosbairros.com.br\/wp\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/jornalnosbairros.com.br\/wp\/wp-json\/wp\/v2\/comments?post=42779"}],"version-history":[{"count":1,"href":"https:\/\/jornalnosbairros.com.br\/wp\/wp-json\/wp\/v2\/posts\/42779\/revisions"}],"predecessor-version":[{"id":42781,"href":"https:\/\/jornalnosbairros.com.br\/wp\/wp-json\/wp\/v2\/posts\/42779\/revisions\/42781"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/jornalnosbairros.com.br\/wp\/wp-json\/wp\/v2\/media\/42782"}],"wp:attachment":[{"href":"https:\/\/jornalnosbairros.com.br\/wp\/wp-json\/wp\/v2\/media?parent=42779"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jornalnosbairros.com.br\/wp\/wp-json\/wp\/v2\/categories?post=42779"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jornalnosbairros.com.br\/wp\/wp-json\/wp\/v2\/tags?post=42779"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}