{"id":42507,"date":"2025-10-21T15:16:29","date_gmt":"2025-10-21T18:16:29","guid":{"rendered":"https:\/\/jornalnosbairros.com.br\/wp\/?p=42507"},"modified":"2025-10-21T15:22:37","modified_gmt":"2025-10-21T18:22:37","slug":"nao-existe-detector-de-metanol-alerta-procon-de-navegantes","status":"publish","type":"post","link":"https:\/\/jornalnosbairros.com.br\/wp\/2025\/10\/nao-existe-detector-de-metanol-alerta-procon-de-navegantes\/","title":{"rendered":"N\u00e3o existe detector de metanol, alerta Procon de Navegantes"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><em><strong>Fraudes envolvem a venda de supostos \u201ckits\u201d ou \u201ccanetas\u201d para detectar metanol em bebidas alco\u00f3licas.<\/strong><\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A Procuradoria Municipal de Prote\u00e7\u00e3o e Defesa do Consumidor de Navegantes (Procon) emitiu um alerta \u00e0 popula\u00e7\u00e3o sobre golpe de falso detector de metanol.  S\u00e3o falsos os an\u00fancios que envolvem a venda de supostos \u201ckits\u201d ou \u201ccanetas\u201d para detectar metanol em bebidas alco\u00f3licas. Esses produtos, anunciados principalmente em sites e redes sociais, n\u00e3o possuem comprova\u00e7\u00e3o cient\u00edfica, registro na Anvisa nem autoriza\u00e7\u00e3o para uso dom\u00e9stico, e podem colocar os consumidores em risco.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De acordo com a Secretaria Nacional do Consumidor (Senacon), vinculada ao Minist\u00e9rio da Justi\u00e7a e Seguran\u00e7a P\u00fablica, o golpe tem se espalhado rapidamente pela internet. Em muitos casos, os criminosos utilizam imagens falsas, marcas inexistentes e at\u00e9 recursos de intelig\u00eancia artificial para dar apar\u00eancia de legitimidade aos an\u00fancios, induzindo o consumidor ao erro e, em alguns casos, roubando dados pessoais e banc\u00e1rios.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O Procon de Navegantes refor\u00e7a que n\u00e3o h\u00e1, at\u00e9 o momento, nenhum produto autorizado no Brasil que permita detectar metanol de forma segura e caseira. A comercializa\u00e7\u00e3o ou divulga\u00e7\u00e3o desses materiais pode configurar infra\u00e7\u00e3o \u00e0s normas de defesa do consumidor e representar risco \u00e0 sa\u00fade.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>LEIA TAMB\u00c9M:<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/jornalnosbairros.com.br\/wp\/2025\/10\/policia-civil-de-navegantes-prende-suspeito-por-falsificacao-de-bebidas\/\">Preso em Navegantes suspeito por falsifica\u00e7\u00e3o de bebidas<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cEsses produtos s\u00e3o fraudulentos e perigosos. Al\u00e9m de n\u00e3o funcionarem, podem expor o consumidor a golpes financeiros e a riscos \u00e0 sa\u00fade. A orienta\u00e7\u00e3o \u00e9 simples: n\u00e3o compre, n\u00e3o compartilhe e, se encontrar esse tipo de an\u00fancio, denuncie\u201d, alerta Gustavo Ghidorsi, gerente de Fiscaliza\u00e7\u00e3o do Procon de Navegantes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cO direito \u00e0 informa\u00e7\u00e3o clara e verdadeira \u00e9 um dos pilares do C\u00f3digo de Defesa do Consumidor. Assim, toda publicidade deve ser baseada em dados reais, sob pena de ser considerada enganosa ou abusiva\u201d, refor\u00e7a.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Consumidores que identificarem an\u00fancios suspeitos ou tenham sido v\u00edtimas desse tipo de fraude podem entrar em contato pelos canais oficiais do Procon de Navegantes ou pela plataforma&nbsp;<a href=\"http:\/\/www.consumidor.gov.br\/\">consumidor.gov.br<\/a>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O atendimento ao p\u00fablico tamb\u00e9m ocorre presencialmente na sede do \u00f3rg\u00e3o, localizada na Avenida Prefeito Jos\u00e9 Juvenal Mafra, 498 \u2013 Centro, em frente \u00e0 Pra\u00e7a dos Emancipadores. Reclama\u00e7\u00f5es podem ser feitas tamb\u00e9m pelo telefone (47) 3342-9500 ou via WhatsApp, no n\u00famero (47) 99290-1398.<\/p>\n\n\n\n<div class=\"wp-block-buttons is-horizontal is-content-justification-center is-nowrap is-layout-flex wp-container-core-buttons-is-layout-c9c93e97 wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button has-custom-width wp-block-button__width-75 is-style-fill\"><a class=\"wp-block-button__link has-black-color has-vivid-green-cyan-background-color has-text-color has-background has-link-color has-text-align-center has-custom-font-size wp-element-button\" href=\"https:\/\/chat.whatsapp.com\/DJkjPyw34SVCxRUdvlspB8\" style=\"border-radius:14px;font-size:18px;text-decoration:none\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">Participe do grupo do <strong>Jornal nos Bairros<\/strong><\/a><\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Fraudes envolvem a venda de supostos \u201ckits\u201d ou \u201ccanetas\u201d para detectar metanol em bebidas alco\u00f3licas. A Procuradoria Municipal de Prote\u00e7\u00e3o e Defesa do Consumidor de Navegantes (Procon) emitiu um alerta \u00e0 popula\u00e7\u00e3o sobre&hellip;<\/p>\n","protected":false},"author":1,"featured_media":42508,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ai_generated_summary":"","footnotes":""},"categories":[3],"tags":[],"class_list":["post-42507","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-geral"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>N\u00e3o existe detector de metanol, alerta Procon de Navegantes - Jornal nos Bairros<\/title>\n<meta name=\"description\" content=\"A Procuradoria de Prote\u00e7\u00e3o e Defesa do Consumidor (Procon) emitiu um alerta \u00e0 popula\u00e7\u00e3o sobre golpe do falso detector de metanol.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/jornalnosbairros.com.br\/wp\/2025\/10\/nao-existe-detector-de-metanol-alerta-procon-de-navegantes\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"N\u00e3o existe detector de metanol, alerta Procon de Navegantes - Jornal nos Bairros\" \/>\n<meta property=\"og:description\" content=\"A Procuradoria de Prote\u00e7\u00e3o e Defesa do Consumidor (Procon) emitiu um alerta \u00e0 popula\u00e7\u00e3o sobre golpe do falso detector de metanol.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/jornalnosbairros.com.br\/wp\/2025\/10\/nao-existe-detector-de-metanol-alerta-procon-de-navegantes\/\" \/>\n<meta property=\"og:site_name\" content=\"Jornal nos Bairros\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/jornalnosbairros\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/jornalnosbairros\" \/>\n<meta property=\"article:published_time\" content=\"2025-10-21T18:16:29+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-21T18:22:37+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/jornalnosbairros.com.br\/wp\/wp-content\/uploads\/2025\/10\/golpe-detector-de-metanol.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"790\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Editoria\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/jornal_bairros\" \/>\n<meta name=\"twitter:site\" content=\"@jornal_bairros\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Editoria\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/2025\\\/10\\\/nao-existe-detector-de-metanol-alerta-procon-de-navegantes\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/2025\\\/10\\\/nao-existe-detector-de-metanol-alerta-procon-de-navegantes\\\/\"},\"author\":{\"name\":\"Editoria\",\"@id\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/#\\\/schema\\\/person\\\/9a74fde2f4332c018c3b4d29a6129437\"},\"headline\":\"N\u00e3o existe detector de metanol, alerta Procon de Navegantes\",\"datePublished\":\"2025-10-21T18:16:29+00:00\",\"dateModified\":\"2025-10-21T18:22:37+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/2025\\\/10\\\/nao-existe-detector-de-metanol-alerta-procon-de-navegantes\\\/\"},\"wordCount\":414,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/2025\\\/10\\\/nao-existe-detector-de-metanol-alerta-procon-de-navegantes\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/golpe-detector-de-metanol.jpg\",\"articleSection\":[\"GERAL\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/2025\\\/10\\\/nao-existe-detector-de-metanol-alerta-procon-de-navegantes\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/2025\\\/10\\\/nao-existe-detector-de-metanol-alerta-procon-de-navegantes\\\/\",\"url\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/2025\\\/10\\\/nao-existe-detector-de-metanol-alerta-procon-de-navegantes\\\/\",\"name\":\"N\u00e3o existe detector de metanol, alerta Procon de Navegantes - Jornal nos Bairros\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/2025\\\/10\\\/nao-existe-detector-de-metanol-alerta-procon-de-navegantes\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/2025\\\/10\\\/nao-existe-detector-de-metanol-alerta-procon-de-navegantes\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/golpe-detector-de-metanol.jpg\",\"datePublished\":\"2025-10-21T18:16:29+00:00\",\"dateModified\":\"2025-10-21T18:22:37+00:00\",\"description\":\"A Procuradoria de Prote\u00e7\u00e3o e Defesa do Consumidor (Procon) emitiu um alerta \u00e0 popula\u00e7\u00e3o sobre golpe do falso detector de metanol.\",\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/2025\\\/10\\\/nao-existe-detector-de-metanol-alerta-procon-de-navegantes\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/2025\\\/10\\\/nao-existe-detector-de-metanol-alerta-procon-de-navegantes\\\/#primaryimage\",\"url\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/golpe-detector-de-metanol.jpg\",\"contentUrl\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/golpe-detector-de-metanol.jpg\",\"width\":1200,\"height\":790},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/#website\",\"url\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/\",\"name\":\"Jornal nos Bairros\",\"description\":\"Not\u00edcias di\u00e1rias de Navegantes e regi\u00e3o\",\"publisher\":{\"@id\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/#organization\"},\"alternateName\":\"JB\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/#organization\",\"name\":\"Jornal nos Bairros de Navegantes\",\"url\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/LOGO-JB.png\",\"contentUrl\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/LOGO-JB.png\",\"width\":168,\"height\":150,\"caption\":\"Jornal nos Bairros de Navegantes\"},\"image\":{\"@id\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/jornalnosbairros\",\"https:\\\/\\\/x.com\\\/jornal_bairros\",\"https:\\\/\\\/www.instagram.com\\\/jornalnosbairros\",\"https:\\\/\\\/www.youtube.com\\\/@jornalnosbairros\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/#\\\/schema\\\/person\\\/9a74fde2f4332c018c3b4d29a6129437\",\"name\":\"Editoria\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b53a04b7003d01b914d43ebacd13b233f0d99ed1cb7f8cb7d8553ef90e3f466b?s=96&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b53a04b7003d01b914d43ebacd13b233f0d99ed1cb7f8cb7d8553ef90e3f466b?s=96&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b53a04b7003d01b914d43ebacd13b233f0d99ed1cb7f8cb7d8553ef90e3f466b?s=96&r=g\",\"caption\":\"Editoria\"},\"description\":\"Edi\u00e7\u00e3o do Jornal nos Bairros de Navegantes - Contato: fale@jornalnosbairros.com.br - Siga: @jornalnosbairros - Acesse: www.jornalnosbairros.com.br\",\"sameAs\":[\"http:\\\/\\\/www.jornalnosbairros.com.br\\\/wp\",\"https:\\\/\\\/www.facebook.com\\\/jornalnosbairros\",\"https:\\\/\\\/www.instagram.com\\\/jornalnosbairros\\\/\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/jornal_bairros\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCbdZNY5wPbaBq5KtRGP4WxQ?view_as=subscriber\"],\"url\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"N\u00e3o existe detector de metanol, alerta Procon de Navegantes - Jornal nos Bairros","description":"A Procuradoria de Prote\u00e7\u00e3o e Defesa do Consumidor (Procon) emitiu um alerta \u00e0 popula\u00e7\u00e3o sobre golpe do falso detector de metanol.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/jornalnosbairros.com.br\/wp\/2025\/10\/nao-existe-detector-de-metanol-alerta-procon-de-navegantes\/","og_locale":"pt_BR","og_type":"article","og_title":"N\u00e3o existe detector de metanol, alerta Procon de Navegantes - Jornal nos Bairros","og_description":"A Procuradoria de Prote\u00e7\u00e3o e Defesa do Consumidor (Procon) emitiu um alerta \u00e0 popula\u00e7\u00e3o sobre golpe do falso detector de metanol.","og_url":"https:\/\/jornalnosbairros.com.br\/wp\/2025\/10\/nao-existe-detector-de-metanol-alerta-procon-de-navegantes\/","og_site_name":"Jornal nos Bairros","article_publisher":"https:\/\/www.facebook.com\/jornalnosbairros","article_author":"https:\/\/www.facebook.com\/jornalnosbairros","article_published_time":"2025-10-21T18:16:29+00:00","article_modified_time":"2025-10-21T18:22:37+00:00","og_image":[{"width":1200,"height":790,"url":"https:\/\/jornalnosbairros.com.br\/wp\/wp-content\/uploads\/2025\/10\/golpe-detector-de-metanol.jpg","type":"image\/jpeg"}],"author":"Editoria","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/jornal_bairros","twitter_site":"@jornal_bairros","twitter_misc":{"Escrito por":"Editoria","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/jornalnosbairros.com.br\/wp\/2025\/10\/nao-existe-detector-de-metanol-alerta-procon-de-navegantes\/#article","isPartOf":{"@id":"https:\/\/jornalnosbairros.com.br\/wp\/2025\/10\/nao-existe-detector-de-metanol-alerta-procon-de-navegantes\/"},"author":{"name":"Editoria","@id":"https:\/\/jornalnosbairros.com.br\/wp\/#\/schema\/person\/9a74fde2f4332c018c3b4d29a6129437"},"headline":"N\u00e3o existe detector de metanol, alerta Procon de Navegantes","datePublished":"2025-10-21T18:16:29+00:00","dateModified":"2025-10-21T18:22:37+00:00","mainEntityOfPage":{"@id":"https:\/\/jornalnosbairros.com.br\/wp\/2025\/10\/nao-existe-detector-de-metanol-alerta-procon-de-navegantes\/"},"wordCount":414,"commentCount":0,"publisher":{"@id":"https:\/\/jornalnosbairros.com.br\/wp\/#organization"},"image":{"@id":"https:\/\/jornalnosbairros.com.br\/wp\/2025\/10\/nao-existe-detector-de-metanol-alerta-procon-de-navegantes\/#primaryimage"},"thumbnailUrl":"https:\/\/jornalnosbairros.com.br\/wp\/wp-content\/uploads\/2025\/10\/golpe-detector-de-metanol.jpg","articleSection":["GERAL"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/jornalnosbairros.com.br\/wp\/2025\/10\/nao-existe-detector-de-metanol-alerta-procon-de-navegantes\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/jornalnosbairros.com.br\/wp\/2025\/10\/nao-existe-detector-de-metanol-alerta-procon-de-navegantes\/","url":"https:\/\/jornalnosbairros.com.br\/wp\/2025\/10\/nao-existe-detector-de-metanol-alerta-procon-de-navegantes\/","name":"N\u00e3o existe detector de metanol, alerta Procon de Navegantes - Jornal nos Bairros","isPartOf":{"@id":"https:\/\/jornalnosbairros.com.br\/wp\/#website"},"primaryImageOfPage":{"@id":"https:\/\/jornalnosbairros.com.br\/wp\/2025\/10\/nao-existe-detector-de-metanol-alerta-procon-de-navegantes\/#primaryimage"},"image":{"@id":"https:\/\/jornalnosbairros.com.br\/wp\/2025\/10\/nao-existe-detector-de-metanol-alerta-procon-de-navegantes\/#primaryimage"},"thumbnailUrl":"https:\/\/jornalnosbairros.com.br\/wp\/wp-content\/uploads\/2025\/10\/golpe-detector-de-metanol.jpg","datePublished":"2025-10-21T18:16:29+00:00","dateModified":"2025-10-21T18:22:37+00:00","description":"A Procuradoria de Prote\u00e7\u00e3o e Defesa do Consumidor (Procon) emitiu um alerta \u00e0 popula\u00e7\u00e3o sobre golpe do falso detector de metanol.","inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/jornalnosbairros.com.br\/wp\/2025\/10\/nao-existe-detector-de-metanol-alerta-procon-de-navegantes\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/jornalnosbairros.com.br\/wp\/2025\/10\/nao-existe-detector-de-metanol-alerta-procon-de-navegantes\/#primaryimage","url":"https:\/\/jornalnosbairros.com.br\/wp\/wp-content\/uploads\/2025\/10\/golpe-detector-de-metanol.jpg","contentUrl":"https:\/\/jornalnosbairros.com.br\/wp\/wp-content\/uploads\/2025\/10\/golpe-detector-de-metanol.jpg","width":1200,"height":790},{"@type":"WebSite","@id":"https:\/\/jornalnosbairros.com.br\/wp\/#website","url":"https:\/\/jornalnosbairros.com.br\/wp\/","name":"Jornal nos Bairros","description":"Not\u00edcias di\u00e1rias de Navegantes e regi\u00e3o","publisher":{"@id":"https:\/\/jornalnosbairros.com.br\/wp\/#organization"},"alternateName":"JB","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/jornalnosbairros.com.br\/wp\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/jornalnosbairros.com.br\/wp\/#organization","name":"Jornal nos Bairros de Navegantes","url":"https:\/\/jornalnosbairros.com.br\/wp\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/jornalnosbairros.com.br\/wp\/#\/schema\/logo\/image\/","url":"https:\/\/jornalnosbairros.com.br\/wp\/wp-content\/uploads\/2025\/01\/LOGO-JB.png","contentUrl":"https:\/\/jornalnosbairros.com.br\/wp\/wp-content\/uploads\/2025\/01\/LOGO-JB.png","width":168,"height":150,"caption":"Jornal nos Bairros de Navegantes"},"image":{"@id":"https:\/\/jornalnosbairros.com.br\/wp\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/jornalnosbairros","https:\/\/x.com\/jornal_bairros","https:\/\/www.instagram.com\/jornalnosbairros","https:\/\/www.youtube.com\/@jornalnosbairros"]},{"@type":"Person","@id":"https:\/\/jornalnosbairros.com.br\/wp\/#\/schema\/person\/9a74fde2f4332c018c3b4d29a6129437","name":"Editoria","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/b53a04b7003d01b914d43ebacd13b233f0d99ed1cb7f8cb7d8553ef90e3f466b?s=96&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b53a04b7003d01b914d43ebacd13b233f0d99ed1cb7f8cb7d8553ef90e3f466b?s=96&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b53a04b7003d01b914d43ebacd13b233f0d99ed1cb7f8cb7d8553ef90e3f466b?s=96&r=g","caption":"Editoria"},"description":"Edi\u00e7\u00e3o do Jornal nos Bairros de Navegantes - Contato: fale@jornalnosbairros.com.br - Siga: @jornalnosbairros - Acesse: www.jornalnosbairros.com.br","sameAs":["http:\/\/www.jornalnosbairros.com.br\/wp","https:\/\/www.facebook.com\/jornalnosbairros","https:\/\/www.instagram.com\/jornalnosbairros\/","https:\/\/x.com\/https:\/\/twitter.com\/jornal_bairros","https:\/\/www.youtube.com\/channel\/UCbdZNY5wPbaBq5KtRGP4WxQ?view_as=subscriber"],"url":"https:\/\/jornalnosbairros.com.br\/wp\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/jornalnosbairros.com.br\/wp\/wp-json\/wp\/v2\/posts\/42507","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jornalnosbairros.com.br\/wp\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jornalnosbairros.com.br\/wp\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jornalnosbairros.com.br\/wp\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/jornalnosbairros.com.br\/wp\/wp-json\/wp\/v2\/comments?post=42507"}],"version-history":[{"count":3,"href":"https:\/\/jornalnosbairros.com.br\/wp\/wp-json\/wp\/v2\/posts\/42507\/revisions"}],"predecessor-version":[{"id":42512,"href":"https:\/\/jornalnosbairros.com.br\/wp\/wp-json\/wp\/v2\/posts\/42507\/revisions\/42512"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/jornalnosbairros.com.br\/wp\/wp-json\/wp\/v2\/media\/42508"}],"wp:attachment":[{"href":"https:\/\/jornalnosbairros.com.br\/wp\/wp-json\/wp\/v2\/media?parent=42507"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jornalnosbairros.com.br\/wp\/wp-json\/wp\/v2\/categories?post=42507"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jornalnosbairros.com.br\/wp\/wp-json\/wp\/v2\/tags?post=42507"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}