{"id":35460,"date":"2025-01-21T15:47:56","date_gmt":"2025-01-21T18:47:56","guid":{"rendered":"https:\/\/jornalnosbairros.com.br\/wp\/?p=35460"},"modified":"2025-01-21T16:21:42","modified_gmt":"2025-01-21T19:21:42","slug":"morre-dona-ema-fagundes-aos-92-anos","status":"publish","type":"post","link":"https:\/\/jornalnosbairros.com.br\/wp\/2025\/01\/morre-dona-ema-fagundes-aos-92-anos\/","title":{"rendered":"Morre Dona Ema Fagundes aos 91 anos"},"content":{"rendered":"\n<p class=\"has-text-align-center wp-block-paragraph\"><strong><em>Ela foi a m\u00e3e fundadora da APAE de Navegantes<\/em><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Faleceu na manh\u00e3 dessa ter\u00e7a-feira (21), no Hospital Marieta, em Itaja\u00ed, a senhora Ema Zucco Fagundes, aos 91 anos de idade, ap\u00f3s complica\u00e7\u00f5es causadas por um AVC.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O vel\u00f3rio ser\u00e1 a partir das 20 horas dessa ter\u00e7a-feira (21), na capela mortu\u00e1ria do Cemit\u00e9rio Municipal Campo da Paz (Centro de Navegantes), e o sepultamento \u00e0s 16 horas de quarta-feira (22). <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Natural do munic\u00edpio de Luiz Alves (SC), com 25 anos de idade veio para Navegantes, para trabalhar na resid\u00eancia do falecido ex-prefeito Cirino Adolfo Cabral. Em 1959, casou-se com Mozart Fagundes, j\u00e1 falecido. Um ano depois, nascia o primeiro dos oito filhos do casal \u2013 seis deles especiais.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ap\u00f3s 17 anos, j\u00e1 cansada e com dificuldade de deslocar-se at\u00e9 o munic\u00edpio vizinho, Itaja\u00ed, para acompanhar os filhos especiais na sede da APAE, Dona Ema solicitou ao ent\u00e3o prefeito Jo\u00e3o Jos\u00e9 Fagundes que fundasse uma APAE em Navegantes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A 1\u00aa Dama do munic\u00edpio na \u00e9poca, Vera Fagundes, ent\u00e3o se reuniu a um grupo de senhoras e formou, no dia 21 de julho de 1980, a primeira diretoria da APAE de Navegantes. Naquele mesmo m\u00eas, iniciava-se o atendimento aos alunos especiais, em uma sala na Col\u00f4nia dos Pescadores. Com sua luta, Dona Ema ajudou muitas m\u00e3es na inser\u00e7\u00e3o de seus filhos na educa\u00e7\u00e3o especial e atendimento especializado.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Al\u00e9m de m\u00e3e fundadora da APAE de Navegantes, ainda era conhecida por seus benzimentos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dona Ema era vi\u00fava e deixou seis filhos (dois j\u00e1 falecidos): Jos\u00e9 Carlos, Luiz Cl\u00e1udio (Zinho), Sandro, Vandelino, Jo\u00e3o Edson e Gerson Fagundes.<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<div class=\"wp-block-buttons is-horizontal is-content-justification-center is-nowrap is-layout-flex wp-container-core-buttons-is-layout-c9c93e97 wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button has-custom-width wp-block-button__width-75 has-custom-font-size is-style-fill\" style=\"font-size:18px;text-decoration:none\"><a class=\"wp-block-button__link has-black-color has-vivid-green-cyan-background-color has-text-color has-background has-link-color has-text-align-center wp-element-button\" href=\"https:\/\/chat.whatsapp.com\/DJkjPyw34SVCxRUdvlspB8\" style=\"border-radius:14px\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">Participe do grupo do <strong>Jornal nos Bairros<\/strong><\/a><\/div>\n<\/div>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Outras not\u00edcias:<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-wp-embed is-provider-jornal-nos-bairros wp-block-embed-jornal-nos-bairros\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"wp-embedded-content\" data-secret=\"Q3CMJQsHjI\"><a href=\"https:\/\/jornalnosbairros.com.br\/wp\/2016\/03\/especial-dia-das-maes-amor-multiplicado-por-oito\/\">ESPECIAL DIA DAS M\u00c3ES: AMOR MULTIPLICADO POR OITO<\/a><\/blockquote><iframe class=\"wp-embedded-content lazyload\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; visibility: hidden;\" title=\"&#8220;ESPECIAL DIA DAS M\u00c3ES: AMOR MULTIPLICADO POR OITO&#8221; &#8212; Jornal nos Bairros\" data-src=\"https:\/\/jornalnosbairros.com.br\/wp\/2016\/03\/especial-dia-das-maes-amor-multiplicado-por-oito\/embed\/#?secret=kJwjkCjuoA#?secret=Q3CMJQsHjI\" data-secret=\"Q3CMJQsHjI\" width=\"600\" height=\"338\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\" src=\"about:blank\" data-load-mode=\"0\"><\/iframe>\n<\/div><\/figure>\n\n\n\n<figure class=\"wp-block-embed is-type-wp-embed is-provider-jornal-nos-bairros wp-block-embed-jornal-nos-bairros\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"wp-embedded-content\" data-secret=\"tFyOZTTwgC\"><a href=\"https:\/\/jornalnosbairros.com.br\/wp\/2024\/03\/dia-da-mulher-a-mulher-responsavel-pela-fundacao-da-apae-de-navegantes\/\">A MULHER RESPONS\u00c1VEL PELA FUNDA\u00c7\u00c3O DA APAE DE NAVEGANTES<\/a><\/blockquote><iframe class=\"wp-embedded-content lazyload\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; visibility: hidden;\" title=\"&#8220;A MULHER RESPONS\u00c1VEL PELA FUNDA\u00c7\u00c3O DA APAE DE NAVEGANTES&#8221; &#8212; Jornal nos Bairros\" data-src=\"https:\/\/jornalnosbairros.com.br\/wp\/2024\/03\/dia-da-mulher-a-mulher-responsavel-pela-fundacao-da-apae-de-navegantes\/embed\/#?secret=gpDDIHOXfk#?secret=tFyOZTTwgC\" data-secret=\"tFyOZTTwgC\" width=\"600\" height=\"338\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\" src=\"about:blank\" data-load-mode=\"0\"><\/iframe>\n<\/div><\/figure>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n","protected":false},"excerpt":{"rendered":"<p>Ela foi a m\u00e3e fundadora da APAE de Navegantes Faleceu na manh\u00e3 dessa ter\u00e7a-feira (21), no Hospital Marieta, em Itaja\u00ed, a senhora Ema Zucco Fagundes, aos 91 anos de idade, ap\u00f3s complica\u00e7\u00f5es causadas&hellip;<\/p>\n","protected":false},"author":1,"featured_media":35469,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ai_generated_summary":"","footnotes":""},"categories":[31],"tags":[40],"class_list":["post-35460","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-navegantes","tag-navegantes"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Morre Dona Ema Fagundes aos 91 anos - Jornal nos Bairros<\/title>\n<meta name=\"description\" content=\"Faleceu na manh\u00e3 dessa ter\u00e7a-feira (21), no Hospital Marieta, em Itaja\u00ed, a senhora Ema Zucco Fagundes, aos 92 anos\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/jornalnosbairros.com.br\/wp\/2025\/01\/morre-dona-ema-fagundes-aos-92-anos\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Morre Dona Ema Fagundes aos 91 anos - Jornal nos Bairros\" \/>\n<meta property=\"og:description\" content=\"Faleceu na manh\u00e3 dessa ter\u00e7a-feira (21), no Hospital Marieta, em Itaja\u00ed, a senhora Ema Zucco Fagundes, aos 92 anos\" \/>\n<meta property=\"og:url\" content=\"https:\/\/jornalnosbairros.com.br\/wp\/2025\/01\/morre-dona-ema-fagundes-aos-92-anos\/\" \/>\n<meta property=\"og:site_name\" content=\"Jornal nos Bairros\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/jornalnosbairros\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/jornalnosbairros\" \/>\n<meta property=\"article:published_time\" content=\"2025-01-21T18:47:56+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-01-21T19:21:42+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/jornalnosbairros.com.br\/wp\/wp-content\/uploads\/2025\/01\/morre-ema-fagundes.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1357\" \/>\n\t<meta property=\"og:image:height\" content=\"962\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Editoria\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/jornal_bairros\" \/>\n<meta name=\"twitter:site\" content=\"@jornal_bairros\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Editoria\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/2025\\\/01\\\/morre-dona-ema-fagundes-aos-92-anos\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/2025\\\/01\\\/morre-dona-ema-fagundes-aos-92-anos\\\/\"},\"author\":{\"name\":\"Editoria\",\"@id\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/#\\\/schema\\\/person\\\/9a74fde2f4332c018c3b4d29a6129437\"},\"headline\":\"Morre Dona Ema Fagundes aos 91 anos\",\"datePublished\":\"2025-01-21T18:47:56+00:00\",\"dateModified\":\"2025-01-21T19:21:42+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/2025\\\/01\\\/morre-dona-ema-fagundes-aos-92-anos\\\/\"},\"wordCount\":301,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/2025\\\/01\\\/morre-dona-ema-fagundes-aos-92-anos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/morre-ema-fagundes.jpg\",\"keywords\":[\"navegantes\"],\"articleSection\":[\"NAVEGANTES\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/2025\\\/01\\\/morre-dona-ema-fagundes-aos-92-anos\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/2025\\\/01\\\/morre-dona-ema-fagundes-aos-92-anos\\\/\",\"url\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/2025\\\/01\\\/morre-dona-ema-fagundes-aos-92-anos\\\/\",\"name\":\"Morre Dona Ema Fagundes aos 91 anos - Jornal nos Bairros\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/2025\\\/01\\\/morre-dona-ema-fagundes-aos-92-anos\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/2025\\\/01\\\/morre-dona-ema-fagundes-aos-92-anos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/morre-ema-fagundes.jpg\",\"datePublished\":\"2025-01-21T18:47:56+00:00\",\"dateModified\":\"2025-01-21T19:21:42+00:00\",\"description\":\"Faleceu na manh\u00e3 dessa ter\u00e7a-feira (21), no Hospital Marieta, em Itaja\u00ed, a senhora Ema Zucco Fagundes, aos 92 anos\",\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/2025\\\/01\\\/morre-dona-ema-fagundes-aos-92-anos\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/2025\\\/01\\\/morre-dona-ema-fagundes-aos-92-anos\\\/#primaryimage\",\"url\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/morre-ema-fagundes.jpg\",\"contentUrl\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/morre-ema-fagundes.jpg\",\"width\":1357,\"height\":962,\"caption\":\"morre ema fagundes\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/#website\",\"url\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/\",\"name\":\"Jornal nos Bairros\",\"description\":\"Not\u00edcias di\u00e1rias de Navegantes e regi\u00e3o\",\"publisher\":{\"@id\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/#organization\"},\"alternateName\":\"JB\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/#organization\",\"name\":\"Jornal nos Bairros de Navegantes\",\"url\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/LOGO-JB.png\",\"contentUrl\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/LOGO-JB.png\",\"width\":168,\"height\":150,\"caption\":\"Jornal nos Bairros de Navegantes\"},\"image\":{\"@id\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/jornalnosbairros\",\"https:\\\/\\\/x.com\\\/jornal_bairros\",\"https:\\\/\\\/www.instagram.com\\\/jornalnosbairros\",\"https:\\\/\\\/www.youtube.com\\\/@jornalnosbairros\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/#\\\/schema\\\/person\\\/9a74fde2f4332c018c3b4d29a6129437\",\"name\":\"Editoria\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b53a04b7003d01b914d43ebacd13b233f0d99ed1cb7f8cb7d8553ef90e3f466b?s=96&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b53a04b7003d01b914d43ebacd13b233f0d99ed1cb7f8cb7d8553ef90e3f466b?s=96&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b53a04b7003d01b914d43ebacd13b233f0d99ed1cb7f8cb7d8553ef90e3f466b?s=96&r=g\",\"caption\":\"Editoria\"},\"description\":\"Edi\u00e7\u00e3o do Jornal nos Bairros de Navegantes - Contato: fale@jornalnosbairros.com.br - Siga: @jornalnosbairros - Acesse: www.jornalnosbairros.com.br\",\"sameAs\":[\"http:\\\/\\\/www.jornalnosbairros.com.br\\\/wp\",\"https:\\\/\\\/www.facebook.com\\\/jornalnosbairros\",\"https:\\\/\\\/www.instagram.com\\\/jornalnosbairros\\\/\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/jornal_bairros\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCbdZNY5wPbaBq5KtRGP4WxQ?view_as=subscriber\"],\"url\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Morre Dona Ema Fagundes aos 91 anos - Jornal nos Bairros","description":"Faleceu na manh\u00e3 dessa ter\u00e7a-feira (21), no Hospital Marieta, em Itaja\u00ed, a senhora Ema Zucco Fagundes, aos 92 anos","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/jornalnosbairros.com.br\/wp\/2025\/01\/morre-dona-ema-fagundes-aos-92-anos\/","og_locale":"pt_BR","og_type":"article","og_title":"Morre Dona Ema Fagundes aos 91 anos - Jornal nos Bairros","og_description":"Faleceu na manh\u00e3 dessa ter\u00e7a-feira (21), no Hospital Marieta, em Itaja\u00ed, a senhora Ema Zucco Fagundes, aos 92 anos","og_url":"https:\/\/jornalnosbairros.com.br\/wp\/2025\/01\/morre-dona-ema-fagundes-aos-92-anos\/","og_site_name":"Jornal nos Bairros","article_publisher":"https:\/\/www.facebook.com\/jornalnosbairros","article_author":"https:\/\/www.facebook.com\/jornalnosbairros","article_published_time":"2025-01-21T18:47:56+00:00","article_modified_time":"2025-01-21T19:21:42+00:00","og_image":[{"width":1357,"height":962,"url":"https:\/\/jornalnosbairros.com.br\/wp\/wp-content\/uploads\/2025\/01\/morre-ema-fagundes.jpg","type":"image\/jpeg"}],"author":"Editoria","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/jornal_bairros","twitter_site":"@jornal_bairros","twitter_misc":{"Escrito por":"Editoria","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/jornalnosbairros.com.br\/wp\/2025\/01\/morre-dona-ema-fagundes-aos-92-anos\/#article","isPartOf":{"@id":"https:\/\/jornalnosbairros.com.br\/wp\/2025\/01\/morre-dona-ema-fagundes-aos-92-anos\/"},"author":{"name":"Editoria","@id":"https:\/\/jornalnosbairros.com.br\/wp\/#\/schema\/person\/9a74fde2f4332c018c3b4d29a6129437"},"headline":"Morre Dona Ema Fagundes aos 91 anos","datePublished":"2025-01-21T18:47:56+00:00","dateModified":"2025-01-21T19:21:42+00:00","mainEntityOfPage":{"@id":"https:\/\/jornalnosbairros.com.br\/wp\/2025\/01\/morre-dona-ema-fagundes-aos-92-anos\/"},"wordCount":301,"commentCount":0,"publisher":{"@id":"https:\/\/jornalnosbairros.com.br\/wp\/#organization"},"image":{"@id":"https:\/\/jornalnosbairros.com.br\/wp\/2025\/01\/morre-dona-ema-fagundes-aos-92-anos\/#primaryimage"},"thumbnailUrl":"https:\/\/jornalnosbairros.com.br\/wp\/wp-content\/uploads\/2025\/01\/morre-ema-fagundes.jpg","keywords":["navegantes"],"articleSection":["NAVEGANTES"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/jornalnosbairros.com.br\/wp\/2025\/01\/morre-dona-ema-fagundes-aos-92-anos\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/jornalnosbairros.com.br\/wp\/2025\/01\/morre-dona-ema-fagundes-aos-92-anos\/","url":"https:\/\/jornalnosbairros.com.br\/wp\/2025\/01\/morre-dona-ema-fagundes-aos-92-anos\/","name":"Morre Dona Ema Fagundes aos 91 anos - Jornal nos Bairros","isPartOf":{"@id":"https:\/\/jornalnosbairros.com.br\/wp\/#website"},"primaryImageOfPage":{"@id":"https:\/\/jornalnosbairros.com.br\/wp\/2025\/01\/morre-dona-ema-fagundes-aos-92-anos\/#primaryimage"},"image":{"@id":"https:\/\/jornalnosbairros.com.br\/wp\/2025\/01\/morre-dona-ema-fagundes-aos-92-anos\/#primaryimage"},"thumbnailUrl":"https:\/\/jornalnosbairros.com.br\/wp\/wp-content\/uploads\/2025\/01\/morre-ema-fagundes.jpg","datePublished":"2025-01-21T18:47:56+00:00","dateModified":"2025-01-21T19:21:42+00:00","description":"Faleceu na manh\u00e3 dessa ter\u00e7a-feira (21), no Hospital Marieta, em Itaja\u00ed, a senhora Ema Zucco Fagundes, aos 92 anos","inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/jornalnosbairros.com.br\/wp\/2025\/01\/morre-dona-ema-fagundes-aos-92-anos\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/jornalnosbairros.com.br\/wp\/2025\/01\/morre-dona-ema-fagundes-aos-92-anos\/#primaryimage","url":"https:\/\/jornalnosbairros.com.br\/wp\/wp-content\/uploads\/2025\/01\/morre-ema-fagundes.jpg","contentUrl":"https:\/\/jornalnosbairros.com.br\/wp\/wp-content\/uploads\/2025\/01\/morre-ema-fagundes.jpg","width":1357,"height":962,"caption":"morre ema fagundes"},{"@type":"WebSite","@id":"https:\/\/jornalnosbairros.com.br\/wp\/#website","url":"https:\/\/jornalnosbairros.com.br\/wp\/","name":"Jornal nos Bairros","description":"Not\u00edcias di\u00e1rias de Navegantes e regi\u00e3o","publisher":{"@id":"https:\/\/jornalnosbairros.com.br\/wp\/#organization"},"alternateName":"JB","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/jornalnosbairros.com.br\/wp\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/jornalnosbairros.com.br\/wp\/#organization","name":"Jornal nos Bairros de Navegantes","url":"https:\/\/jornalnosbairros.com.br\/wp\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/jornalnosbairros.com.br\/wp\/#\/schema\/logo\/image\/","url":"https:\/\/jornalnosbairros.com.br\/wp\/wp-content\/uploads\/2025\/01\/LOGO-JB.png","contentUrl":"https:\/\/jornalnosbairros.com.br\/wp\/wp-content\/uploads\/2025\/01\/LOGO-JB.png","width":168,"height":150,"caption":"Jornal nos Bairros de Navegantes"},"image":{"@id":"https:\/\/jornalnosbairros.com.br\/wp\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/jornalnosbairros","https:\/\/x.com\/jornal_bairros","https:\/\/www.instagram.com\/jornalnosbairros","https:\/\/www.youtube.com\/@jornalnosbairros"]},{"@type":"Person","@id":"https:\/\/jornalnosbairros.com.br\/wp\/#\/schema\/person\/9a74fde2f4332c018c3b4d29a6129437","name":"Editoria","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/b53a04b7003d01b914d43ebacd13b233f0d99ed1cb7f8cb7d8553ef90e3f466b?s=96&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b53a04b7003d01b914d43ebacd13b233f0d99ed1cb7f8cb7d8553ef90e3f466b?s=96&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b53a04b7003d01b914d43ebacd13b233f0d99ed1cb7f8cb7d8553ef90e3f466b?s=96&r=g","caption":"Editoria"},"description":"Edi\u00e7\u00e3o do Jornal nos Bairros de Navegantes - Contato: fale@jornalnosbairros.com.br - Siga: @jornalnosbairros - Acesse: www.jornalnosbairros.com.br","sameAs":["http:\/\/www.jornalnosbairros.com.br\/wp","https:\/\/www.facebook.com\/jornalnosbairros","https:\/\/www.instagram.com\/jornalnosbairros\/","https:\/\/x.com\/https:\/\/twitter.com\/jornal_bairros","https:\/\/www.youtube.com\/channel\/UCbdZNY5wPbaBq5KtRGP4WxQ?view_as=subscriber"],"url":"https:\/\/jornalnosbairros.com.br\/wp\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/jornalnosbairros.com.br\/wp\/wp-json\/wp\/v2\/posts\/35460","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jornalnosbairros.com.br\/wp\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jornalnosbairros.com.br\/wp\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jornalnosbairros.com.br\/wp\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/jornalnosbairros.com.br\/wp\/wp-json\/wp\/v2\/comments?post=35460"}],"version-history":[{"count":6,"href":"https:\/\/jornalnosbairros.com.br\/wp\/wp-json\/wp\/v2\/posts\/35460\/revisions"}],"predecessor-version":[{"id":35476,"href":"https:\/\/jornalnosbairros.com.br\/wp\/wp-json\/wp\/v2\/posts\/35460\/revisions\/35476"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/jornalnosbairros.com.br\/wp\/wp-json\/wp\/v2\/media\/35469"}],"wp:attachment":[{"href":"https:\/\/jornalnosbairros.com.br\/wp\/wp-json\/wp\/v2\/media?parent=35460"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jornalnosbairros.com.br\/wp\/wp-json\/wp\/v2\/categories?post=35460"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jornalnosbairros.com.br\/wp\/wp-json\/wp\/v2\/tags?post=35460"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}