{"id":33957,"date":"2024-11-07T08:55:56","date_gmt":"2024-11-07T11:55:56","guid":{"rendered":"https:\/\/jornalnosbairros.com.br\/wp\/?p=33957"},"modified":"2025-07-04T15:05:38","modified_gmt":"2025-07-04T18:05:38","slug":"vendas-de-veiculos-em-sc-registram-crescimento-de-3821","status":"publish","type":"post","link":"https:\/\/jornalnosbairros.com.br\/wp\/2024\/11\/vendas-de-veiculos-em-sc-registram-crescimento-de-3821\/","title":{"rendered":"Vendas de ve\u00edculos em SC registram crescimento"},"content":{"rendered":"\n<p class=\"has-text-align-center wp-block-paragraph\"><strong><em>O aumento nas vendas de ve\u00edculos em SC foi de 38,21%<\/em>, em compara\u00e7\u00e3o ao mesmo per\u00edodo de 2023. <\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A Federa\u00e7\u00e3o Nacional da Distribui\u00e7\u00e3o de Ve\u00edculos Automotores de Santa Catarina (Fenabrave-SC) divulgou os resultados do setor automotivo para outubro de 2024. Nos primeiros dez meses de 2024, o mercado automotivo catarinense registrou um aumento de 38,21% nos emplacamentos em compara\u00e7\u00e3o ao mesmo per\u00edodo de 2023. Em n\u00fameros absolutos, foram licenciadas 21.859 unidades em 2024, em compara\u00e7\u00e3o a 15.816 em outubro do ano anterior.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O acumulado de 2024 tamb\u00e9m demonstra um crescimento expressivo de 21,87%, com 182.192 unidades licenciadas, frente a 149.503 unidades no mesmo per\u00edodo de 2023.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Em rela\u00e7\u00e3o a setembro de 2024, as vendas de outubro apresentaram um aumento de 15,77%, totalizando 21.859 unidades em outubro, em compara\u00e7\u00e3o \u00e0s 18.881 de setembro.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"713\" height=\"619\" data-src=\"https:\/\/jornalnosbairros.com.br\/wp\/wp-content\/uploads\/2024\/11\/download.png\" alt=\"\" class=\"wp-image-33961 lazyload\" data-srcset=\"https:\/\/jornalnosbairros.com.br\/wp\/wp-content\/uploads\/2024\/11\/download.png 713w, https:\/\/jornalnosbairros.com.br\/wp\/wp-content\/uploads\/2024\/11\/download-300x260.png 300w\" data-sizes=\"(max-width: 713px) 100vw, 713px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 713px; --smush-placeholder-aspect-ratio: 713\/619;\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">\u00c9 importante ressaltar que os dados referentes a Tratores e M\u00e1quinas Agr\u00edcolas s\u00e3o reportados com um m\u00eas de defasagem, com base em levantamentos junto aos fabricantes. No \u00e2mbito nacional, as vendas desse segmento cresceram 5,33% em setembro de 2024 em rela\u00e7\u00e3o a agosto. No entanto, quando comparadas a 2023, houve uma queda de 19,45%. No acumulado de 2024, esse setor apresentou uma retra\u00e7\u00e3o de 25,32% em rela\u00e7\u00e3o ao mesmo per\u00edodo do ano anterior.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Segundo o Diretor Regional Alfredo Breitkopf, o crescimento de 38,21% nas vendas de ve\u00edculos em Santa Catarina \u00e9 um reflexo direto do fortalecimento da economia do estado. <\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\">&#8220;Este desempenho not\u00e1vel demonstra a resili\u00eancia e a capacidade de adapta\u00e7\u00e3o das concession\u00e1rias representadas pela Fenabrave-SC. Estamos comprometidos em continuar fortalecendo o setor, aproveitando as condi\u00e7\u00f5es econ\u00f4micas favor\u00e1veis para impulsionar ainda mais o mercado automotivo.\u201d <\/p>\n<\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\">Em complemento o Diretor Executivo, Piter Santana comentou que o resultado das vendas \u00e9 um reflexo de um ambiente de neg\u00f3cios em constante melhoria para o setor automotivo. <\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\">&#8220;A Fenabrave-SC e o Sincodiv-SC t\u00eam trabalhado arduamente para aprimorar a gest\u00e3o do setor de distribui\u00e7\u00e3o, implementando a\u00e7\u00f5es que beneficiam nossos associados. A capacita\u00e7\u00e3o das redes de distribui\u00e7\u00e3o e a prepara\u00e7\u00e3o dos empres\u00e1rios para a competi\u00e7\u00e3o mercadol\u00f3gica s\u00e3o fundamentais para um setor mais robusto e competitivo. Estamos confiantes de que, juntos, continuaremos a alcan\u00e7ar novos patamares de sucesso.\u201d<\/p>\n<\/blockquote>\n\n\n\n<h2 class=\"wp-block-heading\">Sobre a Fenabrave-SC<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Representante de 558 concession\u00e1rias de ve\u00edculos em todo o estado, a Fenabrave-SC abrange concession\u00e1rias dos segmentos de autom\u00f3veis, comerciais leves, caminh\u00f5es, tratores e m\u00e1quinas agr\u00edcolas, motocicletas e implementos rodovi\u00e1rios.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O aumento nas vendas de ve\u00edculos em SC foi de 38,21%, em compara\u00e7\u00e3o ao mesmo per\u00edodo de 2023. A Federa\u00e7\u00e3o Nacional da Distribui\u00e7\u00e3o de Ve\u00edculos Automotores de Santa Catarina (Fenabrave-SC) divulgou os resultados&hellip;<\/p>\n","protected":false},"author":1,"featured_media":4155,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ai_generated_summary":"","footnotes":""},"categories":[693],"tags":[1097,58,40,83,507],"class_list":["post-33957","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-estado","tag-emplacamentos","tag-itajai","tag-navegantes","tag-penha","tag-transito"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Vendas de ve\u00edculos em SC registram crescimento - Jornal nos Bairros<\/title>\n<meta name=\"description\" content=\"O aumento nas vendas de ve\u00edculos em SC foi de 38,21%, em compara\u00e7\u00e3o ao mesmo per\u00edodo de 2023., segundo a Fenabrave-SC\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/jornalnosbairros.com.br\/wp\/2024\/11\/vendas-de-veiculos-em-sc-registram-crescimento-de-3821\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Vendas de ve\u00edculos em SC registram crescimento - Jornal nos Bairros\" \/>\n<meta property=\"og:description\" content=\"O aumento nas vendas de ve\u00edculos em SC foi de 38,21%, em compara\u00e7\u00e3o ao mesmo per\u00edodo de 2023., segundo a Fenabrave-SC\" \/>\n<meta property=\"og:url\" content=\"https:\/\/jornalnosbairros.com.br\/wp\/2024\/11\/vendas-de-veiculos-em-sc-registram-crescimento-de-3821\/\" \/>\n<meta property=\"og:site_name\" content=\"Jornal nos Bairros\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/jornalnosbairros\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/jornalnosbairros\" \/>\n<meta property=\"article:published_time\" content=\"2024-11-07T11:55:56+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-07-04T18:05:38+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/jornalnosbairros.com.br\/wp\/wp-content\/uploads\/2020\/10\/veiculos-navegantes.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"820\" \/>\n\t<meta property=\"og:image:height\" content=\"554\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Editoria\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/jornal_bairros\" \/>\n<meta name=\"twitter:site\" content=\"@jornal_bairros\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Editoria\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/2024\\\/11\\\/vendas-de-veiculos-em-sc-registram-crescimento-de-3821\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/2024\\\/11\\\/vendas-de-veiculos-em-sc-registram-crescimento-de-3821\\\/\"},\"author\":{\"name\":\"Editoria\",\"@id\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/#\\\/schema\\\/person\\\/9a74fde2f4332c018c3b4d29a6129437\"},\"headline\":\"Vendas de ve\u00edculos em SC registram crescimento\",\"datePublished\":\"2024-11-07T11:55:56+00:00\",\"dateModified\":\"2025-07-04T18:05:38+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/2024\\\/11\\\/vendas-de-veiculos-em-sc-registram-crescimento-de-3821\\\/\"},\"wordCount\":415,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/2024\\\/11\\\/vendas-de-veiculos-em-sc-registram-crescimento-de-3821\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/veiculos-navegantes.jpg\",\"keywords\":[\"emplacamentos\",\"Itaja\u00ed\",\"navegantes\",\"penha\",\"transito\"],\"articleSection\":[\"ESTADO\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/2024\\\/11\\\/vendas-de-veiculos-em-sc-registram-crescimento-de-3821\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/2024\\\/11\\\/vendas-de-veiculos-em-sc-registram-crescimento-de-3821\\\/\",\"url\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/2024\\\/11\\\/vendas-de-veiculos-em-sc-registram-crescimento-de-3821\\\/\",\"name\":\"Vendas de ve\u00edculos em SC registram crescimento - Jornal nos Bairros\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/2024\\\/11\\\/vendas-de-veiculos-em-sc-registram-crescimento-de-3821\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/2024\\\/11\\\/vendas-de-veiculos-em-sc-registram-crescimento-de-3821\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/veiculos-navegantes.jpg\",\"datePublished\":\"2024-11-07T11:55:56+00:00\",\"dateModified\":\"2025-07-04T18:05:38+00:00\",\"description\":\"O aumento nas vendas de ve\u00edculos em SC foi de 38,21%, em compara\u00e7\u00e3o ao mesmo per\u00edodo de 2023., segundo a Fenabrave-SC\",\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/2024\\\/11\\\/vendas-de-veiculos-em-sc-registram-crescimento-de-3821\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/2024\\\/11\\\/vendas-de-veiculos-em-sc-registram-crescimento-de-3821\\\/#primaryimage\",\"url\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/veiculos-navegantes.jpg\",\"contentUrl\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/veiculos-navegantes.jpg\",\"width\":820,\"height\":554},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/#website\",\"url\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/\",\"name\":\"Jornal nos Bairros\",\"description\":\"Not\u00edcias di\u00e1rias de Navegantes e regi\u00e3o\",\"publisher\":{\"@id\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/#organization\"},\"alternateName\":\"JB\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/#organization\",\"name\":\"Jornal nos Bairros de Navegantes\",\"url\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/LOGO-JB.png\",\"contentUrl\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/LOGO-JB.png\",\"width\":168,\"height\":150,\"caption\":\"Jornal nos Bairros de Navegantes\"},\"image\":{\"@id\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/jornalnosbairros\",\"https:\\\/\\\/x.com\\\/jornal_bairros\",\"https:\\\/\\\/www.instagram.com\\\/jornalnosbairros\",\"https:\\\/\\\/www.youtube.com\\\/@jornalnosbairros\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/#\\\/schema\\\/person\\\/9a74fde2f4332c018c3b4d29a6129437\",\"name\":\"Editoria\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b53a04b7003d01b914d43ebacd13b233f0d99ed1cb7f8cb7d8553ef90e3f466b?s=96&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b53a04b7003d01b914d43ebacd13b233f0d99ed1cb7f8cb7d8553ef90e3f466b?s=96&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b53a04b7003d01b914d43ebacd13b233f0d99ed1cb7f8cb7d8553ef90e3f466b?s=96&r=g\",\"caption\":\"Editoria\"},\"description\":\"Edi\u00e7\u00e3o do Jornal nos Bairros de Navegantes - Contato: fale@jornalnosbairros.com.br - Siga: @jornalnosbairros - Acesse: www.jornalnosbairros.com.br\",\"sameAs\":[\"http:\\\/\\\/www.jornalnosbairros.com.br\\\/wp\",\"https:\\\/\\\/www.facebook.com\\\/jornalnosbairros\",\"https:\\\/\\\/www.instagram.com\\\/jornalnosbairros\\\/\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/jornal_bairros\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCbdZNY5wPbaBq5KtRGP4WxQ?view_as=subscriber\"],\"url\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Vendas de ve\u00edculos em SC registram crescimento - Jornal nos Bairros","description":"O aumento nas vendas de ve\u00edculos em SC foi de 38,21%, em compara\u00e7\u00e3o ao mesmo per\u00edodo de 2023., segundo a Fenabrave-SC","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/jornalnosbairros.com.br\/wp\/2024\/11\/vendas-de-veiculos-em-sc-registram-crescimento-de-3821\/","og_locale":"pt_BR","og_type":"article","og_title":"Vendas de ve\u00edculos em SC registram crescimento - Jornal nos Bairros","og_description":"O aumento nas vendas de ve\u00edculos em SC foi de 38,21%, em compara\u00e7\u00e3o ao mesmo per\u00edodo de 2023., segundo a Fenabrave-SC","og_url":"https:\/\/jornalnosbairros.com.br\/wp\/2024\/11\/vendas-de-veiculos-em-sc-registram-crescimento-de-3821\/","og_site_name":"Jornal nos Bairros","article_publisher":"https:\/\/www.facebook.com\/jornalnosbairros","article_author":"https:\/\/www.facebook.com\/jornalnosbairros","article_published_time":"2024-11-07T11:55:56+00:00","article_modified_time":"2025-07-04T18:05:38+00:00","og_image":[{"width":820,"height":554,"url":"https:\/\/jornalnosbairros.com.br\/wp\/wp-content\/uploads\/2020\/10\/veiculos-navegantes.jpg","type":"image\/jpeg"}],"author":"Editoria","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/jornal_bairros","twitter_site":"@jornal_bairros","twitter_misc":{"Escrito por":"Editoria","Est. tempo de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/jornalnosbairros.com.br\/wp\/2024\/11\/vendas-de-veiculos-em-sc-registram-crescimento-de-3821\/#article","isPartOf":{"@id":"https:\/\/jornalnosbairros.com.br\/wp\/2024\/11\/vendas-de-veiculos-em-sc-registram-crescimento-de-3821\/"},"author":{"name":"Editoria","@id":"https:\/\/jornalnosbairros.com.br\/wp\/#\/schema\/person\/9a74fde2f4332c018c3b4d29a6129437"},"headline":"Vendas de ve\u00edculos em SC registram crescimento","datePublished":"2024-11-07T11:55:56+00:00","dateModified":"2025-07-04T18:05:38+00:00","mainEntityOfPage":{"@id":"https:\/\/jornalnosbairros.com.br\/wp\/2024\/11\/vendas-de-veiculos-em-sc-registram-crescimento-de-3821\/"},"wordCount":415,"commentCount":0,"publisher":{"@id":"https:\/\/jornalnosbairros.com.br\/wp\/#organization"},"image":{"@id":"https:\/\/jornalnosbairros.com.br\/wp\/2024\/11\/vendas-de-veiculos-em-sc-registram-crescimento-de-3821\/#primaryimage"},"thumbnailUrl":"https:\/\/jornalnosbairros.com.br\/wp\/wp-content\/uploads\/2020\/10\/veiculos-navegantes.jpg","keywords":["emplacamentos","Itaja\u00ed","navegantes","penha","transito"],"articleSection":["ESTADO"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/jornalnosbairros.com.br\/wp\/2024\/11\/vendas-de-veiculos-em-sc-registram-crescimento-de-3821\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/jornalnosbairros.com.br\/wp\/2024\/11\/vendas-de-veiculos-em-sc-registram-crescimento-de-3821\/","url":"https:\/\/jornalnosbairros.com.br\/wp\/2024\/11\/vendas-de-veiculos-em-sc-registram-crescimento-de-3821\/","name":"Vendas de ve\u00edculos em SC registram crescimento - Jornal nos Bairros","isPartOf":{"@id":"https:\/\/jornalnosbairros.com.br\/wp\/#website"},"primaryImageOfPage":{"@id":"https:\/\/jornalnosbairros.com.br\/wp\/2024\/11\/vendas-de-veiculos-em-sc-registram-crescimento-de-3821\/#primaryimage"},"image":{"@id":"https:\/\/jornalnosbairros.com.br\/wp\/2024\/11\/vendas-de-veiculos-em-sc-registram-crescimento-de-3821\/#primaryimage"},"thumbnailUrl":"https:\/\/jornalnosbairros.com.br\/wp\/wp-content\/uploads\/2020\/10\/veiculos-navegantes.jpg","datePublished":"2024-11-07T11:55:56+00:00","dateModified":"2025-07-04T18:05:38+00:00","description":"O aumento nas vendas de ve\u00edculos em SC foi de 38,21%, em compara\u00e7\u00e3o ao mesmo per\u00edodo de 2023., segundo a Fenabrave-SC","inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/jornalnosbairros.com.br\/wp\/2024\/11\/vendas-de-veiculos-em-sc-registram-crescimento-de-3821\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/jornalnosbairros.com.br\/wp\/2024\/11\/vendas-de-veiculos-em-sc-registram-crescimento-de-3821\/#primaryimage","url":"https:\/\/jornalnosbairros.com.br\/wp\/wp-content\/uploads\/2020\/10\/veiculos-navegantes.jpg","contentUrl":"https:\/\/jornalnosbairros.com.br\/wp\/wp-content\/uploads\/2020\/10\/veiculos-navegantes.jpg","width":820,"height":554},{"@type":"WebSite","@id":"https:\/\/jornalnosbairros.com.br\/wp\/#website","url":"https:\/\/jornalnosbairros.com.br\/wp\/","name":"Jornal nos Bairros","description":"Not\u00edcias di\u00e1rias de Navegantes e regi\u00e3o","publisher":{"@id":"https:\/\/jornalnosbairros.com.br\/wp\/#organization"},"alternateName":"JB","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/jornalnosbairros.com.br\/wp\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/jornalnosbairros.com.br\/wp\/#organization","name":"Jornal nos Bairros de Navegantes","url":"https:\/\/jornalnosbairros.com.br\/wp\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/jornalnosbairros.com.br\/wp\/#\/schema\/logo\/image\/","url":"https:\/\/jornalnosbairros.com.br\/wp\/wp-content\/uploads\/2025\/01\/LOGO-JB.png","contentUrl":"https:\/\/jornalnosbairros.com.br\/wp\/wp-content\/uploads\/2025\/01\/LOGO-JB.png","width":168,"height":150,"caption":"Jornal nos Bairros de Navegantes"},"image":{"@id":"https:\/\/jornalnosbairros.com.br\/wp\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/jornalnosbairros","https:\/\/x.com\/jornal_bairros","https:\/\/www.instagram.com\/jornalnosbairros","https:\/\/www.youtube.com\/@jornalnosbairros"]},{"@type":"Person","@id":"https:\/\/jornalnosbairros.com.br\/wp\/#\/schema\/person\/9a74fde2f4332c018c3b4d29a6129437","name":"Editoria","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/b53a04b7003d01b914d43ebacd13b233f0d99ed1cb7f8cb7d8553ef90e3f466b?s=96&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b53a04b7003d01b914d43ebacd13b233f0d99ed1cb7f8cb7d8553ef90e3f466b?s=96&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b53a04b7003d01b914d43ebacd13b233f0d99ed1cb7f8cb7d8553ef90e3f466b?s=96&r=g","caption":"Editoria"},"description":"Edi\u00e7\u00e3o do Jornal nos Bairros de Navegantes - Contato: fale@jornalnosbairros.com.br - Siga: @jornalnosbairros - Acesse: www.jornalnosbairros.com.br","sameAs":["http:\/\/www.jornalnosbairros.com.br\/wp","https:\/\/www.facebook.com\/jornalnosbairros","https:\/\/www.instagram.com\/jornalnosbairros\/","https:\/\/x.com\/https:\/\/twitter.com\/jornal_bairros","https:\/\/www.youtube.com\/channel\/UCbdZNY5wPbaBq5KtRGP4WxQ?view_as=subscriber"],"url":"https:\/\/jornalnosbairros.com.br\/wp\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/jornalnosbairros.com.br\/wp\/wp-json\/wp\/v2\/posts\/33957","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jornalnosbairros.com.br\/wp\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jornalnosbairros.com.br\/wp\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jornalnosbairros.com.br\/wp\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/jornalnosbairros.com.br\/wp\/wp-json\/wp\/v2\/comments?post=33957"}],"version-history":[{"count":2,"href":"https:\/\/jornalnosbairros.com.br\/wp\/wp-json\/wp\/v2\/posts\/33957\/revisions"}],"predecessor-version":[{"id":39547,"href":"https:\/\/jornalnosbairros.com.br\/wp\/wp-json\/wp\/v2\/posts\/33957\/revisions\/39547"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/jornalnosbairros.com.br\/wp\/wp-json\/wp\/v2\/media\/4155"}],"wp:attachment":[{"href":"https:\/\/jornalnosbairros.com.br\/wp\/wp-json\/wp\/v2\/media?parent=33957"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jornalnosbairros.com.br\/wp\/wp-json\/wp\/v2\/categories?post=33957"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jornalnosbairros.com.br\/wp\/wp-json\/wp\/v2\/tags?post=33957"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}