{"id":33641,"date":"2024-10-18T15:28:15","date_gmt":"2024-10-18T18:28:15","guid":{"rendered":"https:\/\/jornalnosbairros.com.br\/wp\/?p=33641"},"modified":"2024-10-18T15:28:15","modified_gmt":"2024-10-18T18:28:15","slug":"daba-realiza-feira-de-adocao-neste-sabado-19","status":"publish","type":"post","link":"https:\/\/jornalnosbairros.com.br\/wp\/2024\/10\/daba-realiza-feira-de-adocao-neste-sabado-19\/","title":{"rendered":"Daba realiza Feira de Ado\u00e7\u00e3o neste s\u00e1bado (19)"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Neste s\u00e1bado (19), o Departamento de Assist\u00eancia e Bem-Estar Animal (DABA) de Navegantes realiza a tradicional Feira de Ado\u00e7\u00e3o de Animais.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O estande estar\u00e1 no p\u00e1tio do Supermercado Kompr\u00e3o, que fica na Rua Nereu Liberato Nunes, 191, Centro, das 10h \u00e0s 15h.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">S\u00e3o c\u00e3es e gatos castrados, vacinados e microchipados, dispon\u00edveis para ado\u00e7\u00e3o, \u00e0 espera de um lar. Voc\u00ea est\u00e1 convidado a visitar a Feira e, quem sabe, l\u00e1 voc\u00ea vai olhar para um dos bichinhos e ter a certeza de que encontrou o que procurava: um amigo fiel. Essa \u00e9 a sua oportunidade de mudar o destino de um deles e passar a ser o seu tutor.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Neste s\u00e1bado (19), o Departamento de Assist\u00eancia e Bem-Estar Animal (DABA) de Navegantes realiza a tradicional Feira de Ado\u00e7\u00e3o de Animais. O estande estar\u00e1 no p\u00e1tio do Supermercado Kompr\u00e3o, que fica na Rua&hellip;<\/p>\n","protected":false},"author":1,"featured_media":33642,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ai_generated_summary":"","footnotes":""},"categories":[3],"tags":[118,117,40],"class_list":["post-33641","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-geral","tag-adocao","tag-daba","tag-navegantes"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Daba realiza Feira de Ado\u00e7\u00e3o neste s\u00e1bado (19) - Jornal nos Bairros<\/title>\n<meta name=\"description\" content=\"Neste s\u00e1bado (19), o Departamento de Assist\u00eancia e Bem-Estar Animal (DABA) de Navegantes realiza a tradicional Feira de Ado\u00e7\u00e3o de Animais.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/jornalnosbairros.com.br\/wp\/2024\/10\/daba-realiza-feira-de-adocao-neste-sabado-19\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Daba realiza Feira de Ado\u00e7\u00e3o neste s\u00e1bado (19) - Jornal nos Bairros\" \/>\n<meta property=\"og:description\" content=\"Neste s\u00e1bado (19), o Departamento de Assist\u00eancia e Bem-Estar Animal (DABA) de Navegantes realiza a tradicional Feira de Ado\u00e7\u00e3o de Animais.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/jornalnosbairros.com.br\/wp\/2024\/10\/daba-realiza-feira-de-adocao-neste-sabado-19\/\" \/>\n<meta property=\"og:site_name\" content=\"Jornal nos Bairros\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/jornalnosbairros\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/jornalnosbairros\" \/>\n<meta property=\"article:published_time\" content=\"2024-10-18T18:28:15+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/jornalnosbairros.com.br\/wp\/wp-content\/uploads\/2024\/10\/Daba-realiza-Feira-de-Adocao-neste-sabado-19.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"445\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Editoria\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/jornal_bairros\" \/>\n<meta name=\"twitter:site\" content=\"@jornal_bairros\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Editoria\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/2024\\\/10\\\/daba-realiza-feira-de-adocao-neste-sabado-19\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/2024\\\/10\\\/daba-realiza-feira-de-adocao-neste-sabado-19\\\/\"},\"author\":{\"name\":\"Editoria\",\"@id\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/#\\\/schema\\\/person\\\/9a74fde2f4332c018c3b4d29a6129437\"},\"headline\":\"Daba realiza Feira de Ado\u00e7\u00e3o neste s\u00e1bado (19)\",\"datePublished\":\"2024-10-18T18:28:15+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/2024\\\/10\\\/daba-realiza-feira-de-adocao-neste-sabado-19\\\/\"},\"wordCount\":122,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/2024\\\/10\\\/daba-realiza-feira-de-adocao-neste-sabado-19\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/Daba-realiza-Feira-de-Adocao-neste-sabado-19.jpg\",\"keywords\":[\"ado\u00e7\u00e3o\",\"DABA\",\"navegantes\"],\"articleSection\":[\"GERAL\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/2024\\\/10\\\/daba-realiza-feira-de-adocao-neste-sabado-19\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/2024\\\/10\\\/daba-realiza-feira-de-adocao-neste-sabado-19\\\/\",\"url\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/2024\\\/10\\\/daba-realiza-feira-de-adocao-neste-sabado-19\\\/\",\"name\":\"Daba realiza Feira de Ado\u00e7\u00e3o neste s\u00e1bado (19) - Jornal nos Bairros\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/2024\\\/10\\\/daba-realiza-feira-de-adocao-neste-sabado-19\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/2024\\\/10\\\/daba-realiza-feira-de-adocao-neste-sabado-19\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/Daba-realiza-Feira-de-Adocao-neste-sabado-19.jpg\",\"datePublished\":\"2024-10-18T18:28:15+00:00\",\"description\":\"Neste s\u00e1bado (19), o Departamento de Assist\u00eancia e Bem-Estar Animal (DABA) de Navegantes realiza a tradicional Feira de Ado\u00e7\u00e3o de Animais.\",\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/2024\\\/10\\\/daba-realiza-feira-de-adocao-neste-sabado-19\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/2024\\\/10\\\/daba-realiza-feira-de-adocao-neste-sabado-19\\\/#primaryimage\",\"url\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/Daba-realiza-Feira-de-Adocao-neste-sabado-19.jpg\",\"contentUrl\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/Daba-realiza-Feira-de-Adocao-neste-sabado-19.jpg\",\"width\":800,\"height\":445},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/#website\",\"url\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/\",\"name\":\"Jornal nos Bairros\",\"description\":\"Not\u00edcias di\u00e1rias de Navegantes e regi\u00e3o\",\"publisher\":{\"@id\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/#organization\"},\"alternateName\":\"JB\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/#organization\",\"name\":\"Jornal nos Bairros de Navegantes\",\"url\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/LOGO-JB.png\",\"contentUrl\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/LOGO-JB.png\",\"width\":168,\"height\":150,\"caption\":\"Jornal nos Bairros de Navegantes\"},\"image\":{\"@id\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/jornalnosbairros\",\"https:\\\/\\\/x.com\\\/jornal_bairros\",\"https:\\\/\\\/www.instagram.com\\\/jornalnosbairros\",\"https:\\\/\\\/www.youtube.com\\\/@jornalnosbairros\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/#\\\/schema\\\/person\\\/9a74fde2f4332c018c3b4d29a6129437\",\"name\":\"Editoria\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b53a04b7003d01b914d43ebacd13b233f0d99ed1cb7f8cb7d8553ef90e3f466b?s=96&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b53a04b7003d01b914d43ebacd13b233f0d99ed1cb7f8cb7d8553ef90e3f466b?s=96&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b53a04b7003d01b914d43ebacd13b233f0d99ed1cb7f8cb7d8553ef90e3f466b?s=96&r=g\",\"caption\":\"Editoria\"},\"description\":\"Edi\u00e7\u00e3o do Jornal nos Bairros de Navegantes - Contato: fale@jornalnosbairros.com.br - Siga: @jornalnosbairros - Acesse: www.jornalnosbairros.com.br\",\"sameAs\":[\"http:\\\/\\\/www.jornalnosbairros.com.br\\\/wp\",\"https:\\\/\\\/www.facebook.com\\\/jornalnosbairros\",\"https:\\\/\\\/www.instagram.com\\\/jornalnosbairros\\\/\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/jornal_bairros\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCbdZNY5wPbaBq5KtRGP4WxQ?view_as=subscriber\"],\"url\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Daba realiza Feira de Ado\u00e7\u00e3o neste s\u00e1bado (19) - Jornal nos Bairros","description":"Neste s\u00e1bado (19), o Departamento de Assist\u00eancia e Bem-Estar Animal (DABA) de Navegantes realiza a tradicional Feira de Ado\u00e7\u00e3o de Animais.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/jornalnosbairros.com.br\/wp\/2024\/10\/daba-realiza-feira-de-adocao-neste-sabado-19\/","og_locale":"pt_BR","og_type":"article","og_title":"Daba realiza Feira de Ado\u00e7\u00e3o neste s\u00e1bado (19) - Jornal nos Bairros","og_description":"Neste s\u00e1bado (19), o Departamento de Assist\u00eancia e Bem-Estar Animal (DABA) de Navegantes realiza a tradicional Feira de Ado\u00e7\u00e3o de Animais.","og_url":"https:\/\/jornalnosbairros.com.br\/wp\/2024\/10\/daba-realiza-feira-de-adocao-neste-sabado-19\/","og_site_name":"Jornal nos Bairros","article_publisher":"https:\/\/www.facebook.com\/jornalnosbairros","article_author":"https:\/\/www.facebook.com\/jornalnosbairros","article_published_time":"2024-10-18T18:28:15+00:00","og_image":[{"width":800,"height":445,"url":"https:\/\/jornalnosbairros.com.br\/wp\/wp-content\/uploads\/2024\/10\/Daba-realiza-Feira-de-Adocao-neste-sabado-19.jpg","type":"image\/jpeg"}],"author":"Editoria","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/jornal_bairros","twitter_site":"@jornal_bairros","twitter_misc":{"Escrito por":"Editoria","Est. tempo de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/jornalnosbairros.com.br\/wp\/2024\/10\/daba-realiza-feira-de-adocao-neste-sabado-19\/#article","isPartOf":{"@id":"https:\/\/jornalnosbairros.com.br\/wp\/2024\/10\/daba-realiza-feira-de-adocao-neste-sabado-19\/"},"author":{"name":"Editoria","@id":"https:\/\/jornalnosbairros.com.br\/wp\/#\/schema\/person\/9a74fde2f4332c018c3b4d29a6129437"},"headline":"Daba realiza Feira de Ado\u00e7\u00e3o neste s\u00e1bado (19)","datePublished":"2024-10-18T18:28:15+00:00","mainEntityOfPage":{"@id":"https:\/\/jornalnosbairros.com.br\/wp\/2024\/10\/daba-realiza-feira-de-adocao-neste-sabado-19\/"},"wordCount":122,"commentCount":0,"publisher":{"@id":"https:\/\/jornalnosbairros.com.br\/wp\/#organization"},"image":{"@id":"https:\/\/jornalnosbairros.com.br\/wp\/2024\/10\/daba-realiza-feira-de-adocao-neste-sabado-19\/#primaryimage"},"thumbnailUrl":"https:\/\/jornalnosbairros.com.br\/wp\/wp-content\/uploads\/2024\/10\/Daba-realiza-Feira-de-Adocao-neste-sabado-19.jpg","keywords":["ado\u00e7\u00e3o","DABA","navegantes"],"articleSection":["GERAL"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/jornalnosbairros.com.br\/wp\/2024\/10\/daba-realiza-feira-de-adocao-neste-sabado-19\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/jornalnosbairros.com.br\/wp\/2024\/10\/daba-realiza-feira-de-adocao-neste-sabado-19\/","url":"https:\/\/jornalnosbairros.com.br\/wp\/2024\/10\/daba-realiza-feira-de-adocao-neste-sabado-19\/","name":"Daba realiza Feira de Ado\u00e7\u00e3o neste s\u00e1bado (19) - Jornal nos Bairros","isPartOf":{"@id":"https:\/\/jornalnosbairros.com.br\/wp\/#website"},"primaryImageOfPage":{"@id":"https:\/\/jornalnosbairros.com.br\/wp\/2024\/10\/daba-realiza-feira-de-adocao-neste-sabado-19\/#primaryimage"},"image":{"@id":"https:\/\/jornalnosbairros.com.br\/wp\/2024\/10\/daba-realiza-feira-de-adocao-neste-sabado-19\/#primaryimage"},"thumbnailUrl":"https:\/\/jornalnosbairros.com.br\/wp\/wp-content\/uploads\/2024\/10\/Daba-realiza-Feira-de-Adocao-neste-sabado-19.jpg","datePublished":"2024-10-18T18:28:15+00:00","description":"Neste s\u00e1bado (19), o Departamento de Assist\u00eancia e Bem-Estar Animal (DABA) de Navegantes realiza a tradicional Feira de Ado\u00e7\u00e3o de Animais.","inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/jornalnosbairros.com.br\/wp\/2024\/10\/daba-realiza-feira-de-adocao-neste-sabado-19\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/jornalnosbairros.com.br\/wp\/2024\/10\/daba-realiza-feira-de-adocao-neste-sabado-19\/#primaryimage","url":"https:\/\/jornalnosbairros.com.br\/wp\/wp-content\/uploads\/2024\/10\/Daba-realiza-Feira-de-Adocao-neste-sabado-19.jpg","contentUrl":"https:\/\/jornalnosbairros.com.br\/wp\/wp-content\/uploads\/2024\/10\/Daba-realiza-Feira-de-Adocao-neste-sabado-19.jpg","width":800,"height":445},{"@type":"WebSite","@id":"https:\/\/jornalnosbairros.com.br\/wp\/#website","url":"https:\/\/jornalnosbairros.com.br\/wp\/","name":"Jornal nos Bairros","description":"Not\u00edcias di\u00e1rias de Navegantes e regi\u00e3o","publisher":{"@id":"https:\/\/jornalnosbairros.com.br\/wp\/#organization"},"alternateName":"JB","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/jornalnosbairros.com.br\/wp\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/jornalnosbairros.com.br\/wp\/#organization","name":"Jornal nos Bairros de Navegantes","url":"https:\/\/jornalnosbairros.com.br\/wp\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/jornalnosbairros.com.br\/wp\/#\/schema\/logo\/image\/","url":"https:\/\/jornalnosbairros.com.br\/wp\/wp-content\/uploads\/2025\/01\/LOGO-JB.png","contentUrl":"https:\/\/jornalnosbairros.com.br\/wp\/wp-content\/uploads\/2025\/01\/LOGO-JB.png","width":168,"height":150,"caption":"Jornal nos Bairros de Navegantes"},"image":{"@id":"https:\/\/jornalnosbairros.com.br\/wp\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/jornalnosbairros","https:\/\/x.com\/jornal_bairros","https:\/\/www.instagram.com\/jornalnosbairros","https:\/\/www.youtube.com\/@jornalnosbairros"]},{"@type":"Person","@id":"https:\/\/jornalnosbairros.com.br\/wp\/#\/schema\/person\/9a74fde2f4332c018c3b4d29a6129437","name":"Editoria","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/b53a04b7003d01b914d43ebacd13b233f0d99ed1cb7f8cb7d8553ef90e3f466b?s=96&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b53a04b7003d01b914d43ebacd13b233f0d99ed1cb7f8cb7d8553ef90e3f466b?s=96&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b53a04b7003d01b914d43ebacd13b233f0d99ed1cb7f8cb7d8553ef90e3f466b?s=96&r=g","caption":"Editoria"},"description":"Edi\u00e7\u00e3o do Jornal nos Bairros de Navegantes - Contato: fale@jornalnosbairros.com.br - Siga: @jornalnosbairros - Acesse: www.jornalnosbairros.com.br","sameAs":["http:\/\/www.jornalnosbairros.com.br\/wp","https:\/\/www.facebook.com\/jornalnosbairros","https:\/\/www.instagram.com\/jornalnosbairros\/","https:\/\/x.com\/https:\/\/twitter.com\/jornal_bairros","https:\/\/www.youtube.com\/channel\/UCbdZNY5wPbaBq5KtRGP4WxQ?view_as=subscriber"],"url":"https:\/\/jornalnosbairros.com.br\/wp\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/jornalnosbairros.com.br\/wp\/wp-json\/wp\/v2\/posts\/33641","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jornalnosbairros.com.br\/wp\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jornalnosbairros.com.br\/wp\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jornalnosbairros.com.br\/wp\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/jornalnosbairros.com.br\/wp\/wp-json\/wp\/v2\/comments?post=33641"}],"version-history":[{"count":1,"href":"https:\/\/jornalnosbairros.com.br\/wp\/wp-json\/wp\/v2\/posts\/33641\/revisions"}],"predecessor-version":[{"id":33643,"href":"https:\/\/jornalnosbairros.com.br\/wp\/wp-json\/wp\/v2\/posts\/33641\/revisions\/33643"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/jornalnosbairros.com.br\/wp\/wp-json\/wp\/v2\/media\/33642"}],"wp:attachment":[{"href":"https:\/\/jornalnosbairros.com.br\/wp\/wp-json\/wp\/v2\/media?parent=33641"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jornalnosbairros.com.br\/wp\/wp-json\/wp\/v2\/categories?post=33641"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jornalnosbairros.com.br\/wp\/wp-json\/wp\/v2\/tags?post=33641"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}