{"id":31110,"date":"2024-06-13T10:46:40","date_gmt":"2024-06-13T13:46:40","guid":{"rendered":"https:\/\/jornalnosbairros.com.br\/wp\/?p=31110"},"modified":"2024-06-13T10:46:40","modified_gmt":"2024-06-13T13:46:40","slug":"br-101-tera-interdicoes-no-acesso-ao-tunel-do-morro-do-boi","status":"publish","type":"post","link":"https:\/\/jornalnosbairros.com.br\/wp\/2024\/06\/br-101-tera-interdicoes-no-acesso-ao-tunel-do-morro-do-boi\/","title":{"rendered":"BR-101 TER\u00c1 INTERDI\u00c7\u00d5ES NO ACESSO AO T\u00daNEL DO MORRO DO BOI"},"content":{"rendered":"\n<p class=\"has-text-align-center wp-block-paragraph\"><strong>Em raz\u00e3o de obras, rodovia ter\u00e1 interdi\u00e7\u00e3o de uma das faixas entre os Kms 144 e 140 no sentido Norte.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A concession\u00e1ria Arteris Litoral Sul ir\u00e1 realizar, a partir da noite desta quinta-feira (13), obras de recupera\u00e7\u00e3o de pavimento na BR-101\/Norte entre os Kms 144 e 140, no acesso ao t\u00fanel do Morro do Boiem Balne\u00e1rio Cambori\u00fa.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Para a opera\u00e7\u00e3o, uma das faixas da rodovia ser\u00e1 bloqueada entre as 22 horas e 6 horas do dia seguinte, nos dias 13, 14 e 15 de junho, conforme programa\u00e7\u00e3o abaixo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Os trabalhos consistem em remover a camada de pavimento danificada e substituir por uma nova. A Concession\u00e1ria ir\u00e1 sinalizar a rodovia com placas de placas comunicando a exist\u00eancia de obras no trecho.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Em caso de instabilidade clim\u00e1tica a obra ser\u00e1 reprogramada.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Programa\u00e7\u00e3o das interdi\u00e7\u00f5es:<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Dia 13 (Quinta-Feira) a partir das 22 horas at\u00e9 \u00e0s 6 horas de sexta-feira (14) &#8211; Km 144 ao 140 Norte, faixa 02 (Direita e acostamento)<\/li>\n\n\n\n<li>Dia 14 (Sexta-Feira) a partir das 22 horas at\u00e9 \u00e0s 6 horas de s\u00e1bado (15) &#8211; Km 144 ao 140 Norte, faixa 02 (Direita e acostamento)<\/li>\n\n\n\n<li>Dia 15 (S\u00e1bado) a partir das 22 horas at\u00e9 \u00e0s 6 horas de domingo (16) &#8211; Km 144 ao 140 Norte, faixa 01 (Esquerda)<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">PARTICIPE DO GRUPO DE WHATSAPP DO JB PARA RECEBER NOT\u00cdCIAS EM SEU CELULAR:<br><a href=\"https:\/\/chat.whatsapp.com\/DJkjPyw34SVCxRUdvlspB8\">https:\/\/chat.whatsapp.com\/DJkjPyw34SVCxRUdvlspB8<\/a><br><br><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Em raz\u00e3o de obras, rodovia ter\u00e1 interdi\u00e7\u00e3o de uma das faixas entre os Kms 144 e 140 no sentido Norte. A concession\u00e1ria Arteris Litoral Sul ir\u00e1 realizar, a partir da noite desta quinta-feira&hellip;<\/p>\n","protected":false},"author":1,"featured_media":31111,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ai_generated_summary":"","footnotes":""},"categories":[920],"tags":[357],"class_list":["post-31110","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-rodovias","tag-rodovias"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>BR-101 TER\u00c1 INTERDI\u00c7\u00d5ES NO ACESSO AO T\u00daNEL DO MORRO DO BOI - Jornal nos Bairros<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/jornalnosbairros.com.br\/wp\/2024\/06\/br-101-tera-interdicoes-no-acesso-ao-tunel-do-morro-do-boi\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"BR-101 TER\u00c1 INTERDI\u00c7\u00d5ES NO ACESSO AO T\u00daNEL DO MORRO DO BOI - Jornal nos Bairros\" \/>\n<meta property=\"og:description\" content=\"Em raz\u00e3o de obras, rodovia ter\u00e1 interdi\u00e7\u00e3o de uma das faixas entre os Kms 144 e 140 no sentido Norte. A concession\u00e1ria Arteris Litoral Sul ir\u00e1 realizar, a partir da noite desta quinta-feira&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/jornalnosbairros.com.br\/wp\/2024\/06\/br-101-tera-interdicoes-no-acesso-ao-tunel-do-morro-do-boi\/\" \/>\n<meta property=\"og:site_name\" content=\"Jornal nos Bairros\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/jornalnosbairros\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/jornalnosbairros\" \/>\n<meta property=\"article:published_time\" content=\"2024-06-13T13:46:40+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/jornalnosbairros.com.br\/wp\/wp-content\/uploads\/2024\/06\/tunel-do-morro-do-boi.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"694\" \/>\n\t<meta property=\"og:image:height\" content=\"486\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Editoria\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/jornal_bairros\" \/>\n<meta name=\"twitter:site\" content=\"@jornal_bairros\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Editoria\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/2024\\\/06\\\/br-101-tera-interdicoes-no-acesso-ao-tunel-do-morro-do-boi\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/2024\\\/06\\\/br-101-tera-interdicoes-no-acesso-ao-tunel-do-morro-do-boi\\\/\"},\"author\":{\"name\":\"Editoria\",\"@id\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/#\\\/schema\\\/person\\\/9a74fde2f4332c018c3b4d29a6129437\"},\"headline\":\"BR-101 TER\u00c1 INTERDI\u00c7\u00d5ES NO ACESSO AO T\u00daNEL DO MORRO DO BOI\",\"datePublished\":\"2024-06-13T13:46:40+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/2024\\\/06\\\/br-101-tera-interdicoes-no-acesso-ao-tunel-do-morro-do-boi\\\/\"},\"wordCount\":226,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/2024\\\/06\\\/br-101-tera-interdicoes-no-acesso-ao-tunel-do-morro-do-boi\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/tunel-do-morro-do-boi.jpg\",\"keywords\":[\"rodovias\"],\"articleSection\":[\"RODOVIAS\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/2024\\\/06\\\/br-101-tera-interdicoes-no-acesso-ao-tunel-do-morro-do-boi\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/2024\\\/06\\\/br-101-tera-interdicoes-no-acesso-ao-tunel-do-morro-do-boi\\\/\",\"url\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/2024\\\/06\\\/br-101-tera-interdicoes-no-acesso-ao-tunel-do-morro-do-boi\\\/\",\"name\":\"BR-101 TER\u00c1 INTERDI\u00c7\u00d5ES NO ACESSO AO T\u00daNEL DO MORRO DO BOI - Jornal nos Bairros\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/2024\\\/06\\\/br-101-tera-interdicoes-no-acesso-ao-tunel-do-morro-do-boi\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/2024\\\/06\\\/br-101-tera-interdicoes-no-acesso-ao-tunel-do-morro-do-boi\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/tunel-do-morro-do-boi.jpg\",\"datePublished\":\"2024-06-13T13:46:40+00:00\",\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/2024\\\/06\\\/br-101-tera-interdicoes-no-acesso-ao-tunel-do-morro-do-boi\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/2024\\\/06\\\/br-101-tera-interdicoes-no-acesso-ao-tunel-do-morro-do-boi\\\/#primaryimage\",\"url\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/tunel-do-morro-do-boi.jpg\",\"contentUrl\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/tunel-do-morro-do-boi.jpg\",\"width\":694,\"height\":486},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/#website\",\"url\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/\",\"name\":\"Jornal nos Bairros\",\"description\":\"Not\u00edcias di\u00e1rias de Navegantes e regi\u00e3o\",\"publisher\":{\"@id\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/#organization\"},\"alternateName\":\"JB\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/#organization\",\"name\":\"Jornal nos Bairros de Navegantes\",\"url\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/LOGO-JB.png\",\"contentUrl\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/LOGO-JB.png\",\"width\":168,\"height\":150,\"caption\":\"Jornal nos Bairros de Navegantes\"},\"image\":{\"@id\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/jornalnosbairros\",\"https:\\\/\\\/x.com\\\/jornal_bairros\",\"https:\\\/\\\/www.instagram.com\\\/jornalnosbairros\",\"https:\\\/\\\/www.youtube.com\\\/@jornalnosbairros\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/#\\\/schema\\\/person\\\/9a74fde2f4332c018c3b4d29a6129437\",\"name\":\"Editoria\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b53a04b7003d01b914d43ebacd13b233f0d99ed1cb7f8cb7d8553ef90e3f466b?s=96&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b53a04b7003d01b914d43ebacd13b233f0d99ed1cb7f8cb7d8553ef90e3f466b?s=96&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b53a04b7003d01b914d43ebacd13b233f0d99ed1cb7f8cb7d8553ef90e3f466b?s=96&r=g\",\"caption\":\"Editoria\"},\"description\":\"Edi\u00e7\u00e3o do Jornal nos Bairros de Navegantes - Contato: fale@jornalnosbairros.com.br - Siga: @jornalnosbairros - Acesse: www.jornalnosbairros.com.br\",\"sameAs\":[\"http:\\\/\\\/www.jornalnosbairros.com.br\\\/wp\",\"https:\\\/\\\/www.facebook.com\\\/jornalnosbairros\",\"https:\\\/\\\/www.instagram.com\\\/jornalnosbairros\\\/\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/jornal_bairros\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCbdZNY5wPbaBq5KtRGP4WxQ?view_as=subscriber\"],\"url\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"BR-101 TER\u00c1 INTERDI\u00c7\u00d5ES NO ACESSO AO T\u00daNEL DO MORRO DO BOI - Jornal nos Bairros","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/jornalnosbairros.com.br\/wp\/2024\/06\/br-101-tera-interdicoes-no-acesso-ao-tunel-do-morro-do-boi\/","og_locale":"pt_BR","og_type":"article","og_title":"BR-101 TER\u00c1 INTERDI\u00c7\u00d5ES NO ACESSO AO T\u00daNEL DO MORRO DO BOI - Jornal nos Bairros","og_description":"Em raz\u00e3o de obras, rodovia ter\u00e1 interdi\u00e7\u00e3o de uma das faixas entre os Kms 144 e 140 no sentido Norte. A concession\u00e1ria Arteris Litoral Sul ir\u00e1 realizar, a partir da noite desta quinta-feira&hellip;","og_url":"https:\/\/jornalnosbairros.com.br\/wp\/2024\/06\/br-101-tera-interdicoes-no-acesso-ao-tunel-do-morro-do-boi\/","og_site_name":"Jornal nos Bairros","article_publisher":"https:\/\/www.facebook.com\/jornalnosbairros","article_author":"https:\/\/www.facebook.com\/jornalnosbairros","article_published_time":"2024-06-13T13:46:40+00:00","og_image":[{"width":694,"height":486,"url":"https:\/\/jornalnosbairros.com.br\/wp\/wp-content\/uploads\/2024\/06\/tunel-do-morro-do-boi.jpg","type":"image\/jpeg"}],"author":"Editoria","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/jornal_bairros","twitter_site":"@jornal_bairros","twitter_misc":{"Escrito por":"Editoria","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/jornalnosbairros.com.br\/wp\/2024\/06\/br-101-tera-interdicoes-no-acesso-ao-tunel-do-morro-do-boi\/#article","isPartOf":{"@id":"https:\/\/jornalnosbairros.com.br\/wp\/2024\/06\/br-101-tera-interdicoes-no-acesso-ao-tunel-do-morro-do-boi\/"},"author":{"name":"Editoria","@id":"https:\/\/jornalnosbairros.com.br\/wp\/#\/schema\/person\/9a74fde2f4332c018c3b4d29a6129437"},"headline":"BR-101 TER\u00c1 INTERDI\u00c7\u00d5ES NO ACESSO AO T\u00daNEL DO MORRO DO BOI","datePublished":"2024-06-13T13:46:40+00:00","mainEntityOfPage":{"@id":"https:\/\/jornalnosbairros.com.br\/wp\/2024\/06\/br-101-tera-interdicoes-no-acesso-ao-tunel-do-morro-do-boi\/"},"wordCount":226,"commentCount":0,"publisher":{"@id":"https:\/\/jornalnosbairros.com.br\/wp\/#organization"},"image":{"@id":"https:\/\/jornalnosbairros.com.br\/wp\/2024\/06\/br-101-tera-interdicoes-no-acesso-ao-tunel-do-morro-do-boi\/#primaryimage"},"thumbnailUrl":"https:\/\/jornalnosbairros.com.br\/wp\/wp-content\/uploads\/2024\/06\/tunel-do-morro-do-boi.jpg","keywords":["rodovias"],"articleSection":["RODOVIAS"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/jornalnosbairros.com.br\/wp\/2024\/06\/br-101-tera-interdicoes-no-acesso-ao-tunel-do-morro-do-boi\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/jornalnosbairros.com.br\/wp\/2024\/06\/br-101-tera-interdicoes-no-acesso-ao-tunel-do-morro-do-boi\/","url":"https:\/\/jornalnosbairros.com.br\/wp\/2024\/06\/br-101-tera-interdicoes-no-acesso-ao-tunel-do-morro-do-boi\/","name":"BR-101 TER\u00c1 INTERDI\u00c7\u00d5ES NO ACESSO AO T\u00daNEL DO MORRO DO BOI - Jornal nos Bairros","isPartOf":{"@id":"https:\/\/jornalnosbairros.com.br\/wp\/#website"},"primaryImageOfPage":{"@id":"https:\/\/jornalnosbairros.com.br\/wp\/2024\/06\/br-101-tera-interdicoes-no-acesso-ao-tunel-do-morro-do-boi\/#primaryimage"},"image":{"@id":"https:\/\/jornalnosbairros.com.br\/wp\/2024\/06\/br-101-tera-interdicoes-no-acesso-ao-tunel-do-morro-do-boi\/#primaryimage"},"thumbnailUrl":"https:\/\/jornalnosbairros.com.br\/wp\/wp-content\/uploads\/2024\/06\/tunel-do-morro-do-boi.jpg","datePublished":"2024-06-13T13:46:40+00:00","inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/jornalnosbairros.com.br\/wp\/2024\/06\/br-101-tera-interdicoes-no-acesso-ao-tunel-do-morro-do-boi\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/jornalnosbairros.com.br\/wp\/2024\/06\/br-101-tera-interdicoes-no-acesso-ao-tunel-do-morro-do-boi\/#primaryimage","url":"https:\/\/jornalnosbairros.com.br\/wp\/wp-content\/uploads\/2024\/06\/tunel-do-morro-do-boi.jpg","contentUrl":"https:\/\/jornalnosbairros.com.br\/wp\/wp-content\/uploads\/2024\/06\/tunel-do-morro-do-boi.jpg","width":694,"height":486},{"@type":"WebSite","@id":"https:\/\/jornalnosbairros.com.br\/wp\/#website","url":"https:\/\/jornalnosbairros.com.br\/wp\/","name":"Jornal nos Bairros","description":"Not\u00edcias di\u00e1rias de Navegantes e regi\u00e3o","publisher":{"@id":"https:\/\/jornalnosbairros.com.br\/wp\/#organization"},"alternateName":"JB","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/jornalnosbairros.com.br\/wp\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/jornalnosbairros.com.br\/wp\/#organization","name":"Jornal nos Bairros de Navegantes","url":"https:\/\/jornalnosbairros.com.br\/wp\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/jornalnosbairros.com.br\/wp\/#\/schema\/logo\/image\/","url":"https:\/\/jornalnosbairros.com.br\/wp\/wp-content\/uploads\/2025\/01\/LOGO-JB.png","contentUrl":"https:\/\/jornalnosbairros.com.br\/wp\/wp-content\/uploads\/2025\/01\/LOGO-JB.png","width":168,"height":150,"caption":"Jornal nos Bairros de Navegantes"},"image":{"@id":"https:\/\/jornalnosbairros.com.br\/wp\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/jornalnosbairros","https:\/\/x.com\/jornal_bairros","https:\/\/www.instagram.com\/jornalnosbairros","https:\/\/www.youtube.com\/@jornalnosbairros"]},{"@type":"Person","@id":"https:\/\/jornalnosbairros.com.br\/wp\/#\/schema\/person\/9a74fde2f4332c018c3b4d29a6129437","name":"Editoria","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/b53a04b7003d01b914d43ebacd13b233f0d99ed1cb7f8cb7d8553ef90e3f466b?s=96&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b53a04b7003d01b914d43ebacd13b233f0d99ed1cb7f8cb7d8553ef90e3f466b?s=96&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b53a04b7003d01b914d43ebacd13b233f0d99ed1cb7f8cb7d8553ef90e3f466b?s=96&r=g","caption":"Editoria"},"description":"Edi\u00e7\u00e3o do Jornal nos Bairros de Navegantes - Contato: fale@jornalnosbairros.com.br - Siga: @jornalnosbairros - Acesse: www.jornalnosbairros.com.br","sameAs":["http:\/\/www.jornalnosbairros.com.br\/wp","https:\/\/www.facebook.com\/jornalnosbairros","https:\/\/www.instagram.com\/jornalnosbairros\/","https:\/\/x.com\/https:\/\/twitter.com\/jornal_bairros","https:\/\/www.youtube.com\/channel\/UCbdZNY5wPbaBq5KtRGP4WxQ?view_as=subscriber"],"url":"https:\/\/jornalnosbairros.com.br\/wp\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/jornalnosbairros.com.br\/wp\/wp-json\/wp\/v2\/posts\/31110","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jornalnosbairros.com.br\/wp\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jornalnosbairros.com.br\/wp\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jornalnosbairros.com.br\/wp\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/jornalnosbairros.com.br\/wp\/wp-json\/wp\/v2\/comments?post=31110"}],"version-history":[{"count":1,"href":"https:\/\/jornalnosbairros.com.br\/wp\/wp-json\/wp\/v2\/posts\/31110\/revisions"}],"predecessor-version":[{"id":31112,"href":"https:\/\/jornalnosbairros.com.br\/wp\/wp-json\/wp\/v2\/posts\/31110\/revisions\/31112"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/jornalnosbairros.com.br\/wp\/wp-json\/wp\/v2\/media\/31111"}],"wp:attachment":[{"href":"https:\/\/jornalnosbairros.com.br\/wp\/wp-json\/wp\/v2\/media?parent=31110"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jornalnosbairros.com.br\/wp\/wp-json\/wp\/v2\/categories?post=31110"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jornalnosbairros.com.br\/wp\/wp-json\/wp\/v2\/tags?post=31110"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}