{"id":17321,"date":"2022-09-22T12:46:52","date_gmt":"2022-09-22T12:46:52","guid":{"rendered":"https:\/\/jornalnosbairros.com.br\/wp\/?p=17321"},"modified":"2022-09-22T18:19:10","modified_gmt":"2022-09-22T18:19:10","slug":"a-rua-dos-velhacos","status":"publish","type":"post","link":"https:\/\/jornalnosbairros.com.br\/wp\/2022\/09\/a-rua-dos-velhacos\/","title":{"rendered":"OUTROS QUINHENTOS:  A RUA DOS VELHACOS"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Por Rog\u00e9rio Pinheiro<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A coluna \u201cOutros quinhentos\u201d desta semana traz a curiosa hist\u00f3ria da entrega do carn\u00ea do Imposto Predial Urbano de 1958, o atual IPTU. O erro no nome de uma rua de Navegantes deu o que falar e fez a Prefeitura de Itaja\u00ed emitir um pedido de desculpas aos moradores.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Em outubro de 1958, a Diretoria da Fazenda come\u00e7ou a entregar os tal\u00f5es do imposto nos bairros, entre eles Navegantes. A entrega seguia sem problemas at\u00e9 que os moradores da rua de Baixo, atual 26 de agosto, receberam seus tal\u00f5es. Inv\u00e9s de rua de Baixo, os impostos estavam endere\u00e7ados para os moradores da \u201crua dos Velhacos\u201d. Velhaco \u00e9 uma palavra utilizada para aqueles que enganam os outros ou n\u00e3o pagam suas contas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A rea\u00e7\u00e3o dos moradores foi imediata. Alguns protestaram e outros procuram os jornais para reclamar da brincadeira de mau gosto. Um deles foi o Jornal Itaja\u00ed que publicou a indigna\u00e7\u00e3o dos moradores da rua de Baixo na edi\u00e7\u00e3o do dia 25 de outubro de 1958.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cA Prefeitura Municipal de Itaja\u00ed, ao extrair os tal\u00f5es de Imposto Predial de toda uma rua em Navegantes p\u00f4s simplesmente estas indica\u00e7\u00f5es como endere\u00e7os dos contribuintes: \u2018Rua dos Velhacos \u2013 Navegantes\u2019. N\u00e3o foi um caso isolado. Tivemos nesta reda\u00e7\u00e3o mais de dez tal\u00f5es com o mesmo endere\u00e7o. Passadas as elei\u00e7\u00f5es, podemos afirmar agora, sem demagogia: N\u00e3o se trata de \u2018rua dos velhacos\u2019. Trata-se de toda uma zona de pescadores pobres que, certamente, encontram grande dificuldade em resgatar os impostos dos seus modestos casebres. Que n\u00e3o se justifica, em hip\u00f3tese nenhuma, e que a Prefeitura, oficialmente, em avisos de lan\u00e7amentos preenchidos e assinados, use uma denomina\u00e7\u00e3o inexistente para ofender \u00e0queles que n\u00e3o possam estar em dia com os seus impostos.\u201d<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A repercuss\u00e3o negativa fez a Prefeitura de Itaja\u00ed emitir uma nota publicada no mesmo Jornal Itaja\u00ed do 1 de novembro de 1958. Na nota, a Diretoria da Fazenda estava mais preocupada em isentar o prefeito Carlos de Paula Se\u00e1ra, o Lito Se\u00e1ra, eleito em 1955 pelo Partido Social Democr\u00e1tico (PSD), do que fazer um pedido formal de desculpas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cA Diretoria da Fazenda, a fim de prestar p\u00fabico esclarecimento sobre o lament\u00e1vel lapso verificado na oportunidade da expedi\u00e7\u00e3o de avisos de lan\u00e7amentos do Imposto Predial Urbano para determinada rua do bairro de Navegantes cumpre o dever de chamar a si integral responsabilidade pelo fato da indevida denomina\u00e7\u00e3o dada popularmente conhecida como Rua dos Velhacos.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full is-resized\"><img decoding=\"async\" data-src=\"https:\/\/jornalnosbairros.com.br\/wp\/wp-content\/uploads\/2022\/09\/Rua-01-1.jpg\" alt=\"\" class=\"wp-image-17322 lazyload\" width=\"768\" height=\"576\" data-srcset=\"https:\/\/jornalnosbairros.com.br\/wp\/wp-content\/uploads\/2022\/09\/Rua-01-1.jpg 1024w, https:\/\/jornalnosbairros.com.br\/wp\/wp-content\/uploads\/2022\/09\/Rua-01-1-300x225.jpg 300w, https:\/\/jornalnosbairros.com.br\/wp\/wp-content\/uploads\/2022\/09\/Rua-01-1-768x576.jpg 768w\" data-sizes=\"(max-width: 768px) 100vw, 768px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 768px; --smush-placeholder-aspect-ratio: 768\/576;\" \/><figcaption>Artigo publicado na \u00e9poca: &nbsp;Jornal Itaja\u00ed publicou a reclama\u00e7\u00e3o dos moradores de Navegantes<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">A Diretoria da Fazenda em se tratando de um \u00f3rg\u00e3o aut\u00f4nomo \u00e9 respons\u00e1vel pela coleta de dados e elementos necess\u00e1rios a elabora\u00e7\u00e3o dos lan\u00e7amentos de impostos devidos ao munic\u00edpio, sem que tais elementos sofram qualquer inger\u00eancia do prefeito, o qual somente os aprecia em grau de recurso.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Infelizmente, o lament\u00e1vel lapso decorreu na oportunidade da coleta de dados para o citado tributo, quando para controle interno desta reparti\u00e7\u00e3o valeu-se o fiscal lan\u00e7ador das informa\u00e7\u00f5es recebidas e esta denomina\u00e7\u00e3o para uso interno serve apenas para identifica\u00e7\u00e3o, por assim a mesma conhecida pela popula\u00e7\u00e3o daquele bairro, cuja origem n\u00e3o cabe nesta oportunidade apreciar.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nunca, por\u00e9m foi da mais leve inten\u00e7\u00e3o desta Diretoria ou mesmo da Prefeitura, usar desta denomina\u00e7\u00e3o para a citada rua, no sentido de ofender os moradores ou mun\u00edcipes nela residentes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O senhor prefeito, tomando conhecimento do lament\u00e1vel ocorrido, do qual nenhuma responsabilidade lhe cabe, determinou imediatas provid\u00eancias, para que fossem expedidos avisos de lan\u00e7amentos em substitui\u00e7\u00e3o aqueles que deram origem ao fato, bem como advertindo energicamente os respons\u00e1veis pelo ocorrido.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full is-resized\"><img decoding=\"async\" data-src=\"https:\/\/jornalnosbairros.com.br\/wp\/wp-content\/uploads\/2022\/09\/Rua-02-1.jpg\" alt=\"\" class=\"wp-image-17323 lazyload\" width=\"768\" height=\"576\" data-srcset=\"https:\/\/jornalnosbairros.com.br\/wp\/wp-content\/uploads\/2022\/09\/Rua-02-1.jpg 1024w, https:\/\/jornalnosbairros.com.br\/wp\/wp-content\/uploads\/2022\/09\/Rua-02-1-300x225.jpg 300w, https:\/\/jornalnosbairros.com.br\/wp\/wp-content\/uploads\/2022\/09\/Rua-02-1-768x576.jpg 768w\" data-sizes=\"(max-width: 768px) 100vw, 768px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 768px; --smush-placeholder-aspect-ratio: 768\/576;\" \/><figcaption>Repercuss\u00e3o negativa fez Prefeitura de Itaja\u00ed emitir um pedido formal de desculpas<br>Cr\u00e9ditos: Reprodu\u00e7\u00e3o\/Arquivo P\u00fablico de Itaja\u00ed&nbsp;<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Portando, estando o prefeito isento de qualquer parcela de responsabilidade sobre o ocorrido e por dever de justi\u00e7a, \u00e9 que espontaneamente a Diretoria da Fazenda chama a si a integral responsabilidade do acontecido, sem que para isto tenha ela sofrido qualquer coa\u00e7\u00e3o ou determina\u00e7\u00e3o por parte de sua Exma.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">S\u00e3o estes os esclarecimentos que a Diretoria da Fazenda deseja prestar ao p\u00fablico em geral, especialmente aos residentes na citada rua, no bairro de Navegantes.\u201d<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>A origem da rua dos Velhacos<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Antes da emancipa\u00e7\u00e3o de Navegantes em 1962, era comum as pessoas se referirem a avenida Ant\u00f4nio Sacav\u00e9m (atual Jo\u00e3o Sacav\u00e9m) como rua de Cima. J\u00e1 a atual 26 de agosto na \u00e9poca era conhecida apenas por rua de Baixo. A via apelidada de \u201crua dos Velhacos\u201d foi aberta para ser caminho por onde passava o trilho das vias f\u00e9rreas que levaram as locomotivas e os vag\u00f5es com pedras para o aterro do molhe. Depois do t\u00e9rmino da obra do molhe, o caminho ficou aberto para os pedestres e carro\u00e7as transitarem.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">No livro \u201cNot\u00edcias de Navegantes\u201d, de autoria de Vera Estork, o historiador Edison d&#8217;\u00c1vila conta que o apelido surgiu por conta de um comerciante da avenida Ant\u00f4nio Sacav\u00e9m.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u2013 A explica\u00e7\u00e3o que eu ouvi na \u00e9poca \u00e9 que na rua de Cima, havia um comerciante forte de secos e molhados, que vendia a caderneta, no fiado para aquele povo que morava l\u00e1 no Pontal, que era realmente uma popula\u00e7\u00e3o pobre de pescadores artesanais. Eles iam comprando na caderneta e se a pescaria, algumas vezes, n\u00e3o rendia tanto, eles n\u00e3o tinham como pagar a conta. Da\u00ed obviamente ficavam envergonhados de passar em frente da venda com a d\u00edvida que tinham e desviavam para passar pela rua de Baixo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Segundo Edison d&#8217;\u00c1vila, a confus\u00e3o feita pela Prefeitura de Itaja\u00ed tamb\u00e9m foi usada politicamente.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u2013 O Jornal Itaja\u00ed era ligado a UDN (Uni\u00e3o Democr\u00e1tica Nacional) e a mat\u00e9ria foi usada politicamente contra o partido do prefeito da \u00e9poca que era PSD. Tem esse lado pol\u00edtico tem que ser olhar, mas o jornal tinha raz\u00e3o de noticiar porque o que a prefeitura fez foi lastim\u00e1vel \u2014 disse o historiador no livro \u201cNot\u00edcias de Navegantes\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Outra vers\u00e3o da hist\u00f3ria \u00e9 contada pelo navegantino Lauro Jos\u00e9 Toledo dos Santos. Segundo ele, as pessoas que deviam no armaz\u00e9m de secos e molhados da avenida Jo\u00e3o Sacav\u00e9m pediam para cortar caminho onde \u00e9 hoje a rua Jo\u00e3o Em\u00edlio e n\u00e3o a 26 de agosto. Na \u00e9poca, as terras pertenciam ao seu pai, o comerciante Jos\u00e9 Silvestre Toledo dos Santos, o Z\u00e9 Toledo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u2013 Essa rua n\u00e3o existia, era fechado. Tinha um cara na Jo\u00e3o Sacav\u00e9m que se chamava M\u00e1rio Gaya. As pessoas compravam no M\u00e1rio Gaya fiado. Tinha alguns que ficavam devendo e para n\u00e3o passar pela rua, porque o M\u00e1rio chamava, vieram pedir para o meu pai. Eles diziam que estavam devendo no M\u00e1rio. \u00c9 por causa disso que \u00e9 a rua dos Velhacos \u2013 recorda.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">J\u00e1 no livro \u201cO Navegantes que eu conto\u201d, de Didymea Lazzaris de Oliveira, o armaz\u00e9m de secos e molhados pertencia ao comerciante Jo\u00e3o Em\u00edlio, que tamb\u00e9m ficava na atual avenida Jo\u00e3o Sacav\u00e9m. Para evitar as cobran\u00e7as do comerciante, as pessoas que deviam no armaz\u00e9m passavam onde \u00e9 hoje a rua da Prefeitura de Navegantes, que recebeu o nome do comerciante Jo\u00e3o Em\u00edlio.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Por Rog\u00e9rio Pinheiro A coluna \u201cOutros quinhentos\u201d desta semana traz a curiosa hist\u00f3ria da entrega do carn\u00ea do Imposto Predial Urbano de 1958, o atual IPTU. O erro no nome de uma rua&hellip;<\/p>\n","protected":false},"author":1,"featured_media":17328,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"ai_generated_summary":"","footnotes":""},"categories":[35],"tags":[47,240,40,396],"class_list":["post-17321","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-colunistas","tag-cidade","tag-coluna","tag-navegantes","tag-outrosquinhentos"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>OUTROS QUINHENTOS: A RUA DOS VELHACOS - Jornal nos Bairros<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/jornalnosbairros.com.br\/wp\/2022\/09\/a-rua-dos-velhacos\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"OUTROS QUINHENTOS: A RUA DOS VELHACOS - Jornal nos Bairros\" \/>\n<meta property=\"og:description\" content=\"Por Rog\u00e9rio Pinheiro A coluna \u201cOutros quinhentos\u201d desta semana traz a curiosa hist\u00f3ria da entrega do carn\u00ea do Imposto Predial Urbano de 1958, o atual IPTU. O erro no nome de uma rua&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/jornalnosbairros.com.br\/wp\/2022\/09\/a-rua-dos-velhacos\/\" \/>\n<meta property=\"og:site_name\" content=\"Jornal nos Bairros\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/jornalnosbairros\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/jornalnosbairros\" \/>\n<meta property=\"article:published_time\" content=\"2022-09-22T12:46:52+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-09-22T18:19:10+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/jornalnosbairros.com.br\/wp\/wp-content\/uploads\/2022\/09\/rua-joao-emilio-Navegantes-arquivo.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1490\" \/>\n\t<meta property=\"og:image:height\" content=\"990\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Editoria\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/jornal_bairros\" \/>\n<meta name=\"twitter:site\" content=\"@jornal_bairros\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Editoria\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/2022\\\/09\\\/a-rua-dos-velhacos\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/2022\\\/09\\\/a-rua-dos-velhacos\\\/\"},\"author\":{\"name\":\"Editoria\",\"@id\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/#\\\/schema\\\/person\\\/9a74fde2f4332c018c3b4d29a6129437\"},\"headline\":\"OUTROS QUINHENTOS: A RUA DOS VELHACOS\",\"datePublished\":\"2022-09-22T12:46:52+00:00\",\"dateModified\":\"2022-09-22T18:19:10+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/2022\\\/09\\\/a-rua-dos-velhacos\\\/\"},\"wordCount\":1260,\"publisher\":{\"@id\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/2022\\\/09\\\/a-rua-dos-velhacos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/rua-joao-emilio-Navegantes-arquivo.jpg\",\"keywords\":[\"cidade\",\"COLUNA\",\"navegantes\",\"outrosquinhentos\"],\"articleSection\":[\"COLUNISTAS\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/2022\\\/09\\\/a-rua-dos-velhacos\\\/\",\"url\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/2022\\\/09\\\/a-rua-dos-velhacos\\\/\",\"name\":\"OUTROS QUINHENTOS: A RUA DOS VELHACOS - Jornal nos Bairros\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/2022\\\/09\\\/a-rua-dos-velhacos\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/2022\\\/09\\\/a-rua-dos-velhacos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/rua-joao-emilio-Navegantes-arquivo.jpg\",\"datePublished\":\"2022-09-22T12:46:52+00:00\",\"dateModified\":\"2022-09-22T18:19:10+00:00\",\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/2022\\\/09\\\/a-rua-dos-velhacos\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/2022\\\/09\\\/a-rua-dos-velhacos\\\/#primaryimage\",\"url\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/rua-joao-emilio-Navegantes-arquivo.jpg\",\"contentUrl\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/rua-joao-emilio-Navegantes-arquivo.jpg\",\"width\":1490,\"height\":990,\"caption\":\"rua jo\u00e3o em\u00edlio Navegantes arquivo\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/#website\",\"url\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/\",\"name\":\"Jornal nos Bairros\",\"description\":\"Not\u00edcias di\u00e1rias de Navegantes e regi\u00e3o\",\"publisher\":{\"@id\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/#organization\"},\"alternateName\":\"JB\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/#organization\",\"name\":\"Jornal nos Bairros de Navegantes\",\"url\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/LOGO-JB.png\",\"contentUrl\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/LOGO-JB.png\",\"width\":168,\"height\":150,\"caption\":\"Jornal nos Bairros de Navegantes\"},\"image\":{\"@id\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/jornalnosbairros\",\"https:\\\/\\\/x.com\\\/jornal_bairros\",\"https:\\\/\\\/www.instagram.com\\\/jornalnosbairros\",\"https:\\\/\\\/www.youtube.com\\\/@jornalnosbairros\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/#\\\/schema\\\/person\\\/9a74fde2f4332c018c3b4d29a6129437\",\"name\":\"Editoria\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b53a04b7003d01b914d43ebacd13b233f0d99ed1cb7f8cb7d8553ef90e3f466b?s=96&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b53a04b7003d01b914d43ebacd13b233f0d99ed1cb7f8cb7d8553ef90e3f466b?s=96&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b53a04b7003d01b914d43ebacd13b233f0d99ed1cb7f8cb7d8553ef90e3f466b?s=96&r=g\",\"caption\":\"Editoria\"},\"description\":\"Edi\u00e7\u00e3o do Jornal nos Bairros de Navegantes - Contato: fale@jornalnosbairros.com.br - Siga: @jornalnosbairros - Acesse: www.jornalnosbairros.com.br\",\"sameAs\":[\"http:\\\/\\\/www.jornalnosbairros.com.br\\\/wp\",\"https:\\\/\\\/www.facebook.com\\\/jornalnosbairros\",\"https:\\\/\\\/www.instagram.com\\\/jornalnosbairros\\\/\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/jornal_bairros\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCbdZNY5wPbaBq5KtRGP4WxQ?view_as=subscriber\"],\"url\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"OUTROS QUINHENTOS: A RUA DOS VELHACOS - Jornal nos Bairros","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/jornalnosbairros.com.br\/wp\/2022\/09\/a-rua-dos-velhacos\/","og_locale":"pt_BR","og_type":"article","og_title":"OUTROS QUINHENTOS: A RUA DOS VELHACOS - Jornal nos Bairros","og_description":"Por Rog\u00e9rio Pinheiro A coluna \u201cOutros quinhentos\u201d desta semana traz a curiosa hist\u00f3ria da entrega do carn\u00ea do Imposto Predial Urbano de 1958, o atual IPTU. O erro no nome de uma rua&hellip;","og_url":"https:\/\/jornalnosbairros.com.br\/wp\/2022\/09\/a-rua-dos-velhacos\/","og_site_name":"Jornal nos Bairros","article_publisher":"https:\/\/www.facebook.com\/jornalnosbairros","article_author":"https:\/\/www.facebook.com\/jornalnosbairros","article_published_time":"2022-09-22T12:46:52+00:00","article_modified_time":"2022-09-22T18:19:10+00:00","og_image":[{"width":1490,"height":990,"url":"https:\/\/jornalnosbairros.com.br\/wp\/wp-content\/uploads\/2022\/09\/rua-joao-emilio-Navegantes-arquivo.jpg","type":"image\/jpeg"}],"author":"Editoria","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/jornal_bairros","twitter_site":"@jornal_bairros","twitter_misc":{"Escrito por":"Editoria","Est. tempo de leitura":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/jornalnosbairros.com.br\/wp\/2022\/09\/a-rua-dos-velhacos\/#article","isPartOf":{"@id":"https:\/\/jornalnosbairros.com.br\/wp\/2022\/09\/a-rua-dos-velhacos\/"},"author":{"name":"Editoria","@id":"https:\/\/jornalnosbairros.com.br\/wp\/#\/schema\/person\/9a74fde2f4332c018c3b4d29a6129437"},"headline":"OUTROS QUINHENTOS: A RUA DOS VELHACOS","datePublished":"2022-09-22T12:46:52+00:00","dateModified":"2022-09-22T18:19:10+00:00","mainEntityOfPage":{"@id":"https:\/\/jornalnosbairros.com.br\/wp\/2022\/09\/a-rua-dos-velhacos\/"},"wordCount":1260,"publisher":{"@id":"https:\/\/jornalnosbairros.com.br\/wp\/#organization"},"image":{"@id":"https:\/\/jornalnosbairros.com.br\/wp\/2022\/09\/a-rua-dos-velhacos\/#primaryimage"},"thumbnailUrl":"https:\/\/jornalnosbairros.com.br\/wp\/wp-content\/uploads\/2022\/09\/rua-joao-emilio-Navegantes-arquivo.jpg","keywords":["cidade","COLUNA","navegantes","outrosquinhentos"],"articleSection":["COLUNISTAS"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/jornalnosbairros.com.br\/wp\/2022\/09\/a-rua-dos-velhacos\/","url":"https:\/\/jornalnosbairros.com.br\/wp\/2022\/09\/a-rua-dos-velhacos\/","name":"OUTROS QUINHENTOS: A RUA DOS VELHACOS - Jornal nos Bairros","isPartOf":{"@id":"https:\/\/jornalnosbairros.com.br\/wp\/#website"},"primaryImageOfPage":{"@id":"https:\/\/jornalnosbairros.com.br\/wp\/2022\/09\/a-rua-dos-velhacos\/#primaryimage"},"image":{"@id":"https:\/\/jornalnosbairros.com.br\/wp\/2022\/09\/a-rua-dos-velhacos\/#primaryimage"},"thumbnailUrl":"https:\/\/jornalnosbairros.com.br\/wp\/wp-content\/uploads\/2022\/09\/rua-joao-emilio-Navegantes-arquivo.jpg","datePublished":"2022-09-22T12:46:52+00:00","dateModified":"2022-09-22T18:19:10+00:00","inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/jornalnosbairros.com.br\/wp\/2022\/09\/a-rua-dos-velhacos\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/jornalnosbairros.com.br\/wp\/2022\/09\/a-rua-dos-velhacos\/#primaryimage","url":"https:\/\/jornalnosbairros.com.br\/wp\/wp-content\/uploads\/2022\/09\/rua-joao-emilio-Navegantes-arquivo.jpg","contentUrl":"https:\/\/jornalnosbairros.com.br\/wp\/wp-content\/uploads\/2022\/09\/rua-joao-emilio-Navegantes-arquivo.jpg","width":1490,"height":990,"caption":"rua jo\u00e3o em\u00edlio Navegantes arquivo"},{"@type":"WebSite","@id":"https:\/\/jornalnosbairros.com.br\/wp\/#website","url":"https:\/\/jornalnosbairros.com.br\/wp\/","name":"Jornal nos Bairros","description":"Not\u00edcias di\u00e1rias de Navegantes e regi\u00e3o","publisher":{"@id":"https:\/\/jornalnosbairros.com.br\/wp\/#organization"},"alternateName":"JB","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/jornalnosbairros.com.br\/wp\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/jornalnosbairros.com.br\/wp\/#organization","name":"Jornal nos Bairros de Navegantes","url":"https:\/\/jornalnosbairros.com.br\/wp\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/jornalnosbairros.com.br\/wp\/#\/schema\/logo\/image\/","url":"https:\/\/jornalnosbairros.com.br\/wp\/wp-content\/uploads\/2025\/01\/LOGO-JB.png","contentUrl":"https:\/\/jornalnosbairros.com.br\/wp\/wp-content\/uploads\/2025\/01\/LOGO-JB.png","width":168,"height":150,"caption":"Jornal nos Bairros de Navegantes"},"image":{"@id":"https:\/\/jornalnosbairros.com.br\/wp\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/jornalnosbairros","https:\/\/x.com\/jornal_bairros","https:\/\/www.instagram.com\/jornalnosbairros","https:\/\/www.youtube.com\/@jornalnosbairros"]},{"@type":"Person","@id":"https:\/\/jornalnosbairros.com.br\/wp\/#\/schema\/person\/9a74fde2f4332c018c3b4d29a6129437","name":"Editoria","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/b53a04b7003d01b914d43ebacd13b233f0d99ed1cb7f8cb7d8553ef90e3f466b?s=96&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b53a04b7003d01b914d43ebacd13b233f0d99ed1cb7f8cb7d8553ef90e3f466b?s=96&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b53a04b7003d01b914d43ebacd13b233f0d99ed1cb7f8cb7d8553ef90e3f466b?s=96&r=g","caption":"Editoria"},"description":"Edi\u00e7\u00e3o do Jornal nos Bairros de Navegantes - Contato: fale@jornalnosbairros.com.br - Siga: @jornalnosbairros - Acesse: www.jornalnosbairros.com.br","sameAs":["http:\/\/www.jornalnosbairros.com.br\/wp","https:\/\/www.facebook.com\/jornalnosbairros","https:\/\/www.instagram.com\/jornalnosbairros\/","https:\/\/x.com\/https:\/\/twitter.com\/jornal_bairros","https:\/\/www.youtube.com\/channel\/UCbdZNY5wPbaBq5KtRGP4WxQ?view_as=subscriber"],"url":"https:\/\/jornalnosbairros.com.br\/wp\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/jornalnosbairros.com.br\/wp\/wp-json\/wp\/v2\/posts\/17321","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jornalnosbairros.com.br\/wp\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jornalnosbairros.com.br\/wp\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jornalnosbairros.com.br\/wp\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/jornalnosbairros.com.br\/wp\/wp-json\/wp\/v2\/comments?post=17321"}],"version-history":[{"count":8,"href":"https:\/\/jornalnosbairros.com.br\/wp\/wp-json\/wp\/v2\/posts\/17321\/revisions"}],"predecessor-version":[{"id":17339,"href":"https:\/\/jornalnosbairros.com.br\/wp\/wp-json\/wp\/v2\/posts\/17321\/revisions\/17339"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/jornalnosbairros.com.br\/wp\/wp-json\/wp\/v2\/media\/17328"}],"wp:attachment":[{"href":"https:\/\/jornalnosbairros.com.br\/wp\/wp-json\/wp\/v2\/media?parent=17321"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jornalnosbairros.com.br\/wp\/wp-json\/wp\/v2\/categories?post=17321"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jornalnosbairros.com.br\/wp\/wp-json\/wp\/v2\/tags?post=17321"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}