{"id":17289,"date":"2022-09-21T16:38:34","date_gmt":"2022-09-21T16:38:34","guid":{"rendered":"https:\/\/jornalnosbairros.com.br\/wp\/?p=17289"},"modified":"2023-01-26T17:32:20","modified_gmt":"2023-01-26T17:32:20","slug":"politicas-publicas-de-bem-estar-animal-de-navegantes-e-referencia-em-sc","status":"publish","type":"post","link":"https:\/\/jornalnosbairros.com.br\/wp\/2022\/09\/politicas-publicas-de-bem-estar-animal-de-navegantes-e-referencia-em-sc\/","title":{"rendered":"POL\u00cdTICAS P\u00daBLICAS DE BEM ESTAR ANIMAL DE NAVEGANTES \u00c9 REFER\u00caNCIA EM SC"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Navegantes est\u00e1 se tornando refer\u00eancia entre as cidades catarinenses, com as melhores estrat\u00e9gias de pol\u00edticas p\u00fablicas de manejo populacional e bem-estar animal, de c\u00e3es e gatos. As a\u00e7\u00f5es desenvolvidas em parceria do executivo e legislativo (emendas), atrav\u00e9s da ativista e vereadora <a href=\"https:\/\/www.facebook.com\/Sorilei\">Sol Dapper<\/a> (Uni\u00e3o Brasil), est\u00e1 al\u00e7ando \u00edndices jamais vistos. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Durante os \u00faltimos meses, Navegantes recebeu representantes do poderes p\u00fablicos de v\u00e1rias cidades que fizeram uma visita t\u00e9cnica, a fim de conhecer as pol\u00edticas de Bem Estar Animal, bem como a estrutura, prova de que est\u00e1 dando certo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dentre as a\u00e7\u00f5es de destaque do munic\u00edpio est\u00e3o projetos inovadores nas \u00e1reas de educa\u00e7\u00e3o em guarda respons\u00e1vel, animais comunit\u00e1rios, registro e identifica\u00e7\u00e3o com microchipagem, autua\u00e7\u00e3o de maus tratos com den\u00fancias direcionadas ao Instituto Ambiental de Navegantes (IAN). <\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"718\" height=\"495\" data-src=\"https:\/\/jornalnosbairros.com.br\/wp\/wp-content\/uploads\/2022\/09\/Castracao-em-Navegantes-por-Eder-Nascimento.jpg\" alt=\"\" class=\"wp-image-17293 lazyload\" data-srcset=\"https:\/\/jornalnosbairros.com.br\/wp\/wp-content\/uploads\/2022\/09\/Castracao-em-Navegantes-por-Eder-Nascimento.jpg 718w, https:\/\/jornalnosbairros.com.br\/wp\/wp-content\/uploads\/2022\/09\/Castracao-em-Navegantes-por-Eder-Nascimento-300x207.jpg 300w, https:\/\/jornalnosbairros.com.br\/wp\/wp-content\/uploads\/2022\/09\/Castracao-em-Navegantes-por-Eder-Nascimento-130x90.jpg 130w\" data-sizes=\"(max-width: 718px) 100vw, 718px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 718px; --smush-placeholder-aspect-ratio: 718\/495;\" \/><figcaption>Somente em 2022 foram castrados 3.511 c\u00e3es e gatos em Navegantes<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Recorde na castra\u00e7\u00e3o de animais<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Somente neste ano foram castrados 3.511 c\u00e3es e gatos, 4.701 microchipados, 1.989 consultas, 1.328 vacinados, 600 encaminhamentos de alta complexidade, 298 encaminhamentos de baixa e m\u00e9dia complexidade, 259 ado\u00e7\u00f5es e 510 resgates. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Al\u00e9m dos mutir\u00f5es, Navegantes conta, ainda, com o Departamento de Assist\u00eancia e Bem-Estar Animal (Daba),onde s\u00e3o microchipados, vacinados e castrados animais de rua e de fam\u00edlia de baixa renda. Tamb\u00e9m com atendimento m\u00e9dico veterin\u00e1rio, com cirurgias de baixa e m\u00e9dia complexidade e para casos de alta complexidade uma cl\u00ednica conveniada. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cQuem acompanha a minha trajet\u00f3ria, na causa animal, sabe o quanto eu falo de pol\u00edticas p\u00fablicas e de sa\u00fade \u00fanica e sabe o quanto n\u00f3s, eu e os demais protetores da nossa cidade lutamos. A causa animal \u00e9 uma causa de todos, n\u00e3o \u00e9 s\u00f3 dos ativistas, nem s\u00f3 da vereadora Sol e nem s\u00f3 do poder p\u00fablico. H\u00e1 necessidade do engajamento de todos para que juntos desenvolvam pol\u00edticas p\u00fablicas efetivas.\u201d, comenta Sol.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Navegantes est\u00e1 se tornando refer\u00eancia entre as cidades catarinenses, com as melhores estrat\u00e9gias de pol\u00edticas p\u00fablicas de manejo populacional e bem-estar animal, de c\u00e3es e gatos. As a\u00e7\u00f5es desenvolvidas em parceria do executivo&hellip;<\/p>\n","protected":false},"author":1,"featured_media":17290,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"ai_generated_summary":"","footnotes":""},"categories":[3],"tags":[48,416,47,40,73],"class_list":["post-17289","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-geral","tag-acao","tag-bemestaranimal","tag-cidade","tag-navegantes","tag-saude"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>POL\u00cdTICAS P\u00daBLICAS DE BEM ESTAR ANIMAL DE NAVEGANTES \u00c9 REFER\u00caNCIA EM SC<\/title>\n<meta name=\"description\" content=\"As a\u00e7\u00f5es desenvolvidas em parceria do executivo e legislativo (emendas), atrav\u00e9s da ativista e vereadora Sol Dapper, est\u00e1 al\u00e7ando \u00edndices\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/jornalnosbairros.com.br\/wp\/2022\/09\/politicas-publicas-de-bem-estar-animal-de-navegantes-e-referencia-em-sc\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"POL\u00cdTICAS P\u00daBLICAS DE BEM ESTAR ANIMAL DE NAVEGANTES \u00c9 REFER\u00caNCIA EM SC\" \/>\n<meta property=\"og:description\" content=\"As a\u00e7\u00f5es desenvolvidas em parceria do executivo e legislativo (emendas), atrav\u00e9s da ativista e vereadora Sol Dapper, est\u00e1 al\u00e7ando \u00edndices\" \/>\n<meta property=\"og:url\" content=\"https:\/\/jornalnosbairros.com.br\/wp\/2022\/09\/politicas-publicas-de-bem-estar-animal-de-navegantes-e-referencia-em-sc\/\" \/>\n<meta property=\"og:site_name\" content=\"Jornal nos Bairros\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/jornalnosbairros\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/jornalnosbairros\" \/>\n<meta property=\"article:published_time\" content=\"2022-09-21T16:38:34+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-01-26T17:32:20+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/jornalnosbairros.com.br\/wp\/wp-content\/uploads\/2022\/09\/Visita-ao-Daba-Sol-Dapper.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1121\" \/>\n\t<meta property=\"og:image:height\" content=\"841\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Editoria\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/jornal_bairros\" \/>\n<meta name=\"twitter:site\" content=\"@jornal_bairros\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Editoria\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/2022\\\/09\\\/politicas-publicas-de-bem-estar-animal-de-navegantes-e-referencia-em-sc\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/2022\\\/09\\\/politicas-publicas-de-bem-estar-animal-de-navegantes-e-referencia-em-sc\\\/\"},\"author\":{\"name\":\"Editoria\",\"@id\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/#\\\/schema\\\/person\\\/9a74fde2f4332c018c3b4d29a6129437\"},\"headline\":\"POL\u00cdTICAS P\u00daBLICAS DE BEM ESTAR ANIMAL DE NAVEGANTES \u00c9 REFER\u00caNCIA EM SC\",\"datePublished\":\"2022-09-21T16:38:34+00:00\",\"dateModified\":\"2023-01-26T17:32:20+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/2022\\\/09\\\/politicas-publicas-de-bem-estar-animal-de-navegantes-e-referencia-em-sc\\\/\"},\"wordCount\":345,\"publisher\":{\"@id\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/2022\\\/09\\\/politicas-publicas-de-bem-estar-animal-de-navegantes-e-referencia-em-sc\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/Visita-ao-Daba-Sol-Dapper.jpeg\",\"keywords\":[\"acao\",\"bemestaranimal\",\"cidade\",\"navegantes\",\"saude\"],\"articleSection\":[\"GERAL\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/2022\\\/09\\\/politicas-publicas-de-bem-estar-animal-de-navegantes-e-referencia-em-sc\\\/\",\"url\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/2022\\\/09\\\/politicas-publicas-de-bem-estar-animal-de-navegantes-e-referencia-em-sc\\\/\",\"name\":\"POL\u00cdTICAS P\u00daBLICAS DE BEM ESTAR ANIMAL DE NAVEGANTES \u00c9 REFER\u00caNCIA EM SC\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/2022\\\/09\\\/politicas-publicas-de-bem-estar-animal-de-navegantes-e-referencia-em-sc\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/2022\\\/09\\\/politicas-publicas-de-bem-estar-animal-de-navegantes-e-referencia-em-sc\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/Visita-ao-Daba-Sol-Dapper.jpeg\",\"datePublished\":\"2022-09-21T16:38:34+00:00\",\"dateModified\":\"2023-01-26T17:32:20+00:00\",\"description\":\"As a\u00e7\u00f5es desenvolvidas em parceria do executivo e legislativo (emendas), atrav\u00e9s da ativista e vereadora Sol Dapper, est\u00e1 al\u00e7ando \u00edndices\",\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/2022\\\/09\\\/politicas-publicas-de-bem-estar-animal-de-navegantes-e-referencia-em-sc\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/2022\\\/09\\\/politicas-publicas-de-bem-estar-animal-de-navegantes-e-referencia-em-sc\\\/#primaryimage\",\"url\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/Visita-ao-Daba-Sol-Dapper.jpeg\",\"contentUrl\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/Visita-ao-Daba-Sol-Dapper.jpeg\",\"width\":1121,\"height\":841,\"caption\":\"Visita ao Daba Sol Dapper\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/#website\",\"url\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/\",\"name\":\"Jornal nos Bairros\",\"description\":\"Not\u00edcias di\u00e1rias de Navegantes e regi\u00e3o\",\"publisher\":{\"@id\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/#organization\"},\"alternateName\":\"JB\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/#organization\",\"name\":\"Jornal nos Bairros de Navegantes\",\"url\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/LOGO-JB.png\",\"contentUrl\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/LOGO-JB.png\",\"width\":168,\"height\":150,\"caption\":\"Jornal nos Bairros de Navegantes\"},\"image\":{\"@id\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/jornalnosbairros\",\"https:\\\/\\\/x.com\\\/jornal_bairros\",\"https:\\\/\\\/www.instagram.com\\\/jornalnosbairros\",\"https:\\\/\\\/www.youtube.com\\\/@jornalnosbairros\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/#\\\/schema\\\/person\\\/9a74fde2f4332c018c3b4d29a6129437\",\"name\":\"Editoria\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b53a04b7003d01b914d43ebacd13b233f0d99ed1cb7f8cb7d8553ef90e3f466b?s=96&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b53a04b7003d01b914d43ebacd13b233f0d99ed1cb7f8cb7d8553ef90e3f466b?s=96&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b53a04b7003d01b914d43ebacd13b233f0d99ed1cb7f8cb7d8553ef90e3f466b?s=96&r=g\",\"caption\":\"Editoria\"},\"description\":\"Edi\u00e7\u00e3o do Jornal nos Bairros de Navegantes - Contato: fale@jornalnosbairros.com.br - Siga: @jornalnosbairros - Acesse: www.jornalnosbairros.com.br\",\"sameAs\":[\"http:\\\/\\\/www.jornalnosbairros.com.br\\\/wp\",\"https:\\\/\\\/www.facebook.com\\\/jornalnosbairros\",\"https:\\\/\\\/www.instagram.com\\\/jornalnosbairros\\\/\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/jornal_bairros\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCbdZNY5wPbaBq5KtRGP4WxQ?view_as=subscriber\"],\"url\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"POL\u00cdTICAS P\u00daBLICAS DE BEM ESTAR ANIMAL DE NAVEGANTES \u00c9 REFER\u00caNCIA EM SC","description":"As a\u00e7\u00f5es desenvolvidas em parceria do executivo e legislativo (emendas), atrav\u00e9s da ativista e vereadora Sol Dapper, est\u00e1 al\u00e7ando \u00edndices","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/jornalnosbairros.com.br\/wp\/2022\/09\/politicas-publicas-de-bem-estar-animal-de-navegantes-e-referencia-em-sc\/","og_locale":"pt_BR","og_type":"article","og_title":"POL\u00cdTICAS P\u00daBLICAS DE BEM ESTAR ANIMAL DE NAVEGANTES \u00c9 REFER\u00caNCIA EM SC","og_description":"As a\u00e7\u00f5es desenvolvidas em parceria do executivo e legislativo (emendas), atrav\u00e9s da ativista e vereadora Sol Dapper, est\u00e1 al\u00e7ando \u00edndices","og_url":"https:\/\/jornalnosbairros.com.br\/wp\/2022\/09\/politicas-publicas-de-bem-estar-animal-de-navegantes-e-referencia-em-sc\/","og_site_name":"Jornal nos Bairros","article_publisher":"https:\/\/www.facebook.com\/jornalnosbairros","article_author":"https:\/\/www.facebook.com\/jornalnosbairros","article_published_time":"2022-09-21T16:38:34+00:00","article_modified_time":"2023-01-26T17:32:20+00:00","og_image":[{"width":1121,"height":841,"url":"https:\/\/jornalnosbairros.com.br\/wp\/wp-content\/uploads\/2022\/09\/Visita-ao-Daba-Sol-Dapper.jpeg","type":"image\/jpeg"}],"author":"Editoria","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/jornal_bairros","twitter_site":"@jornal_bairros","twitter_misc":{"Escrito por":"Editoria","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/jornalnosbairros.com.br\/wp\/2022\/09\/politicas-publicas-de-bem-estar-animal-de-navegantes-e-referencia-em-sc\/#article","isPartOf":{"@id":"https:\/\/jornalnosbairros.com.br\/wp\/2022\/09\/politicas-publicas-de-bem-estar-animal-de-navegantes-e-referencia-em-sc\/"},"author":{"name":"Editoria","@id":"https:\/\/jornalnosbairros.com.br\/wp\/#\/schema\/person\/9a74fde2f4332c018c3b4d29a6129437"},"headline":"POL\u00cdTICAS P\u00daBLICAS DE BEM ESTAR ANIMAL DE NAVEGANTES \u00c9 REFER\u00caNCIA EM SC","datePublished":"2022-09-21T16:38:34+00:00","dateModified":"2023-01-26T17:32:20+00:00","mainEntityOfPage":{"@id":"https:\/\/jornalnosbairros.com.br\/wp\/2022\/09\/politicas-publicas-de-bem-estar-animal-de-navegantes-e-referencia-em-sc\/"},"wordCount":345,"publisher":{"@id":"https:\/\/jornalnosbairros.com.br\/wp\/#organization"},"image":{"@id":"https:\/\/jornalnosbairros.com.br\/wp\/2022\/09\/politicas-publicas-de-bem-estar-animal-de-navegantes-e-referencia-em-sc\/#primaryimage"},"thumbnailUrl":"https:\/\/jornalnosbairros.com.br\/wp\/wp-content\/uploads\/2022\/09\/Visita-ao-Daba-Sol-Dapper.jpeg","keywords":["acao","bemestaranimal","cidade","navegantes","saude"],"articleSection":["GERAL"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/jornalnosbairros.com.br\/wp\/2022\/09\/politicas-publicas-de-bem-estar-animal-de-navegantes-e-referencia-em-sc\/","url":"https:\/\/jornalnosbairros.com.br\/wp\/2022\/09\/politicas-publicas-de-bem-estar-animal-de-navegantes-e-referencia-em-sc\/","name":"POL\u00cdTICAS P\u00daBLICAS DE BEM ESTAR ANIMAL DE NAVEGANTES \u00c9 REFER\u00caNCIA EM SC","isPartOf":{"@id":"https:\/\/jornalnosbairros.com.br\/wp\/#website"},"primaryImageOfPage":{"@id":"https:\/\/jornalnosbairros.com.br\/wp\/2022\/09\/politicas-publicas-de-bem-estar-animal-de-navegantes-e-referencia-em-sc\/#primaryimage"},"image":{"@id":"https:\/\/jornalnosbairros.com.br\/wp\/2022\/09\/politicas-publicas-de-bem-estar-animal-de-navegantes-e-referencia-em-sc\/#primaryimage"},"thumbnailUrl":"https:\/\/jornalnosbairros.com.br\/wp\/wp-content\/uploads\/2022\/09\/Visita-ao-Daba-Sol-Dapper.jpeg","datePublished":"2022-09-21T16:38:34+00:00","dateModified":"2023-01-26T17:32:20+00:00","description":"As a\u00e7\u00f5es desenvolvidas em parceria do executivo e legislativo (emendas), atrav\u00e9s da ativista e vereadora Sol Dapper, est\u00e1 al\u00e7ando \u00edndices","inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/jornalnosbairros.com.br\/wp\/2022\/09\/politicas-publicas-de-bem-estar-animal-de-navegantes-e-referencia-em-sc\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/jornalnosbairros.com.br\/wp\/2022\/09\/politicas-publicas-de-bem-estar-animal-de-navegantes-e-referencia-em-sc\/#primaryimage","url":"https:\/\/jornalnosbairros.com.br\/wp\/wp-content\/uploads\/2022\/09\/Visita-ao-Daba-Sol-Dapper.jpeg","contentUrl":"https:\/\/jornalnosbairros.com.br\/wp\/wp-content\/uploads\/2022\/09\/Visita-ao-Daba-Sol-Dapper.jpeg","width":1121,"height":841,"caption":"Visita ao Daba Sol Dapper"},{"@type":"WebSite","@id":"https:\/\/jornalnosbairros.com.br\/wp\/#website","url":"https:\/\/jornalnosbairros.com.br\/wp\/","name":"Jornal nos Bairros","description":"Not\u00edcias di\u00e1rias de Navegantes e regi\u00e3o","publisher":{"@id":"https:\/\/jornalnosbairros.com.br\/wp\/#organization"},"alternateName":"JB","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/jornalnosbairros.com.br\/wp\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/jornalnosbairros.com.br\/wp\/#organization","name":"Jornal nos Bairros de Navegantes","url":"https:\/\/jornalnosbairros.com.br\/wp\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/jornalnosbairros.com.br\/wp\/#\/schema\/logo\/image\/","url":"https:\/\/jornalnosbairros.com.br\/wp\/wp-content\/uploads\/2025\/01\/LOGO-JB.png","contentUrl":"https:\/\/jornalnosbairros.com.br\/wp\/wp-content\/uploads\/2025\/01\/LOGO-JB.png","width":168,"height":150,"caption":"Jornal nos Bairros de Navegantes"},"image":{"@id":"https:\/\/jornalnosbairros.com.br\/wp\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/jornalnosbairros","https:\/\/x.com\/jornal_bairros","https:\/\/www.instagram.com\/jornalnosbairros","https:\/\/www.youtube.com\/@jornalnosbairros"]},{"@type":"Person","@id":"https:\/\/jornalnosbairros.com.br\/wp\/#\/schema\/person\/9a74fde2f4332c018c3b4d29a6129437","name":"Editoria","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/b53a04b7003d01b914d43ebacd13b233f0d99ed1cb7f8cb7d8553ef90e3f466b?s=96&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b53a04b7003d01b914d43ebacd13b233f0d99ed1cb7f8cb7d8553ef90e3f466b?s=96&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b53a04b7003d01b914d43ebacd13b233f0d99ed1cb7f8cb7d8553ef90e3f466b?s=96&r=g","caption":"Editoria"},"description":"Edi\u00e7\u00e3o do Jornal nos Bairros de Navegantes - Contato: fale@jornalnosbairros.com.br - Siga: @jornalnosbairros - Acesse: www.jornalnosbairros.com.br","sameAs":["http:\/\/www.jornalnosbairros.com.br\/wp","https:\/\/www.facebook.com\/jornalnosbairros","https:\/\/www.instagram.com\/jornalnosbairros\/","https:\/\/x.com\/https:\/\/twitter.com\/jornal_bairros","https:\/\/www.youtube.com\/channel\/UCbdZNY5wPbaBq5KtRGP4WxQ?view_as=subscriber"],"url":"https:\/\/jornalnosbairros.com.br\/wp\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/jornalnosbairros.com.br\/wp\/wp-json\/wp\/v2\/posts\/17289","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jornalnosbairros.com.br\/wp\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jornalnosbairros.com.br\/wp\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jornalnosbairros.com.br\/wp\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/jornalnosbairros.com.br\/wp\/wp-json\/wp\/v2\/comments?post=17289"}],"version-history":[{"count":11,"href":"https:\/\/jornalnosbairros.com.br\/wp\/wp-json\/wp\/v2\/posts\/17289\/revisions"}],"predecessor-version":[{"id":17305,"href":"https:\/\/jornalnosbairros.com.br\/wp\/wp-json\/wp\/v2\/posts\/17289\/revisions\/17305"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/jornalnosbairros.com.br\/wp\/wp-json\/wp\/v2\/media\/17290"}],"wp:attachment":[{"href":"https:\/\/jornalnosbairros.com.br\/wp\/wp-json\/wp\/v2\/media?parent=17289"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jornalnosbairros.com.br\/wp\/wp-json\/wp\/v2\/categories?post=17289"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jornalnosbairros.com.br\/wp\/wp-json\/wp\/v2\/tags?post=17289"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}