{"id":16915,"date":"2022-09-08T13:06:47","date_gmt":"2022-09-08T13:06:47","guid":{"rendered":"https:\/\/jornalnosbairros.com.br\/wp\/?p=16915"},"modified":"2022-09-08T13:09:28","modified_gmt":"2022-09-08T13:09:28","slug":"setembro-amarelo-alerta-aumento-de-casos-de-suicidio","status":"publish","type":"post","link":"https:\/\/jornalnosbairros.com.br\/wp\/2022\/09\/setembro-amarelo-alerta-aumento-de-casos-de-suicidio\/","title":{"rendered":"SETEMBRO AMARELO ALERTA AUMENTO DE CASOS DE SUIC\u00cdDIO"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><br><strong>*Artigo: psic\u00f3loga Emmanuelle Fernandes<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br>Neste s\u00e1bado (10), acontece o Dia Mundial de Preven\u00e7\u00e3o ao Suic\u00eddio e durante todo o m\u00eas \u00e9 realizada a campanha Setembro Amarelo. Dados divulgados em julho deste ano pelo DataSUS apontam que o n\u00famero de casos de suic\u00eddio no Brasil dobrou de 7 para 14 mil nos \u00faltimos 20 anos &#8211; mais de um suic\u00eddio cometido a cada hora, sem contar casos n\u00e3o notificados.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Percebo que ainda existe um tabu em torno do tema. Portanto, orientar a sociedade a como identificar sinais de alerta e como ajudar pessoas com risco de cometer suic\u00eddio \u00e9 muito importante. A troca de informa\u00e7\u00f5es \u00e9 positiva, pois como estamos nos comunicando e nos organizando enquanto indiv\u00edduos e enquanto sociedade, \u00e9 o que determina o impacto que sofremos.<br>Em alguns casos, a pessoa com idea\u00e7\u00e3o suicida deixa claro sua inten\u00e7\u00e3o por meio de queixas constantes, compara\u00e7\u00f5es em que se v\u00ea em posi\u00e7\u00e3o inferior e\/ou como v\u00edtima. Os pensamentos suicidas t\u00eam rela\u00e7\u00e3o direta com o desejo da n\u00e3o exist\u00eancia e podem ser desencadeados pela resist\u00eancia ou dificuldade em lidar com a dor ou adversidades da vida.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nesse sentido, existem alguns sinais que merecem aten\u00e7\u00e3o. Pela minha experi\u00eancia, pessoas com um n\u00edvel de ansiedade grande tendem a se isolar do contato social, enquanto que as com depress\u00e3o podem se tornar extremamente falantes na tentativa de disfar\u00e7ar sentimentos.<br>Quando a pessoa d\u00e1 sinais de alerta, a busca por um profissional de sa\u00fade deve ser imediata, visando apoiar o processo de reabilita\u00e7\u00e3o, a busca por um tratamento que ajude a aumentar os fatores de prote\u00e7\u00e3o e diminuir os riscos de suic\u00eddio. Al\u00e9m disso, quanto mais pessoas envolvidas no processo de tratamento de pessoas com idea\u00e7\u00e3o suicida, melhor!<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Vale lembrar que algumas pessoas n\u00e3o d\u00e3o sinais de idea\u00e7\u00e3o suicida. Contudo, ao se deparar com uma pessoa com problemas de sa\u00fade mental, a melhor forma de ajudar \u00e9 oferecendo escuta atenta, presente e respeitosa e, dentro do poss\u00edvel, ajudar a pessoa a encontrar o melhor caminho para o tratamento.<br>O processo de pensar sobre o suic\u00eddio ocorre de maneira c\u00edclica, na intera\u00e7\u00e3o entre corpo e mente, e geralmente envolve um ciclo de alimenta\u00e7\u00e3o e sono ruim que prejudicam a qualidade da produ\u00e7\u00e3o hormonal, provocam pensamentos negativos e sentimentos de estresse e ang\u00fastia, prejudicando a qualidade de vida em um c\u00edrculo vicioso. Por isso, nossos cuidados devem sempre envolver a sa\u00fade f\u00edsica, mental e espiritual.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>*Artigo: psic\u00f3loga Emmanuelle Fernandes Neste s\u00e1bado (10), acontece o Dia Mundial de Preven\u00e7\u00e3o ao Suic\u00eddio e durante todo o m\u00eas \u00e9 realizada a campanha Setembro Amarelo. Dados divulgados em julho deste ano pelo&hellip;<\/p>\n","protected":false},"author":2,"featured_media":16918,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"ai_generated_summary":"","footnotes":""},"categories":[23],"tags":[],"class_list":["post-16915","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-editorial"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>SETEMBRO AMARELO ALERTA AUMENTO DE CASOS DE SUIC\u00cdDIO - Jornal nos Bairros<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/jornalnosbairros.com.br\/wp\/2022\/09\/setembro-amarelo-alerta-aumento-de-casos-de-suicidio\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"SETEMBRO AMARELO ALERTA AUMENTO DE CASOS DE SUIC\u00cdDIO - Jornal nos Bairros\" \/>\n<meta property=\"og:description\" content=\"*Artigo: psic\u00f3loga Emmanuelle Fernandes Neste s\u00e1bado (10), acontece o Dia Mundial de Preven\u00e7\u00e3o ao Suic\u00eddio e durante todo o m\u00eas \u00e9 realizada a campanha Setembro Amarelo. Dados divulgados em julho deste ano pelo&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/jornalnosbairros.com.br\/wp\/2022\/09\/setembro-amarelo-alerta-aumento-de-casos-de-suicidio\/\" \/>\n<meta property=\"og:site_name\" content=\"Jornal nos Bairros\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/jornalnosbairros\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/jornalnosbairros\" \/>\n<meta property=\"article:published_time\" content=\"2022-09-08T13:06:47+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-09-08T13:09:28+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/jornalnosbairros.com.br\/wp\/wp-content\/uploads\/2022\/09\/download.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1240\" \/>\n\t<meta property=\"og:image:height\" content=\"695\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Louise Benassi\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/jornal_bairros\" \/>\n<meta name=\"twitter:site\" content=\"@jornal_bairros\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Louise Benassi\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/2022\\\/09\\\/setembro-amarelo-alerta-aumento-de-casos-de-suicidio\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/2022\\\/09\\\/setembro-amarelo-alerta-aumento-de-casos-de-suicidio\\\/\"},\"author\":{\"name\":\"Louise Benassi\",\"@id\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/#\\\/schema\\\/person\\\/0fff6800408f4a5288e868b423aa66e6\"},\"headline\":\"SETEMBRO AMARELO ALERTA AUMENTO DE CASOS DE SUIC\u00cdDIO\",\"datePublished\":\"2022-09-08T13:06:47+00:00\",\"dateModified\":\"2022-09-08T13:09:28+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/2022\\\/09\\\/setembro-amarelo-alerta-aumento-de-casos-de-suicidio\\\/\"},\"wordCount\":445,\"publisher\":{\"@id\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/2022\\\/09\\\/setembro-amarelo-alerta-aumento-de-casos-de-suicidio\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/download.jpg\",\"articleSection\":[\"EDITORIAL\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/2022\\\/09\\\/setembro-amarelo-alerta-aumento-de-casos-de-suicidio\\\/\",\"url\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/2022\\\/09\\\/setembro-amarelo-alerta-aumento-de-casos-de-suicidio\\\/\",\"name\":\"SETEMBRO AMARELO ALERTA AUMENTO DE CASOS DE SUIC\u00cdDIO - Jornal nos Bairros\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/2022\\\/09\\\/setembro-amarelo-alerta-aumento-de-casos-de-suicidio\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/2022\\\/09\\\/setembro-amarelo-alerta-aumento-de-casos-de-suicidio\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/download.jpg\",\"datePublished\":\"2022-09-08T13:06:47+00:00\",\"dateModified\":\"2022-09-08T13:09:28+00:00\",\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/2022\\\/09\\\/setembro-amarelo-alerta-aumento-de-casos-de-suicidio\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/2022\\\/09\\\/setembro-amarelo-alerta-aumento-de-casos-de-suicidio\\\/#primaryimage\",\"url\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/download.jpg\",\"contentUrl\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/download.jpg\",\"width\":1240,\"height\":695},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/#website\",\"url\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/\",\"name\":\"Jornal nos Bairros\",\"description\":\"Not\u00edcias di\u00e1rias de Navegantes e regi\u00e3o\",\"publisher\":{\"@id\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/#organization\"},\"alternateName\":\"JB\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/#organization\",\"name\":\"Jornal nos Bairros de Navegantes\",\"url\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/LOGO-JB.png\",\"contentUrl\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/LOGO-JB.png\",\"width\":168,\"height\":150,\"caption\":\"Jornal nos Bairros de Navegantes\"},\"image\":{\"@id\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/jornalnosbairros\",\"https:\\\/\\\/x.com\\\/jornal_bairros\",\"https:\\\/\\\/www.instagram.com\\\/jornalnosbairros\",\"https:\\\/\\\/www.youtube.com\\\/@jornalnosbairros\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/#\\\/schema\\\/person\\\/0fff6800408f4a5288e868b423aa66e6\",\"name\":\"Louise Benassi\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9d4314cebcb775b6f2598392f1ed67a5d487928fbd387d9492add88335cb0166?s=96&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9d4314cebcb775b6f2598392f1ed67a5d487928fbd387d9492add88335cb0166?s=96&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9d4314cebcb775b6f2598392f1ed67a5d487928fbd387d9492add88335cb0166?s=96&r=g\",\"caption\":\"Louise Benassi\"},\"description\":\"Louise Benassi SC 002880\\\/JP - Jornalista do Jornal nos Bairros de Navegantes - Contato: fale@jornalnosbairros.com.br - Siga: @jornalnosbairros - Acesse: www.jornalnosbairros.com.br - WhatsApp 47 33196585\",\"sameAs\":[\"http:\\\/\\\/www.jornalnosbairros.com.br\",\"https:\\\/\\\/www.facebook.com\\\/jornalnosbairros\",\"https:\\\/\\\/www.instagram.com\\\/jornalnosbairros\\\/\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/jornal_bairros\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCbdZNY5wPbaBq5KtRGP4WxQ\"],\"url\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/author\\\/louise\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"SETEMBRO AMARELO ALERTA AUMENTO DE CASOS DE SUIC\u00cdDIO - Jornal nos Bairros","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/jornalnosbairros.com.br\/wp\/2022\/09\/setembro-amarelo-alerta-aumento-de-casos-de-suicidio\/","og_locale":"pt_BR","og_type":"article","og_title":"SETEMBRO AMARELO ALERTA AUMENTO DE CASOS DE SUIC\u00cdDIO - Jornal nos Bairros","og_description":"*Artigo: psic\u00f3loga Emmanuelle Fernandes Neste s\u00e1bado (10), acontece o Dia Mundial de Preven\u00e7\u00e3o ao Suic\u00eddio e durante todo o m\u00eas \u00e9 realizada a campanha Setembro Amarelo. Dados divulgados em julho deste ano pelo&hellip;","og_url":"https:\/\/jornalnosbairros.com.br\/wp\/2022\/09\/setembro-amarelo-alerta-aumento-de-casos-de-suicidio\/","og_site_name":"Jornal nos Bairros","article_publisher":"https:\/\/www.facebook.com\/jornalnosbairros","article_author":"https:\/\/www.facebook.com\/jornalnosbairros","article_published_time":"2022-09-08T13:06:47+00:00","article_modified_time":"2022-09-08T13:09:28+00:00","og_image":[{"width":1240,"height":695,"url":"https:\/\/jornalnosbairros.com.br\/wp\/wp-content\/uploads\/2022\/09\/download.jpg","type":"image\/jpeg"}],"author":"Louise Benassi","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/jornal_bairros","twitter_site":"@jornal_bairros","twitter_misc":{"Escrito por":"Louise Benassi","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/jornalnosbairros.com.br\/wp\/2022\/09\/setembro-amarelo-alerta-aumento-de-casos-de-suicidio\/#article","isPartOf":{"@id":"https:\/\/jornalnosbairros.com.br\/wp\/2022\/09\/setembro-amarelo-alerta-aumento-de-casos-de-suicidio\/"},"author":{"name":"Louise Benassi","@id":"https:\/\/jornalnosbairros.com.br\/wp\/#\/schema\/person\/0fff6800408f4a5288e868b423aa66e6"},"headline":"SETEMBRO AMARELO ALERTA AUMENTO DE CASOS DE SUIC\u00cdDIO","datePublished":"2022-09-08T13:06:47+00:00","dateModified":"2022-09-08T13:09:28+00:00","mainEntityOfPage":{"@id":"https:\/\/jornalnosbairros.com.br\/wp\/2022\/09\/setembro-amarelo-alerta-aumento-de-casos-de-suicidio\/"},"wordCount":445,"publisher":{"@id":"https:\/\/jornalnosbairros.com.br\/wp\/#organization"},"image":{"@id":"https:\/\/jornalnosbairros.com.br\/wp\/2022\/09\/setembro-amarelo-alerta-aumento-de-casos-de-suicidio\/#primaryimage"},"thumbnailUrl":"https:\/\/jornalnosbairros.com.br\/wp\/wp-content\/uploads\/2022\/09\/download.jpg","articleSection":["EDITORIAL"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/jornalnosbairros.com.br\/wp\/2022\/09\/setembro-amarelo-alerta-aumento-de-casos-de-suicidio\/","url":"https:\/\/jornalnosbairros.com.br\/wp\/2022\/09\/setembro-amarelo-alerta-aumento-de-casos-de-suicidio\/","name":"SETEMBRO AMARELO ALERTA AUMENTO DE CASOS DE SUIC\u00cdDIO - Jornal nos Bairros","isPartOf":{"@id":"https:\/\/jornalnosbairros.com.br\/wp\/#website"},"primaryImageOfPage":{"@id":"https:\/\/jornalnosbairros.com.br\/wp\/2022\/09\/setembro-amarelo-alerta-aumento-de-casos-de-suicidio\/#primaryimage"},"image":{"@id":"https:\/\/jornalnosbairros.com.br\/wp\/2022\/09\/setembro-amarelo-alerta-aumento-de-casos-de-suicidio\/#primaryimage"},"thumbnailUrl":"https:\/\/jornalnosbairros.com.br\/wp\/wp-content\/uploads\/2022\/09\/download.jpg","datePublished":"2022-09-08T13:06:47+00:00","dateModified":"2022-09-08T13:09:28+00:00","inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/jornalnosbairros.com.br\/wp\/2022\/09\/setembro-amarelo-alerta-aumento-de-casos-de-suicidio\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/jornalnosbairros.com.br\/wp\/2022\/09\/setembro-amarelo-alerta-aumento-de-casos-de-suicidio\/#primaryimage","url":"https:\/\/jornalnosbairros.com.br\/wp\/wp-content\/uploads\/2022\/09\/download.jpg","contentUrl":"https:\/\/jornalnosbairros.com.br\/wp\/wp-content\/uploads\/2022\/09\/download.jpg","width":1240,"height":695},{"@type":"WebSite","@id":"https:\/\/jornalnosbairros.com.br\/wp\/#website","url":"https:\/\/jornalnosbairros.com.br\/wp\/","name":"Jornal nos Bairros","description":"Not\u00edcias di\u00e1rias de Navegantes e regi\u00e3o","publisher":{"@id":"https:\/\/jornalnosbairros.com.br\/wp\/#organization"},"alternateName":"JB","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/jornalnosbairros.com.br\/wp\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/jornalnosbairros.com.br\/wp\/#organization","name":"Jornal nos Bairros de Navegantes","url":"https:\/\/jornalnosbairros.com.br\/wp\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/jornalnosbairros.com.br\/wp\/#\/schema\/logo\/image\/","url":"https:\/\/jornalnosbairros.com.br\/wp\/wp-content\/uploads\/2025\/01\/LOGO-JB.png","contentUrl":"https:\/\/jornalnosbairros.com.br\/wp\/wp-content\/uploads\/2025\/01\/LOGO-JB.png","width":168,"height":150,"caption":"Jornal nos Bairros de Navegantes"},"image":{"@id":"https:\/\/jornalnosbairros.com.br\/wp\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/jornalnosbairros","https:\/\/x.com\/jornal_bairros","https:\/\/www.instagram.com\/jornalnosbairros","https:\/\/www.youtube.com\/@jornalnosbairros"]},{"@type":"Person","@id":"https:\/\/jornalnosbairros.com.br\/wp\/#\/schema\/person\/0fff6800408f4a5288e868b423aa66e6","name":"Louise Benassi","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/9d4314cebcb775b6f2598392f1ed67a5d487928fbd387d9492add88335cb0166?s=96&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/9d4314cebcb775b6f2598392f1ed67a5d487928fbd387d9492add88335cb0166?s=96&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9d4314cebcb775b6f2598392f1ed67a5d487928fbd387d9492add88335cb0166?s=96&r=g","caption":"Louise Benassi"},"description":"Louise Benassi SC 002880\/JP - Jornalista do Jornal nos Bairros de Navegantes - Contato: fale@jornalnosbairros.com.br - Siga: @jornalnosbairros - Acesse: www.jornalnosbairros.com.br - WhatsApp 47 33196585","sameAs":["http:\/\/www.jornalnosbairros.com.br","https:\/\/www.facebook.com\/jornalnosbairros","https:\/\/www.instagram.com\/jornalnosbairros\/","https:\/\/x.com\/https:\/\/twitter.com\/jornal_bairros","https:\/\/www.youtube.com\/channel\/UCbdZNY5wPbaBq5KtRGP4WxQ"],"url":"https:\/\/jornalnosbairros.com.br\/wp\/author\/louise\/"}]}},"_links":{"self":[{"href":"https:\/\/jornalnosbairros.com.br\/wp\/wp-json\/wp\/v2\/posts\/16915","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jornalnosbairros.com.br\/wp\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jornalnosbairros.com.br\/wp\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jornalnosbairros.com.br\/wp\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/jornalnosbairros.com.br\/wp\/wp-json\/wp\/v2\/comments?post=16915"}],"version-history":[{"count":2,"href":"https:\/\/jornalnosbairros.com.br\/wp\/wp-json\/wp\/v2\/posts\/16915\/revisions"}],"predecessor-version":[{"id":16919,"href":"https:\/\/jornalnosbairros.com.br\/wp\/wp-json\/wp\/v2\/posts\/16915\/revisions\/16919"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/jornalnosbairros.com.br\/wp\/wp-json\/wp\/v2\/media\/16918"}],"wp:attachment":[{"href":"https:\/\/jornalnosbairros.com.br\/wp\/wp-json\/wp\/v2\/media?parent=16915"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jornalnosbairros.com.br\/wp\/wp-json\/wp\/v2\/categories?post=16915"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jornalnosbairros.com.br\/wp\/wp-json\/wp\/v2\/tags?post=16915"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}