{"id":16607,"date":"2022-08-22T19:22:47","date_gmt":"2022-08-22T19:22:47","guid":{"rendered":"https:\/\/jornalnosbairros.com.br\/wp\/?p=16607"},"modified":"2024-09-30T14:38:13","modified_gmt":"2024-09-30T17:38:13","slug":"dois-partidos-disputaram-primeira-eleicao-de-navegantes","status":"publish","type":"post","link":"https:\/\/jornalnosbairros.com.br\/wp\/2022\/08\/dois-partidos-disputaram-primeira-eleicao-de-navegantes\/","title":{"rendered":"DOIS PARTIDOS DISPUTARAM PRIMEIRA ELEI\u00c7\u00c3O DE NAVEGANTES"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>Por Rog\u00e9rio Pinheiro <\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ap\u00f3s se emancipar de Itaja\u00ed no dia 26 de agosto de 1962, Navegantes come\u00e7ou uma corrida contra o tempo para que os partidos lan\u00e7assem candidaturas para os cargos de prefeito e vereador. Em 1962, as elei\u00e7\u00f5es estavam marcadas para o dia 7 de outubro. Al\u00e9m do prefeito e vereador, o eleitor navegantino iria escolher naquele ano deputados federais, estaduais e senadores.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O Partido Social Democr\u00e1tico (PSD) e o Partido Trabalhista Brasileiro (PTB) lan\u00e7aram candidatos a prefeito. Ad\u00edlio Juvenal Mafra foi o candidato escolhido pelo PSD e Cirino Adolfo Cabral pelo PTB. J\u00e1 a Uni\u00e3o Democr\u00e1tica Nacional (UDN) decidiu apoiar a candidatura de Cirino Cabral.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sem santinhos ou publicidade em jornais, Cirino e Ad\u00edlio fizeram suas campanhas de casa em casa. Em 1962, Navegantes tinha aproximadamente 10 mil habitantes, metade moravam na zona rural. Eleitores eram menos de 2 mil.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Segundo a professora Vilma Rebello Mafra, 73 anos, a primeira campanha foi tranquila, ao contr\u00e1rio das anteriores, sempre com discuss\u00f5es e brigas. Vilma \u00e9 neta do primeiro prefeito de Navegantes, Athan\u00e1zio Joaquim Rodrigues (PTB), nomeado pelo governador Celso Ramos (PSD) em 1962.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u2013 Antes acontecia o com\u00edcio da UDN, o pessoal do PSD atrapalhava. Vinha o com\u00edcio do PSD e o pessoal da UDN acabava com tudo. Era briga de bate-boca, briga de se agredirem. Isso nas campanhas antes de 1962. Na primeira campanha n\u00e3o teve nada isso, era muito fam\u00edlia. Fizeram uns palanques pequenos para os candidatos. A campanha foi tranquila. Quando visitavam as casas, eles falavam das propostas. Os projetos eram pequenos, por exemplo, ilumina\u00e7\u00e3o p\u00fablica que n\u00e3o tinha \u2013 lembra.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mesmo sendo neta da principal lideran\u00e7a do PTB de Navegantes, Athan\u00e1zio Joaquim Rodrigues, a fam\u00edlia da dona Vilma votou no candidato do PSD, Ad\u00edlio Mafra.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u2013 O Cirino chegou a nos visitar, mas gost\u00e1vamos mais do Ad\u00edlio. O Ad\u00edlio tinha mais express\u00e3o. Todo mundo se dava bem, mas meu pai e minha m\u00e3e votaram no Ad\u00edlio \u2013 relata dona Vilma, que na \u00e9poca tinha 13 anos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ela contou que Athan\u00e1zio Rodrigues desistiu de ser candidato a prefeito por causa das brigas no pr\u00f3prio partido, o PTB.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u2013 Os pr\u00f3prios membros do partido come\u00e7aram a brigar e meu av\u00f4 n\u00e3o gostou disso. Ele preferiu n\u00e3o participar da elei\u00e7\u00e3o, ficou neutro. N\u00e3o apoiou nenhum candidato e ele tinha peso para isso. Ele nunca mais voltou para a pol\u00edtica \u2013 lamentou dona Vilma.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Elei\u00e7\u00e3o disputada&nbsp;&nbsp;&nbsp;&nbsp;<\/strong>&nbsp;&nbsp;&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">No domingo, 7 de outubro, a popula\u00e7\u00e3o de Navegantes saiu de casa em peso para eleger seu primeiro prefeito. A vota\u00e7\u00e3o foi tranquila e sem incidentes. Depois da apura\u00e7\u00e3o, Cirino Adolfo Cabral (PTB) foi eleito prefeito de Navegantes com 842 votos. Ad\u00edlio Mafra (PSD) foi o preferido de 733 eleitores. Votos em branco somaram 118 e os nulos apenas 11.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Al\u00e9m do prefeito, foram eleitos sete vereadores. Pela UDN, Arnoldo Bento Rodrigues, Manoel Durval Costa e Os\u00f3rio Gon\u00e7alves Viana. Pelo PSD se elegeram Manoel Ant\u00f4nio Coelho e Nereu Liberato Nunes. J\u00e1 Onofre Joaquim Rodrigues e Gildo Batista foram os vereadores eleitos pelo PTB.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A diploma\u00e7\u00e3o do primeiro prefeito, bem como dos primeiros vereadores foi realizada no dia 27 de novembro de 1962 e noticiada pelo Jornal do Povo de 2 de dezembro daquele ano.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cContando com a presen\u00e7a das mais destacadas personalidades itajaienses e sendo o ato presidido pelo doutor Osmundo Vieira Dutra, Juiz Eleitoral da Comarca, realizou-se na manh\u00e3 do dia 27 findo, a cerim\u00f4nia de diploma\u00e7\u00e3o do prefeito e vereadores da C\u00e2mara de Navegantes, o mais novo munic\u00edpio do Estado de Santa Catarina.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large is-resized\"><img decoding=\"async\" width=\"1024\" height=\"683\" data-src=\"https:\/\/jornalnosbairros.com.br\/wp\/wp-content\/uploads\/2022\/08\/Foto-2-1024x683.jpg\" alt=\"\" class=\"wp-image-16610 lazyload\" style=\"--smush-placeholder-width: 1024px; --smush-placeholder-aspect-ratio: 1024\/683;width:768px;height:512px\" data-srcset=\"https:\/\/jornalnosbairros.com.br\/wp\/wp-content\/uploads\/2022\/08\/Foto-2-1024x683.jpg 1024w, https:\/\/jornalnosbairros.com.br\/wp\/wp-content\/uploads\/2022\/08\/Foto-2-300x200.jpg 300w, https:\/\/jornalnosbairros.com.br\/wp\/wp-content\/uploads\/2022\/08\/Foto-2-768x512.jpg 768w, https:\/\/jornalnosbairros.com.br\/wp\/wp-content\/uploads\/2022\/08\/Foto-2-1536x1024.jpg 1536w, https:\/\/jornalnosbairros.com.br\/wp\/wp-content\/uploads\/2022\/08\/Foto-2.jpg 1710w\" data-sizes=\"(max-width: 1024px) 100vw, 1024px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" \/><figcaption class=\"wp-element-caption\">&nbsp;Com o apoio da UDN, Cirino Adolfo Cabral (PTB) foi eleito prefeito de Navegantes com 842 votos no dia 7 de outubro de 1962<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Preliminarmente, o doutor Osmundo Vieira Dutra, que foi assessorado pelo senhor Arnou Teixeira de Mello, esfor\u00e7ado Escriv\u00e3o Eleitoral, disse das finalidades daquela significativa cerim\u00f4nia e convidou o senhor prefeito e senhores vereadores eleitos no dia 7 de outubro a receberem seus diplomas, que foram alvos de longos aplausos e vibrante salva de palmas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ap\u00f3s a diploma\u00e7\u00e3o dos eleitos, usaram a palavra pela ordem o senhor Abdon F\u00f3es, Presidente do Partido Trabalhista Brasileiro, Sec\u00e7\u00e3o Itaja\u00ed, Padre Gilberto Gonzaga, senhor Eduardo Solon Cabral Canziani, prefeito de Itaja\u00ed e vereador Gildo Batista em nome da bancada do PTB. Encerrou a solene reuni\u00e3o o doutor Osmundo Vieira Dutra, que na oportunidade declarou que a posse dos diplomados se daria em 31 de janeiro de 1963.\u201d<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">No dia 31 de janeiro de 1963, como previsto, aconteceu a posse do prefeito e dos vereadores de Navegantes. A primeira C\u00e2mara de Vereadores de Navegantes ficou assim constitu\u00edda: presidente Os\u00f3rio Viana (UDN), vice-presidente Onofre Rodrigues Junior (PTB), 1\u00ba secret\u00e1rio Arnaldo Rodrigues (UDN) e 2\u00ba secret\u00e1rio Gildo Batista (PTB).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De acordo com a ata da primeira sess\u00e3o, realizada no sal\u00e3o nobre da Prefeitura Municipal, Os\u00f3rio Gon\u00e7alves Viana foi empossado como presidente por ser o vereador mais idoso, acompanhado por Arnoldo Bento Rodrigues e Gildo Batista como primeiro e segundo secret\u00e1rios, respectivamente. O mandato para a legislatura seria v\u00e1lido at\u00e9 o m\u00eas de janeiro de 1967.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Durante a vota\u00e7\u00e3o secreta, foram eleitos os membros da mesa diretora da Casa. Para presidente, Os\u00f3rio Gon\u00e7alves Viana recebeu cinco votos, contra dois a favor de Manoel Ant\u00f4nio Coelho. Na disputa para a vice-presid\u00eancia, venceu Onofre Rodrigues J\u00fanior depois de obter cinco votos. Como primeiro-secret\u00e1rio, a maioria ficou ao lado de Arnoldo Bento Rodrigues e Gildo Batista, com quatro votos v\u00e1lidos e dois em branco.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A primeira sede da Prefeitura Municipal de Navegantes foi uma casa de madeira na avenida Jo\u00e3o Sacav\u00e9m, em frente da Col\u00f4nia de Pescadores. A casa pertencia \u00e0 filha de Athan\u00e1zio Rodrigues. Em seguida, o prefeito Cirino Adolfo Cabral come\u00e7ou a despachar no casar\u00e3o da professora Paulina Gaya. O mandato do prefeito de Navegantes que terminaria no dia 31 de janeiro de 1967 foi estendido at\u00e9 1968 com a chegada dos militares ao poder em 1964, mas isso j\u00e1 s\u00e3o outros quinhentos.&nbsp;&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Por Rog\u00e9rio Pinheiro Ap\u00f3s se emancipar de Itaja\u00ed no dia 26 de agosto de 1962, Navegantes come\u00e7ou uma corrida contra o tempo para que os partidos lan\u00e7assem candidaturas para os cargos de prefeito&hellip;<\/p>\n","protected":false},"author":1,"featured_media":16608,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"ai_generated_summary":"","footnotes":""},"categories":[35],"tags":[428,48,47,40],"class_list":["post-16607","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-colunistas","tag-60anos","tag-acao","tag-cidade","tag-navegantes"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>DOIS PARTIDOS DISPUTARAM PRIMEIRA ELEI\u00c7\u00c3O DE NAVEGANTES - Jornal nos Bairros<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/jornalnosbairros.com.br\/wp\/2022\/08\/dois-partidos-disputaram-primeira-eleicao-de-navegantes\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"DOIS PARTIDOS DISPUTARAM PRIMEIRA ELEI\u00c7\u00c3O DE NAVEGANTES - Jornal nos Bairros\" \/>\n<meta property=\"og:description\" content=\"Por Rog\u00e9rio Pinheiro Ap\u00f3s se emancipar de Itaja\u00ed no dia 26 de agosto de 1962, Navegantes come\u00e7ou uma corrida contra o tempo para que os partidos lan\u00e7assem candidaturas para os cargos de prefeito&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/jornalnosbairros.com.br\/wp\/2022\/08\/dois-partidos-disputaram-primeira-eleicao-de-navegantes\/\" \/>\n<meta property=\"og:site_name\" content=\"Jornal nos Bairros\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/jornalnosbairros\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/jornalnosbairros\" \/>\n<meta property=\"article:published_time\" content=\"2022-08-22T19:22:47+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-09-30T17:38:13+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/jornalnosbairros.com.br\/wp\/wp-content\/uploads\/2022\/08\/Foto-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1709\" \/>\n\t<meta property=\"og:image:height\" content=\"1024\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Editoria\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/jornal_bairros\" \/>\n<meta name=\"twitter:site\" content=\"@jornal_bairros\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Editoria\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/2022\\\/08\\\/dois-partidos-disputaram-primeira-eleicao-de-navegantes\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/2022\\\/08\\\/dois-partidos-disputaram-primeira-eleicao-de-navegantes\\\/\"},\"author\":{\"name\":\"Editoria\",\"@id\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/#\\\/schema\\\/person\\\/9a74fde2f4332c018c3b4d29a6129437\"},\"headline\":\"DOIS PARTIDOS DISPUTARAM PRIMEIRA ELEI\u00c7\u00c3O DE NAVEGANTES\",\"datePublished\":\"2022-08-22T19:22:47+00:00\",\"dateModified\":\"2024-09-30T17:38:13+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/2022\\\/08\\\/dois-partidos-disputaram-primeira-eleicao-de-navegantes\\\/\"},\"wordCount\":1044,\"publisher\":{\"@id\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/2022\\\/08\\\/dois-partidos-disputaram-primeira-eleicao-de-navegantes\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/Foto-1.jpg\",\"keywords\":[\"60anos\",\"acao\",\"cidade\",\"navegantes\"],\"articleSection\":[\"COLUNISTAS\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/2022\\\/08\\\/dois-partidos-disputaram-primeira-eleicao-de-navegantes\\\/\",\"url\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/2022\\\/08\\\/dois-partidos-disputaram-primeira-eleicao-de-navegantes\\\/\",\"name\":\"DOIS PARTIDOS DISPUTARAM PRIMEIRA ELEI\u00c7\u00c3O DE NAVEGANTES - Jornal nos Bairros\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/2022\\\/08\\\/dois-partidos-disputaram-primeira-eleicao-de-navegantes\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/2022\\\/08\\\/dois-partidos-disputaram-primeira-eleicao-de-navegantes\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/Foto-1.jpg\",\"datePublished\":\"2022-08-22T19:22:47+00:00\",\"dateModified\":\"2024-09-30T17:38:13+00:00\",\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/2022\\\/08\\\/dois-partidos-disputaram-primeira-eleicao-de-navegantes\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/2022\\\/08\\\/dois-partidos-disputaram-primeira-eleicao-de-navegantes\\\/#primaryimage\",\"url\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/Foto-1.jpg\",\"contentUrl\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/Foto-1.jpg\",\"width\":1709,\"height\":1024,\"caption\":\"casar\u00e3o que morou Paulina Gaya antiga prefeitura de navegantes\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/#website\",\"url\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/\",\"name\":\"Jornal nos Bairros\",\"description\":\"Not\u00edcias di\u00e1rias de Navegantes e regi\u00e3o\",\"publisher\":{\"@id\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/#organization\"},\"alternateName\":\"JB\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/#organization\",\"name\":\"Jornal nos Bairros de Navegantes\",\"url\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/LOGO-JB.png\",\"contentUrl\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/LOGO-JB.png\",\"width\":168,\"height\":150,\"caption\":\"Jornal nos Bairros de Navegantes\"},\"image\":{\"@id\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/jornalnosbairros\",\"https:\\\/\\\/x.com\\\/jornal_bairros\",\"https:\\\/\\\/www.instagram.com\\\/jornalnosbairros\",\"https:\\\/\\\/www.youtube.com\\\/@jornalnosbairros\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/#\\\/schema\\\/person\\\/9a74fde2f4332c018c3b4d29a6129437\",\"name\":\"Editoria\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b53a04b7003d01b914d43ebacd13b233f0d99ed1cb7f8cb7d8553ef90e3f466b?s=96&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b53a04b7003d01b914d43ebacd13b233f0d99ed1cb7f8cb7d8553ef90e3f466b?s=96&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b53a04b7003d01b914d43ebacd13b233f0d99ed1cb7f8cb7d8553ef90e3f466b?s=96&r=g\",\"caption\":\"Editoria\"},\"description\":\"Edi\u00e7\u00e3o do Jornal nos Bairros de Navegantes - Contato: fale@jornalnosbairros.com.br - Siga: @jornalnosbairros - Acesse: www.jornalnosbairros.com.br\",\"sameAs\":[\"http:\\\/\\\/www.jornalnosbairros.com.br\\\/wp\",\"https:\\\/\\\/www.facebook.com\\\/jornalnosbairros\",\"https:\\\/\\\/www.instagram.com\\\/jornalnosbairros\\\/\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/jornal_bairros\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCbdZNY5wPbaBq5KtRGP4WxQ?view_as=subscriber\"],\"url\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"DOIS PARTIDOS DISPUTARAM PRIMEIRA ELEI\u00c7\u00c3O DE NAVEGANTES - Jornal nos Bairros","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/jornalnosbairros.com.br\/wp\/2022\/08\/dois-partidos-disputaram-primeira-eleicao-de-navegantes\/","og_locale":"pt_BR","og_type":"article","og_title":"DOIS PARTIDOS DISPUTARAM PRIMEIRA ELEI\u00c7\u00c3O DE NAVEGANTES - Jornal nos Bairros","og_description":"Por Rog\u00e9rio Pinheiro Ap\u00f3s se emancipar de Itaja\u00ed no dia 26 de agosto de 1962, Navegantes come\u00e7ou uma corrida contra o tempo para que os partidos lan\u00e7assem candidaturas para os cargos de prefeito&hellip;","og_url":"https:\/\/jornalnosbairros.com.br\/wp\/2022\/08\/dois-partidos-disputaram-primeira-eleicao-de-navegantes\/","og_site_name":"Jornal nos Bairros","article_publisher":"https:\/\/www.facebook.com\/jornalnosbairros","article_author":"https:\/\/www.facebook.com\/jornalnosbairros","article_published_time":"2022-08-22T19:22:47+00:00","article_modified_time":"2024-09-30T17:38:13+00:00","og_image":[{"width":1709,"height":1024,"url":"https:\/\/jornalnosbairros.com.br\/wp\/wp-content\/uploads\/2022\/08\/Foto-1.jpg","type":"image\/jpeg"}],"author":"Editoria","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/jornal_bairros","twitter_site":"@jornal_bairros","twitter_misc":{"Escrito por":"Editoria","Est. tempo de leitura":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/jornalnosbairros.com.br\/wp\/2022\/08\/dois-partidos-disputaram-primeira-eleicao-de-navegantes\/#article","isPartOf":{"@id":"https:\/\/jornalnosbairros.com.br\/wp\/2022\/08\/dois-partidos-disputaram-primeira-eleicao-de-navegantes\/"},"author":{"name":"Editoria","@id":"https:\/\/jornalnosbairros.com.br\/wp\/#\/schema\/person\/9a74fde2f4332c018c3b4d29a6129437"},"headline":"DOIS PARTIDOS DISPUTARAM PRIMEIRA ELEI\u00c7\u00c3O DE NAVEGANTES","datePublished":"2022-08-22T19:22:47+00:00","dateModified":"2024-09-30T17:38:13+00:00","mainEntityOfPage":{"@id":"https:\/\/jornalnosbairros.com.br\/wp\/2022\/08\/dois-partidos-disputaram-primeira-eleicao-de-navegantes\/"},"wordCount":1044,"publisher":{"@id":"https:\/\/jornalnosbairros.com.br\/wp\/#organization"},"image":{"@id":"https:\/\/jornalnosbairros.com.br\/wp\/2022\/08\/dois-partidos-disputaram-primeira-eleicao-de-navegantes\/#primaryimage"},"thumbnailUrl":"https:\/\/jornalnosbairros.com.br\/wp\/wp-content\/uploads\/2022\/08\/Foto-1.jpg","keywords":["60anos","acao","cidade","navegantes"],"articleSection":["COLUNISTAS"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/jornalnosbairros.com.br\/wp\/2022\/08\/dois-partidos-disputaram-primeira-eleicao-de-navegantes\/","url":"https:\/\/jornalnosbairros.com.br\/wp\/2022\/08\/dois-partidos-disputaram-primeira-eleicao-de-navegantes\/","name":"DOIS PARTIDOS DISPUTARAM PRIMEIRA ELEI\u00c7\u00c3O DE NAVEGANTES - Jornal nos Bairros","isPartOf":{"@id":"https:\/\/jornalnosbairros.com.br\/wp\/#website"},"primaryImageOfPage":{"@id":"https:\/\/jornalnosbairros.com.br\/wp\/2022\/08\/dois-partidos-disputaram-primeira-eleicao-de-navegantes\/#primaryimage"},"image":{"@id":"https:\/\/jornalnosbairros.com.br\/wp\/2022\/08\/dois-partidos-disputaram-primeira-eleicao-de-navegantes\/#primaryimage"},"thumbnailUrl":"https:\/\/jornalnosbairros.com.br\/wp\/wp-content\/uploads\/2022\/08\/Foto-1.jpg","datePublished":"2022-08-22T19:22:47+00:00","dateModified":"2024-09-30T17:38:13+00:00","inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/jornalnosbairros.com.br\/wp\/2022\/08\/dois-partidos-disputaram-primeira-eleicao-de-navegantes\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/jornalnosbairros.com.br\/wp\/2022\/08\/dois-partidos-disputaram-primeira-eleicao-de-navegantes\/#primaryimage","url":"https:\/\/jornalnosbairros.com.br\/wp\/wp-content\/uploads\/2022\/08\/Foto-1.jpg","contentUrl":"https:\/\/jornalnosbairros.com.br\/wp\/wp-content\/uploads\/2022\/08\/Foto-1.jpg","width":1709,"height":1024,"caption":"casar\u00e3o que morou Paulina Gaya antiga prefeitura de navegantes"},{"@type":"WebSite","@id":"https:\/\/jornalnosbairros.com.br\/wp\/#website","url":"https:\/\/jornalnosbairros.com.br\/wp\/","name":"Jornal nos Bairros","description":"Not\u00edcias di\u00e1rias de Navegantes e regi\u00e3o","publisher":{"@id":"https:\/\/jornalnosbairros.com.br\/wp\/#organization"},"alternateName":"JB","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/jornalnosbairros.com.br\/wp\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/jornalnosbairros.com.br\/wp\/#organization","name":"Jornal nos Bairros de Navegantes","url":"https:\/\/jornalnosbairros.com.br\/wp\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/jornalnosbairros.com.br\/wp\/#\/schema\/logo\/image\/","url":"https:\/\/jornalnosbairros.com.br\/wp\/wp-content\/uploads\/2025\/01\/LOGO-JB.png","contentUrl":"https:\/\/jornalnosbairros.com.br\/wp\/wp-content\/uploads\/2025\/01\/LOGO-JB.png","width":168,"height":150,"caption":"Jornal nos Bairros de Navegantes"},"image":{"@id":"https:\/\/jornalnosbairros.com.br\/wp\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/jornalnosbairros","https:\/\/x.com\/jornal_bairros","https:\/\/www.instagram.com\/jornalnosbairros","https:\/\/www.youtube.com\/@jornalnosbairros"]},{"@type":"Person","@id":"https:\/\/jornalnosbairros.com.br\/wp\/#\/schema\/person\/9a74fde2f4332c018c3b4d29a6129437","name":"Editoria","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/b53a04b7003d01b914d43ebacd13b233f0d99ed1cb7f8cb7d8553ef90e3f466b?s=96&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b53a04b7003d01b914d43ebacd13b233f0d99ed1cb7f8cb7d8553ef90e3f466b?s=96&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b53a04b7003d01b914d43ebacd13b233f0d99ed1cb7f8cb7d8553ef90e3f466b?s=96&r=g","caption":"Editoria"},"description":"Edi\u00e7\u00e3o do Jornal nos Bairros de Navegantes - Contato: fale@jornalnosbairros.com.br - Siga: @jornalnosbairros - Acesse: www.jornalnosbairros.com.br","sameAs":["http:\/\/www.jornalnosbairros.com.br\/wp","https:\/\/www.facebook.com\/jornalnosbairros","https:\/\/www.instagram.com\/jornalnosbairros\/","https:\/\/x.com\/https:\/\/twitter.com\/jornal_bairros","https:\/\/www.youtube.com\/channel\/UCbdZNY5wPbaBq5KtRGP4WxQ?view_as=subscriber"],"url":"https:\/\/jornalnosbairros.com.br\/wp\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/jornalnosbairros.com.br\/wp\/wp-json\/wp\/v2\/posts\/16607","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jornalnosbairros.com.br\/wp\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jornalnosbairros.com.br\/wp\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jornalnosbairros.com.br\/wp\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/jornalnosbairros.com.br\/wp\/wp-json\/wp\/v2\/comments?post=16607"}],"version-history":[{"count":3,"href":"https:\/\/jornalnosbairros.com.br\/wp\/wp-json\/wp\/v2\/posts\/16607\/revisions"}],"predecessor-version":[{"id":33246,"href":"https:\/\/jornalnosbairros.com.br\/wp\/wp-json\/wp\/v2\/posts\/16607\/revisions\/33246"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/jornalnosbairros.com.br\/wp\/wp-json\/wp\/v2\/media\/16608"}],"wp:attachment":[{"href":"https:\/\/jornalnosbairros.com.br\/wp\/wp-json\/wp\/v2\/media?parent=16607"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jornalnosbairros.com.br\/wp\/wp-json\/wp\/v2\/categories?post=16607"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jornalnosbairros.com.br\/wp\/wp-json\/wp\/v2\/tags?post=16607"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}