{"id":15466,"date":"2022-06-23T17:00:16","date_gmt":"2022-06-23T17:00:16","guid":{"rendered":"https:\/\/jornalnosbairros.com.br\/wp\/?p=15466"},"modified":"2022-06-23T17:02:21","modified_gmt":"2022-06-23T17:02:21","slug":"editorial-santo-de-casa-faz-milagre","status":"publish","type":"post","link":"https:\/\/jornalnosbairros.com.br\/wp\/2022\/06\/editorial-santo-de-casa-faz-milagre\/","title":{"rendered":"EDITORIAL: SANTO DE CASA FAZ MILAGRE"},"content":{"rendered":"<p>O Jornal nos Bairros traz, nessa edi\u00e7\u00e3o, uma entrevista exclusiva com o vice-prefeito de Navegantes, Wancarlos Corsani, que confirmou sua pr\u00e9-candidatura para disputar uma cadeira na Assembleia Legislativa de Santa Catarina. Assim como Wancarlos, outros nomes a pr\u00e9-candidatos a deputado est\u00e3o come\u00e7ando a aparecer no munic\u00edpio.<\/p>\n<p>Importante lembrar que Navegantes nunca elegeu um deputado estadual da cidade. O mais perto que se conseguiu foi a supl\u00eancia do ex-prefeito Deba. Nas elei\u00e7\u00f5es de 2006, ele concorreu \u00e0 vaga de deputado estadual pelo PMDB, obtendo 26.316 votos e ficando na posi\u00e7\u00e3o de quinto suplente. Foi convocado e exerceu fun\u00e7\u00f5es por sessenta dias, a partir de 7 de agosto de 2008, durante licen\u00e7a do Deputado Edson Piriquito, e a partir de 13 de janeiro de 2009, pelo afastamento do Deputado Ant\u00f4nio Ceron.<\/p>\n<p>Ou seja, um representante de Navegantes nunca esquentou a cadeira por mais de 60 dias na ALESC. E quem perde com isso \u00e9 a pr\u00f3pria cidade. Por mais que candidatos de outras cidades fa\u00e7am votos em Navegantes, nunca ter\u00e1 o mesmo olhar que tem pela sua cidade base eleitoral.<\/p>\n<p>Cidades que elegeram representantes da sua base eleitoral sempre tiveram resultados positivos. O munic\u00edpio de Bombinhas, por exemplo, com menos de 15 mil habitantes, conseguiu eleger uma parlamentar ao estado. \u00c8 claro, que somaram votos de toda a regi\u00e3o, no entanto, os votos dos eleitores locais fizeram toda a diferen\u00e7a. E hoje o munic\u00edpio j\u00e1 \u00e9 olhado com outros olhos pelo Estado, com vinda de recursos e melhorias para a cidade.<\/p>\n<p>E Navegantes, uma cidade com 85 mil ambientes, com uma forte economia e em pleno desenvolvimento, n\u00e3o consegue eleger um representante ao Parlamento Catarinense.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O Jornal nos Bairros traz, nessa edi\u00e7\u00e3o, uma entrevista exclusiva com o vice-prefeito de Navegantes, Wancarlos Corsani, que confirmou sua pr\u00e9-candidatura para disputar uma cadeira na Assembleia Legislativa de Santa Catarina. Assim como&hellip;<\/p>\n","protected":false},"author":2,"featured_media":15467,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"ai_generated_summary":"","footnotes":""},"categories":[23],"tags":[],"class_list":["post-15466","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-editorial"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>EDITORIAL: SANTO DE CASA FAZ MILAGRE - Jornal nos Bairros<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/jornalnosbairros.com.br\/wp\/2022\/06\/editorial-santo-de-casa-faz-milagre\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"EDITORIAL: SANTO DE CASA FAZ MILAGRE - Jornal nos Bairros\" \/>\n<meta property=\"og:description\" content=\"O Jornal nos Bairros traz, nessa edi\u00e7\u00e3o, uma entrevista exclusiva com o vice-prefeito de Navegantes, Wancarlos Corsani, que confirmou sua pr\u00e9-candidatura para disputar uma cadeira na Assembleia Legislativa de Santa Catarina. Assim como&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/jornalnosbairros.com.br\/wp\/2022\/06\/editorial-santo-de-casa-faz-milagre\/\" \/>\n<meta property=\"og:site_name\" content=\"Jornal nos Bairros\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/jornalnosbairros\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/jornalnosbairros\" \/>\n<meta property=\"article:published_time\" content=\"2022-06-23T17:00:16+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-06-23T17:02:21+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/jornalnosbairros.com.br\/wp\/wp-content\/uploads\/2022\/06\/ALESC.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1362\" \/>\n\t<meta property=\"og:image:height\" content=\"908\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Louise Benassi\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/jornal_bairros\" \/>\n<meta name=\"twitter:site\" content=\"@jornal_bairros\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Louise Benassi\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/2022\\\/06\\\/editorial-santo-de-casa-faz-milagre\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/2022\\\/06\\\/editorial-santo-de-casa-faz-milagre\\\/\"},\"author\":{\"name\":\"Louise Benassi\",\"@id\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/#\\\/schema\\\/person\\\/0fff6800408f4a5288e868b423aa66e6\"},\"headline\":\"EDITORIAL: SANTO DE CASA FAZ MILAGRE\",\"datePublished\":\"2022-06-23T17:00:16+00:00\",\"dateModified\":\"2022-06-23T17:02:21+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/2022\\\/06\\\/editorial-santo-de-casa-faz-milagre\\\/\"},\"wordCount\":285,\"publisher\":{\"@id\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/2022\\\/06\\\/editorial-santo-de-casa-faz-milagre\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/ALESC.jpg\",\"articleSection\":[\"EDITORIAL\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/2022\\\/06\\\/editorial-santo-de-casa-faz-milagre\\\/\",\"url\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/2022\\\/06\\\/editorial-santo-de-casa-faz-milagre\\\/\",\"name\":\"EDITORIAL: SANTO DE CASA FAZ MILAGRE - Jornal nos Bairros\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/2022\\\/06\\\/editorial-santo-de-casa-faz-milagre\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/2022\\\/06\\\/editorial-santo-de-casa-faz-milagre\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/ALESC.jpg\",\"datePublished\":\"2022-06-23T17:00:16+00:00\",\"dateModified\":\"2022-06-23T17:02:21+00:00\",\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/2022\\\/06\\\/editorial-santo-de-casa-faz-milagre\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/2022\\\/06\\\/editorial-santo-de-casa-faz-milagre\\\/#primaryimage\",\"url\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/ALESC.jpg\",\"contentUrl\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/ALESC.jpg\",\"width\":1362,\"height\":908,\"caption\":\"ALESC\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/#website\",\"url\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/\",\"name\":\"Jornal nos Bairros\",\"description\":\"Not\u00edcias di\u00e1rias de Navegantes e regi\u00e3o\",\"publisher\":{\"@id\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/#organization\"},\"alternateName\":\"JB\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/#organization\",\"name\":\"Jornal nos Bairros de Navegantes\",\"url\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/LOGO-JB.png\",\"contentUrl\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/LOGO-JB.png\",\"width\":168,\"height\":150,\"caption\":\"Jornal nos Bairros de Navegantes\"},\"image\":{\"@id\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/jornalnosbairros\",\"https:\\\/\\\/x.com\\\/jornal_bairros\",\"https:\\\/\\\/www.instagram.com\\\/jornalnosbairros\",\"https:\\\/\\\/www.youtube.com\\\/@jornalnosbairros\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/#\\\/schema\\\/person\\\/0fff6800408f4a5288e868b423aa66e6\",\"name\":\"Louise Benassi\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9d4314cebcb775b6f2598392f1ed67a5d487928fbd387d9492add88335cb0166?s=96&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9d4314cebcb775b6f2598392f1ed67a5d487928fbd387d9492add88335cb0166?s=96&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9d4314cebcb775b6f2598392f1ed67a5d487928fbd387d9492add88335cb0166?s=96&r=g\",\"caption\":\"Louise Benassi\"},\"description\":\"Louise Benassi SC 002880\\\/JP - Jornalista do Jornal nos Bairros de Navegantes - Contato: fale@jornalnosbairros.com.br - Siga: @jornalnosbairros - Acesse: www.jornalnosbairros.com.br - WhatsApp 47 33196585\",\"sameAs\":[\"http:\\\/\\\/www.jornalnosbairros.com.br\",\"https:\\\/\\\/www.facebook.com\\\/jornalnosbairros\",\"https:\\\/\\\/www.instagram.com\\\/jornalnosbairros\\\/\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/jornal_bairros\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCbdZNY5wPbaBq5KtRGP4WxQ\"],\"url\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/author\\\/louise\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"EDITORIAL: SANTO DE CASA FAZ MILAGRE - Jornal nos Bairros","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/jornalnosbairros.com.br\/wp\/2022\/06\/editorial-santo-de-casa-faz-milagre\/","og_locale":"pt_BR","og_type":"article","og_title":"EDITORIAL: SANTO DE CASA FAZ MILAGRE - Jornal nos Bairros","og_description":"O Jornal nos Bairros traz, nessa edi\u00e7\u00e3o, uma entrevista exclusiva com o vice-prefeito de Navegantes, Wancarlos Corsani, que confirmou sua pr\u00e9-candidatura para disputar uma cadeira na Assembleia Legislativa de Santa Catarina. Assim como&hellip;","og_url":"https:\/\/jornalnosbairros.com.br\/wp\/2022\/06\/editorial-santo-de-casa-faz-milagre\/","og_site_name":"Jornal nos Bairros","article_publisher":"https:\/\/www.facebook.com\/jornalnosbairros","article_author":"https:\/\/www.facebook.com\/jornalnosbairros","article_published_time":"2022-06-23T17:00:16+00:00","article_modified_time":"2022-06-23T17:02:21+00:00","og_image":[{"width":1362,"height":908,"url":"https:\/\/jornalnosbairros.com.br\/wp\/wp-content\/uploads\/2022\/06\/ALESC.jpg","type":"image\/jpeg"}],"author":"Louise Benassi","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/jornal_bairros","twitter_site":"@jornal_bairros","twitter_misc":{"Escrito por":"Louise Benassi","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/jornalnosbairros.com.br\/wp\/2022\/06\/editorial-santo-de-casa-faz-milagre\/#article","isPartOf":{"@id":"https:\/\/jornalnosbairros.com.br\/wp\/2022\/06\/editorial-santo-de-casa-faz-milagre\/"},"author":{"name":"Louise Benassi","@id":"https:\/\/jornalnosbairros.com.br\/wp\/#\/schema\/person\/0fff6800408f4a5288e868b423aa66e6"},"headline":"EDITORIAL: SANTO DE CASA FAZ MILAGRE","datePublished":"2022-06-23T17:00:16+00:00","dateModified":"2022-06-23T17:02:21+00:00","mainEntityOfPage":{"@id":"https:\/\/jornalnosbairros.com.br\/wp\/2022\/06\/editorial-santo-de-casa-faz-milagre\/"},"wordCount":285,"publisher":{"@id":"https:\/\/jornalnosbairros.com.br\/wp\/#organization"},"image":{"@id":"https:\/\/jornalnosbairros.com.br\/wp\/2022\/06\/editorial-santo-de-casa-faz-milagre\/#primaryimage"},"thumbnailUrl":"https:\/\/jornalnosbairros.com.br\/wp\/wp-content\/uploads\/2022\/06\/ALESC.jpg","articleSection":["EDITORIAL"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/jornalnosbairros.com.br\/wp\/2022\/06\/editorial-santo-de-casa-faz-milagre\/","url":"https:\/\/jornalnosbairros.com.br\/wp\/2022\/06\/editorial-santo-de-casa-faz-milagre\/","name":"EDITORIAL: SANTO DE CASA FAZ MILAGRE - Jornal nos Bairros","isPartOf":{"@id":"https:\/\/jornalnosbairros.com.br\/wp\/#website"},"primaryImageOfPage":{"@id":"https:\/\/jornalnosbairros.com.br\/wp\/2022\/06\/editorial-santo-de-casa-faz-milagre\/#primaryimage"},"image":{"@id":"https:\/\/jornalnosbairros.com.br\/wp\/2022\/06\/editorial-santo-de-casa-faz-milagre\/#primaryimage"},"thumbnailUrl":"https:\/\/jornalnosbairros.com.br\/wp\/wp-content\/uploads\/2022\/06\/ALESC.jpg","datePublished":"2022-06-23T17:00:16+00:00","dateModified":"2022-06-23T17:02:21+00:00","inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/jornalnosbairros.com.br\/wp\/2022\/06\/editorial-santo-de-casa-faz-milagre\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/jornalnosbairros.com.br\/wp\/2022\/06\/editorial-santo-de-casa-faz-milagre\/#primaryimage","url":"https:\/\/jornalnosbairros.com.br\/wp\/wp-content\/uploads\/2022\/06\/ALESC.jpg","contentUrl":"https:\/\/jornalnosbairros.com.br\/wp\/wp-content\/uploads\/2022\/06\/ALESC.jpg","width":1362,"height":908,"caption":"ALESC"},{"@type":"WebSite","@id":"https:\/\/jornalnosbairros.com.br\/wp\/#website","url":"https:\/\/jornalnosbairros.com.br\/wp\/","name":"Jornal nos Bairros","description":"Not\u00edcias di\u00e1rias de Navegantes e regi\u00e3o","publisher":{"@id":"https:\/\/jornalnosbairros.com.br\/wp\/#organization"},"alternateName":"JB","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/jornalnosbairros.com.br\/wp\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/jornalnosbairros.com.br\/wp\/#organization","name":"Jornal nos Bairros de Navegantes","url":"https:\/\/jornalnosbairros.com.br\/wp\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/jornalnosbairros.com.br\/wp\/#\/schema\/logo\/image\/","url":"https:\/\/jornalnosbairros.com.br\/wp\/wp-content\/uploads\/2025\/01\/LOGO-JB.png","contentUrl":"https:\/\/jornalnosbairros.com.br\/wp\/wp-content\/uploads\/2025\/01\/LOGO-JB.png","width":168,"height":150,"caption":"Jornal nos Bairros de Navegantes"},"image":{"@id":"https:\/\/jornalnosbairros.com.br\/wp\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/jornalnosbairros","https:\/\/x.com\/jornal_bairros","https:\/\/www.instagram.com\/jornalnosbairros","https:\/\/www.youtube.com\/@jornalnosbairros"]},{"@type":"Person","@id":"https:\/\/jornalnosbairros.com.br\/wp\/#\/schema\/person\/0fff6800408f4a5288e868b423aa66e6","name":"Louise Benassi","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/9d4314cebcb775b6f2598392f1ed67a5d487928fbd387d9492add88335cb0166?s=96&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/9d4314cebcb775b6f2598392f1ed67a5d487928fbd387d9492add88335cb0166?s=96&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9d4314cebcb775b6f2598392f1ed67a5d487928fbd387d9492add88335cb0166?s=96&r=g","caption":"Louise Benassi"},"description":"Louise Benassi SC 002880\/JP - Jornalista do Jornal nos Bairros de Navegantes - Contato: fale@jornalnosbairros.com.br - Siga: @jornalnosbairros - Acesse: www.jornalnosbairros.com.br - WhatsApp 47 33196585","sameAs":["http:\/\/www.jornalnosbairros.com.br","https:\/\/www.facebook.com\/jornalnosbairros","https:\/\/www.instagram.com\/jornalnosbairros\/","https:\/\/x.com\/https:\/\/twitter.com\/jornal_bairros","https:\/\/www.youtube.com\/channel\/UCbdZNY5wPbaBq5KtRGP4WxQ"],"url":"https:\/\/jornalnosbairros.com.br\/wp\/author\/louise\/"}]}},"_links":{"self":[{"href":"https:\/\/jornalnosbairros.com.br\/wp\/wp-json\/wp\/v2\/posts\/15466","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jornalnosbairros.com.br\/wp\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jornalnosbairros.com.br\/wp\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jornalnosbairros.com.br\/wp\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/jornalnosbairros.com.br\/wp\/wp-json\/wp\/v2\/comments?post=15466"}],"version-history":[{"count":3,"href":"https:\/\/jornalnosbairros.com.br\/wp\/wp-json\/wp\/v2\/posts\/15466\/revisions"}],"predecessor-version":[{"id":15470,"href":"https:\/\/jornalnosbairros.com.br\/wp\/wp-json\/wp\/v2\/posts\/15466\/revisions\/15470"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/jornalnosbairros.com.br\/wp\/wp-json\/wp\/v2\/media\/15467"}],"wp:attachment":[{"href":"https:\/\/jornalnosbairros.com.br\/wp\/wp-json\/wp\/v2\/media?parent=15466"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jornalnosbairros.com.br\/wp\/wp-json\/wp\/v2\/categories?post=15466"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jornalnosbairros.com.br\/wp\/wp-json\/wp\/v2\/tags?post=15466"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}