{"id":13032,"date":"2022-02-08T15:32:36","date_gmt":"2022-02-08T15:32:36","guid":{"rendered":"https:\/\/jornalnosbairros.com.br\/wp\/?p=13032"},"modified":"2022-02-08T15:32:57","modified_gmt":"2022-02-08T15:32:57","slug":"projeto-cria-13-novos-cargos-comissionados-na-camara-de-navegantes","status":"publish","type":"post","link":"https:\/\/jornalnosbairros.com.br\/wp\/2022\/02\/projeto-cria-13-novos-cargos-comissionados-na-camara-de-navegantes\/","title":{"rendered":"PROJETO CRIA 13 NOVOS CARGOS COMISSIONADOS NA C\u00c2MARA DE NAVEGANTES"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Na segunda-feira (7), os vereadores analisaram dois anteprojetos de lei, na 2\u00aa sess\u00e3o ordin\u00e1ria de 2022. Al\u00e9m destas mat\u00e9rias, seis projetos de lei deram entrada na Casa para tramita\u00e7\u00e3o nas comiss\u00f5es e delibera\u00e7\u00e3o em plen\u00e1rio nas pr\u00f3ximas sess\u00f5es legislativas. Um deles \u00e9 o projeto de lei complementar n\u00b0 0002\/2022, de autoria da mesa diretora.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O PL disp\u00f5e sobre a cria\u00e7\u00e3o e extin\u00e7\u00e3o de cargos no quadro de servidores da C\u00e2mara Municipal de Navegantes e altera a lei complementar 256\/2015, que disp\u00f5e sobre a organiza\u00e7\u00e3o administrativa, classifica\u00e7\u00e3o, extin\u00e7\u00e3o, cria\u00e7\u00e3o de cargos e a remunera\u00e7\u00e3o dos servidores p\u00fablicos.<br>Se o PL for aprovado, ser\u00e3o criados novos cargos e vagas, de provimento em comiss\u00e3o, sendo uma vaga para Assessor das Comiss\u00f5es Permanentes; uma vaga para Coordenador de Comunica\u00e7\u00e3o Social; uma vaga para Coordenador do Gabinete da Presid\u00eancia; e 10 vagas para Chefe de Gabinete.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Conforme o texto, tamb\u00e9m ser\u00e3o extintos os cargos e vagas de Coordenador de Patrim\u00f4nio e Ouvidor; Controlador Interno com habilita\u00e7\u00e3o em Ci\u00eancias Cont\u00e1beis; Assistente Cont\u00e1bil e Contador.<br>Com a altera\u00e7\u00e3o na lei, os cargos de provimento efetivo da C\u00e2mara Municipal passam a ser os seguintes: Agente de Servi\u00e7os Gerais; Assessor Administrativo de Recursos Humanos; Assessor Jur\u00eddico; Assessor Legislativo; Assistente Cont\u00e1bil; Assistente Legislativo; Contador; Controlador Interno.<br>J\u00e1 os cargos de provimento em comiss\u00e3o da C\u00e2mara Municipal passar\u00e3o a ser os seguintes: Assessor das Comiss\u00f5es Permanentes; Assessor de Comunica\u00e7\u00e3o Social; Assessor de Gabinete; Chefe de Gabinete; Coordenador de Comunica\u00e7\u00e3o Social; Coordenador Financeiro; Coordenador do Gabinete da Presid\u00eancia; Diretor Administrativo e Procurador Geral.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Na segunda-feira (7), os vereadores analisaram dois anteprojetos de lei, na 2\u00aa sess\u00e3o ordin\u00e1ria de 2022. Al\u00e9m destas mat\u00e9rias, seis projetos de lei deram entrada na Casa para tramita\u00e7\u00e3o nas comiss\u00f5es e delibera\u00e7\u00e3o&hellip;<\/p>\n","protected":false},"author":1,"featured_media":1122,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"ai_generated_summary":"","footnotes":""},"categories":[4],"tags":[47,40],"class_list":["post-13032","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica","tag-cidade","tag-navegantes"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>PROJETO CRIA 13 NOVOS CARGOS COMISSIONADOS NA C\u00c2MARA DE NAVEGANTES - Jornal nos Bairros<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/jornalnosbairros.com.br\/wp\/2022\/02\/projeto-cria-13-novos-cargos-comissionados-na-camara-de-navegantes\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"PROJETO CRIA 13 NOVOS CARGOS COMISSIONADOS NA C\u00c2MARA DE NAVEGANTES - Jornal nos Bairros\" \/>\n<meta property=\"og:description\" content=\"Na segunda-feira (7), os vereadores analisaram dois anteprojetos de lei, na 2\u00aa sess\u00e3o ordin\u00e1ria de 2022. Al\u00e9m destas mat\u00e9rias, seis projetos de lei deram entrada na Casa para tramita\u00e7\u00e3o nas comiss\u00f5es e delibera\u00e7\u00e3o&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/jornalnosbairros.com.br\/wp\/2022\/02\/projeto-cria-13-novos-cargos-comissionados-na-camara-de-navegantes\/\" \/>\n<meta property=\"og:site_name\" content=\"Jornal nos Bairros\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/jornalnosbairros\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/jornalnosbairros\" \/>\n<meta property=\"article:published_time\" content=\"2022-02-08T15:32:36+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-02-08T15:32:57+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/jornalnosbairros.com.br\/wp\/wp-content\/uploads\/2020\/04\/4138984_x720.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Editoria\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/jornal_bairros\" \/>\n<meta name=\"twitter:site\" content=\"@jornal_bairros\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Editoria\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/2022\\\/02\\\/projeto-cria-13-novos-cargos-comissionados-na-camara-de-navegantes\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/2022\\\/02\\\/projeto-cria-13-novos-cargos-comissionados-na-camara-de-navegantes\\\/\"},\"author\":{\"name\":\"Editoria\",\"@id\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/#\\\/schema\\\/person\\\/9a74fde2f4332c018c3b4d29a6129437\"},\"headline\":\"PROJETO CRIA 13 NOVOS CARGOS COMISSIONADOS NA C\u00c2MARA DE NAVEGANTES\",\"datePublished\":\"2022-02-08T15:32:36+00:00\",\"dateModified\":\"2022-02-08T15:32:57+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/2022\\\/02\\\/projeto-cria-13-novos-cargos-comissionados-na-camara-de-navegantes\\\/\"},\"wordCount\":299,\"publisher\":{\"@id\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/2022\\\/02\\\/projeto-cria-13-novos-cargos-comissionados-na-camara-de-navegantes\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/4138984_x720.jpg\",\"keywords\":[\"cidade\",\"navegantes\"],\"articleSection\":[\"POL\u00cdTICA\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/2022\\\/02\\\/projeto-cria-13-novos-cargos-comissionados-na-camara-de-navegantes\\\/\",\"url\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/2022\\\/02\\\/projeto-cria-13-novos-cargos-comissionados-na-camara-de-navegantes\\\/\",\"name\":\"PROJETO CRIA 13 NOVOS CARGOS COMISSIONADOS NA C\u00c2MARA DE NAVEGANTES - Jornal nos Bairros\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/2022\\\/02\\\/projeto-cria-13-novos-cargos-comissionados-na-camara-de-navegantes\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/2022\\\/02\\\/projeto-cria-13-novos-cargos-comissionados-na-camara-de-navegantes\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/4138984_x720.jpg\",\"datePublished\":\"2022-02-08T15:32:36+00:00\",\"dateModified\":\"2022-02-08T15:32:57+00:00\",\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/2022\\\/02\\\/projeto-cria-13-novos-cargos-comissionados-na-camara-de-navegantes\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/2022\\\/02\\\/projeto-cria-13-novos-cargos-comissionados-na-camara-de-navegantes\\\/#primaryimage\",\"url\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/4138984_x720.jpg\",\"contentUrl\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/4138984_x720.jpg\",\"width\":1280,\"height\":720,\"caption\":\"C\u00e2mara de Vereadores de Navegantes\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/#website\",\"url\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/\",\"name\":\"Jornal nos Bairros\",\"description\":\"Not\u00edcias di\u00e1rias de Navegantes e regi\u00e3o\",\"publisher\":{\"@id\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/#organization\"},\"alternateName\":\"JB\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/#organization\",\"name\":\"Jornal nos Bairros de Navegantes\",\"url\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/LOGO-JB.png\",\"contentUrl\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/LOGO-JB.png\",\"width\":168,\"height\":150,\"caption\":\"Jornal nos Bairros de Navegantes\"},\"image\":{\"@id\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/jornalnosbairros\",\"https:\\\/\\\/x.com\\\/jornal_bairros\",\"https:\\\/\\\/www.instagram.com\\\/jornalnosbairros\",\"https:\\\/\\\/www.youtube.com\\\/@jornalnosbairros\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/#\\\/schema\\\/person\\\/9a74fde2f4332c018c3b4d29a6129437\",\"name\":\"Editoria\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b53a04b7003d01b914d43ebacd13b233f0d99ed1cb7f8cb7d8553ef90e3f466b?s=96&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b53a04b7003d01b914d43ebacd13b233f0d99ed1cb7f8cb7d8553ef90e3f466b?s=96&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b53a04b7003d01b914d43ebacd13b233f0d99ed1cb7f8cb7d8553ef90e3f466b?s=96&r=g\",\"caption\":\"Editoria\"},\"description\":\"Edi\u00e7\u00e3o do Jornal nos Bairros de Navegantes - Contato: fale@jornalnosbairros.com.br - Siga: @jornalnosbairros - Acesse: www.jornalnosbairros.com.br\",\"sameAs\":[\"http:\\\/\\\/www.jornalnosbairros.com.br\\\/wp\",\"https:\\\/\\\/www.facebook.com\\\/jornalnosbairros\",\"https:\\\/\\\/www.instagram.com\\\/jornalnosbairros\\\/\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/jornal_bairros\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCbdZNY5wPbaBq5KtRGP4WxQ?view_as=subscriber\"],\"url\":\"https:\\\/\\\/jornalnosbairros.com.br\\\/wp\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"PROJETO CRIA 13 NOVOS CARGOS COMISSIONADOS NA C\u00c2MARA DE NAVEGANTES - Jornal nos Bairros","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/jornalnosbairros.com.br\/wp\/2022\/02\/projeto-cria-13-novos-cargos-comissionados-na-camara-de-navegantes\/","og_locale":"pt_BR","og_type":"article","og_title":"PROJETO CRIA 13 NOVOS CARGOS COMISSIONADOS NA C\u00c2MARA DE NAVEGANTES - Jornal nos Bairros","og_description":"Na segunda-feira (7), os vereadores analisaram dois anteprojetos de lei, na 2\u00aa sess\u00e3o ordin\u00e1ria de 2022. Al\u00e9m destas mat\u00e9rias, seis projetos de lei deram entrada na Casa para tramita\u00e7\u00e3o nas comiss\u00f5es e delibera\u00e7\u00e3o&hellip;","og_url":"https:\/\/jornalnosbairros.com.br\/wp\/2022\/02\/projeto-cria-13-novos-cargos-comissionados-na-camara-de-navegantes\/","og_site_name":"Jornal nos Bairros","article_publisher":"https:\/\/www.facebook.com\/jornalnosbairros","article_author":"https:\/\/www.facebook.com\/jornalnosbairros","article_published_time":"2022-02-08T15:32:36+00:00","article_modified_time":"2022-02-08T15:32:57+00:00","og_image":[{"width":1280,"height":720,"url":"https:\/\/jornalnosbairros.com.br\/wp\/wp-content\/uploads\/2020\/04\/4138984_x720.jpg","type":"image\/jpeg"}],"author":"Editoria","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/jornal_bairros","twitter_site":"@jornal_bairros","twitter_misc":{"Escrito por":"Editoria","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/jornalnosbairros.com.br\/wp\/2022\/02\/projeto-cria-13-novos-cargos-comissionados-na-camara-de-navegantes\/#article","isPartOf":{"@id":"https:\/\/jornalnosbairros.com.br\/wp\/2022\/02\/projeto-cria-13-novos-cargos-comissionados-na-camara-de-navegantes\/"},"author":{"name":"Editoria","@id":"https:\/\/jornalnosbairros.com.br\/wp\/#\/schema\/person\/9a74fde2f4332c018c3b4d29a6129437"},"headline":"PROJETO CRIA 13 NOVOS CARGOS COMISSIONADOS NA C\u00c2MARA DE NAVEGANTES","datePublished":"2022-02-08T15:32:36+00:00","dateModified":"2022-02-08T15:32:57+00:00","mainEntityOfPage":{"@id":"https:\/\/jornalnosbairros.com.br\/wp\/2022\/02\/projeto-cria-13-novos-cargos-comissionados-na-camara-de-navegantes\/"},"wordCount":299,"publisher":{"@id":"https:\/\/jornalnosbairros.com.br\/wp\/#organization"},"image":{"@id":"https:\/\/jornalnosbairros.com.br\/wp\/2022\/02\/projeto-cria-13-novos-cargos-comissionados-na-camara-de-navegantes\/#primaryimage"},"thumbnailUrl":"https:\/\/jornalnosbairros.com.br\/wp\/wp-content\/uploads\/2020\/04\/4138984_x720.jpg","keywords":["cidade","navegantes"],"articleSection":["POL\u00cdTICA"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/jornalnosbairros.com.br\/wp\/2022\/02\/projeto-cria-13-novos-cargos-comissionados-na-camara-de-navegantes\/","url":"https:\/\/jornalnosbairros.com.br\/wp\/2022\/02\/projeto-cria-13-novos-cargos-comissionados-na-camara-de-navegantes\/","name":"PROJETO CRIA 13 NOVOS CARGOS COMISSIONADOS NA C\u00c2MARA DE NAVEGANTES - Jornal nos Bairros","isPartOf":{"@id":"https:\/\/jornalnosbairros.com.br\/wp\/#website"},"primaryImageOfPage":{"@id":"https:\/\/jornalnosbairros.com.br\/wp\/2022\/02\/projeto-cria-13-novos-cargos-comissionados-na-camara-de-navegantes\/#primaryimage"},"image":{"@id":"https:\/\/jornalnosbairros.com.br\/wp\/2022\/02\/projeto-cria-13-novos-cargos-comissionados-na-camara-de-navegantes\/#primaryimage"},"thumbnailUrl":"https:\/\/jornalnosbairros.com.br\/wp\/wp-content\/uploads\/2020\/04\/4138984_x720.jpg","datePublished":"2022-02-08T15:32:36+00:00","dateModified":"2022-02-08T15:32:57+00:00","inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/jornalnosbairros.com.br\/wp\/2022\/02\/projeto-cria-13-novos-cargos-comissionados-na-camara-de-navegantes\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/jornalnosbairros.com.br\/wp\/2022\/02\/projeto-cria-13-novos-cargos-comissionados-na-camara-de-navegantes\/#primaryimage","url":"https:\/\/jornalnosbairros.com.br\/wp\/wp-content\/uploads\/2020\/04\/4138984_x720.jpg","contentUrl":"https:\/\/jornalnosbairros.com.br\/wp\/wp-content\/uploads\/2020\/04\/4138984_x720.jpg","width":1280,"height":720,"caption":"C\u00e2mara de Vereadores de Navegantes"},{"@type":"WebSite","@id":"https:\/\/jornalnosbairros.com.br\/wp\/#website","url":"https:\/\/jornalnosbairros.com.br\/wp\/","name":"Jornal nos Bairros","description":"Not\u00edcias di\u00e1rias de Navegantes e regi\u00e3o","publisher":{"@id":"https:\/\/jornalnosbairros.com.br\/wp\/#organization"},"alternateName":"JB","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/jornalnosbairros.com.br\/wp\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/jornalnosbairros.com.br\/wp\/#organization","name":"Jornal nos Bairros de Navegantes","url":"https:\/\/jornalnosbairros.com.br\/wp\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/jornalnosbairros.com.br\/wp\/#\/schema\/logo\/image\/","url":"https:\/\/jornalnosbairros.com.br\/wp\/wp-content\/uploads\/2025\/01\/LOGO-JB.png","contentUrl":"https:\/\/jornalnosbairros.com.br\/wp\/wp-content\/uploads\/2025\/01\/LOGO-JB.png","width":168,"height":150,"caption":"Jornal nos Bairros de Navegantes"},"image":{"@id":"https:\/\/jornalnosbairros.com.br\/wp\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/jornalnosbairros","https:\/\/x.com\/jornal_bairros","https:\/\/www.instagram.com\/jornalnosbairros","https:\/\/www.youtube.com\/@jornalnosbairros"]},{"@type":"Person","@id":"https:\/\/jornalnosbairros.com.br\/wp\/#\/schema\/person\/9a74fde2f4332c018c3b4d29a6129437","name":"Editoria","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/b53a04b7003d01b914d43ebacd13b233f0d99ed1cb7f8cb7d8553ef90e3f466b?s=96&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b53a04b7003d01b914d43ebacd13b233f0d99ed1cb7f8cb7d8553ef90e3f466b?s=96&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b53a04b7003d01b914d43ebacd13b233f0d99ed1cb7f8cb7d8553ef90e3f466b?s=96&r=g","caption":"Editoria"},"description":"Edi\u00e7\u00e3o do Jornal nos Bairros de Navegantes - Contato: fale@jornalnosbairros.com.br - Siga: @jornalnosbairros - Acesse: www.jornalnosbairros.com.br","sameAs":["http:\/\/www.jornalnosbairros.com.br\/wp","https:\/\/www.facebook.com\/jornalnosbairros","https:\/\/www.instagram.com\/jornalnosbairros\/","https:\/\/x.com\/https:\/\/twitter.com\/jornal_bairros","https:\/\/www.youtube.com\/channel\/UCbdZNY5wPbaBq5KtRGP4WxQ?view_as=subscriber"],"url":"https:\/\/jornalnosbairros.com.br\/wp\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/jornalnosbairros.com.br\/wp\/wp-json\/wp\/v2\/posts\/13032","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jornalnosbairros.com.br\/wp\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jornalnosbairros.com.br\/wp\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jornalnosbairros.com.br\/wp\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/jornalnosbairros.com.br\/wp\/wp-json\/wp\/v2\/comments?post=13032"}],"version-history":[{"count":2,"href":"https:\/\/jornalnosbairros.com.br\/wp\/wp-json\/wp\/v2\/posts\/13032\/revisions"}],"predecessor-version":[{"id":13034,"href":"https:\/\/jornalnosbairros.com.br\/wp\/wp-json\/wp\/v2\/posts\/13032\/revisions\/13034"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/jornalnosbairros.com.br\/wp\/wp-json\/wp\/v2\/media\/1122"}],"wp:attachment":[{"href":"https:\/\/jornalnosbairros.com.br\/wp\/wp-json\/wp\/v2\/media?parent=13032"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jornalnosbairros.com.br\/wp\/wp-json\/wp\/v2\/categories?post=13032"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jornalnosbairros.com.br\/wp\/wp-json\/wp\/v2\/tags?post=13032"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}